{"id":52306,"date":"2016-01-18T13:56:45","date_gmt":"2016-01-18T17:56:45","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52306"},"modified":"2016-01-18T13:56:45","modified_gmt":"2016-01-18T17:56:45","slug":"10-cosas-que-debes-evitar-hacer-despues-de-las-comidas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/10-cosas-que-debes-evitar-hacer-despues-de-las-comidas\/","title":{"rendered":"10 cosas que debes evitar hacer despu\u00e9s de las comidas"},"content":{"rendered":"<div class=\"mc-header\">\n<div class=\"headline-article\">Las infusiones inmediatamente despu\u00e9s de comer pueden dificultar la adecuada absorci\u00f3n de nutrientes. Sus taninos pueden provocar problemas digestivos al interferir con las prote\u00ednas de los alimentos.<!--more--><\/div>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/mujer-limpiando-servilleta-500x333.jpg\" rel=\"attachment wp-att-52307\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-52307\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/mujer-limpiando-servilleta-500x333.jpg\" alt=\"mujer-limpiando-servilleta-500x333\" width=\"500\" height=\"333\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/mujer-limpiando-servilleta-500x333.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/mujer-limpiando-servilleta-500x333-300x200.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<div class=\"mc-content\">\n<p>Muchas personas tienen ciertas costumbres despu\u00e9s de comer sin saber que pueden estar dificultando las labores en su sistema digestivo.<\/p>\n<p>Resulta com\u00fan que una comida provoque <strong>indigesti\u00f3n, reflujo g\u00e1strico y otros s\u00edntomas molestos que interrumpen una buena jornada.<\/strong><\/p>\n<p>Sin embargo, lo que muchos no saben es que, por lo general, todo esto tiene alg\u00fan tipo de relaci\u00f3n con los h\u00e1bitos que se ponen en pr\u00e1ctica despu\u00e9s de comer.<\/p>\n<div class=\"ad-desktop\"><\/div>\n<p>Teniendo en cuenta que algunos a\u00fan lo ignoran y no dejan de realizarlos, a continuaci\u00f3n <strong>vamos a revelar esas 10 cosas que es mejor evitar <\/strong>para no sufrir molestas sensaciones tras ingerir los alimentos.<\/p>\n<h2>1. Dormir<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-89228\" src=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2016\/01\/Dormir-500x334.jpg\" alt=\"Dormir\" width=\"500\" height=\"334\" \/><\/p>\n<p>Tomar la decisi\u00f3n de echar\u00a0una siesta o dormir despu\u00e9s de comer es una mala idea, en especial si los alimentos eran demasiado copiosos.<\/p>\n<p>La gravedad radica en que, al acostarse, <strong>los jugos digestivos se alejan del est\u00f3mago y conducen a desarrollar inflamaciones intestinales.<\/strong><\/p>\n<p>Esto aumenta la presi\u00f3n sobre el diafragma y provoca\u00a0molestos s\u00edntomas como el\u00a0ardor o el\u00a0reflujo \u00e1cido.<\/p>\n<h2>2. Tomar una ducha<\/h2>\n<p>Para todos es m\u00e1s conveniente esperar un tiempo prudente antes de ducharse. Al hacerlo despu\u00e9s de comer, el cuerpo se enfr\u00eda, se produce un <strong>incremento del flujo sangu\u00edneo y disminuye la cantidad de sangre alrededor del est\u00f3mago.<\/strong><\/p>\n<p>Este efecto causa trastornos en el sistema digestivo y tambi\u00e9n puede convertirse en la causa de otros problemas de salud.<\/p>\n<h2>3. Fumar<\/h2>\n<p>Hoy en d\u00eda todas las personas saben que el consumo diario de cigarrillo tiene efectos negativos en la salud, que se traducen en enfermedades a mediano y largo plazo.<\/p>\n<p>Lo que algunos desconocen es que <strong>fumar despu\u00e9s de comer equivale a consumir 10 cigarrillos<\/strong>\u00a0lo que, de forma inevitable, aumenta el riesgo de desarrollar alg\u00fan tipo de c\u00e1ncer.<\/p>\n<h2>4. Tomar infusiones o t\u00e9<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-89230\" src=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2016\/01\/Tomar-infusiones-o-t%C3%A9-500x334.jpg\" alt=\"Tomar infusiones o t\u00e9\" width=\"500\" height=\"334\" \/><\/p>\n<p>El consumo de bebidas calientes despu\u00e9s de comer, como las infusiones o el t\u00e9, tiene un efecto negativo en el cuerpo al impedir la adecuada absorci\u00f3n de nutrientes como el hierro.<\/p>\n<p>Los taninos, compuestos activos de este tipo de bebidas,\u00a0<strong>interfieren con las prote\u00ednas de los alimentos y provocan dificultades digestivas.<\/strong><\/p>\n<h2>5. Usar ropa demasiado ajustada<\/h2>\n<p>Apretar el cintur\u00f3n del pantal\u00f3n o utilizar una prenda demasiado ajustada\u00a0<strong>causa problemas a nivel intestinal<\/strong> y, al alterarse su funci\u00f3n, puede provocar reflujo g\u00e1strico o acidez.<\/p>\n<h2>6. Nadar<\/h2>\n<p>\u00a1Cuidado! Siempre resulta prudente esperar como m\u00ednimo media hora despu\u00e9s de comer para meterse en la piscina.<\/p>\n<p>Esto se debe a que, tras ingerir comidas, \u00a0se requiere\u00a0m\u00e1s sangre en el tracto gastrointestinal para ayudar a la\u00a0digesti\u00f3n.<\/p>\n<p>Una vez se sumerge el cuerpo en el agua <strong>se pueden producir fuertes calambresestomacales o entumecimiento de las extremidades.<\/strong><\/p>\n<h2>7. Caminar<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-37036\" src=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2014\/09\/Caminar-diariamente-500x334.jpg\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" srcset=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2014\/09\/Caminar-diariamente-377x252.jpg 377w, http:\/\/mejorconsalud.com\/wp-content\/uploads\/2014\/09\/Caminar-diariamente.jpg 500w\" alt=\"Caminar-diariamente\" width=\"500\" height=\"334\" \/><\/p>\n<p>Caminar es un buen ejercicio para aumentar el gasto energ\u00e9tico y activar el cuerpo. No obstante, hacerlo despu\u00e9s de comer <strong>puede provocar en algunas personas reflujo \u00e1cido o malestar estomacal<\/strong> debido a que impide que los jugos digestivos absorban de manera adecuada los nutrientes.<\/p>\n<p>Para evitar este efecto no deseado resulta apropiado dejar pasar, como m\u00ednimo, 30 o 40 minutos tras cada comida.<\/p>\n<h2>8. Comer frutas<\/h2>\n<p>Tras ingerir alimentos demasiado copiosos o en grandes cantidades no es buena idea a\u00f1adirle frutas como postre.<\/p>\n<p>Es cierto que algunas cuentan con propiedades y enzimas digestivas que apoyan la descomposici\u00f3n y absorci\u00f3n de los nutrientes. El problema es que <strong>estas pueden atascar el est\u00f3mago y producir inflamaci\u00f3n.<\/strong><\/p>\n<p>La mejor manera de aprovechar sus propiedades es incluy\u00e9ndolas en el desayuno o a la hora de la merienda.<\/p>\n<p>Tambi\u00e9n hay que aprender a combinarlas de manera adecuada, ya que <strong>la mezcla de varios componentes puede causar dolores digestivos.<\/strong><\/p>\n<h2>9. Tomar agua fr\u00eda<\/h2>\n<p>El consumo de agua fr\u00eda con las comidas o inmediatamente despu\u00e9s no es una buena elecci\u00f3n. <strong>Esta puede causar aglutinaci\u00f3n de los alimentos<\/strong>\u00a0e impedir\u00a0que al llegar al intestino se absorban y clasifiquen de manera adecuada.<\/p>\n<p>Por el contrario, ingerir agua caliente unos 10 o 20 minutos m\u00e1s tarde ayuda a tener un mejor proceso digestivo.<\/p>\n<h2>10. Bailar<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-89232\" src=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2016\/01\/Bailar-500x334.jpg\" alt=\"Bailar\" width=\"500\" height=\"334\" \/><\/p>\n<p>Aunque es poco com\u00fan bailar tras ingerir alimentos, puede pasar, por ejemplo, en una fiesta. El inconveniente es que los movimientos causan dificultades a nivel digestivo y <strong>pueden ocasionar gases, inflamaci\u00f3n y problemas de absorci\u00f3n de nutrientes.<\/strong><\/p>\n<p>\u00bfIdentificas alguno? Es muy probable que sean la causa de esos s\u00edntomas estomacales que aquejan con frecuencia tu organismo. A partir de ahora trata de hacer todo lo posible para evitarlos y no correr los riesgos que acarrean.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las infusiones inmediatamente despu\u00e9s de comer pueden dificultar la adecuada absorci\u00f3n de nutrientes. Sus taninos pueden provocar problemas digestivos al interferir con las prote\u00ednas de los alimentos.<\/p>\n","protected":false},"author":12,"featured_media":52307,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-52306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52306"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52306\/revisions"}],"predecessor-version":[{"id":52308,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52306\/revisions\/52308"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/52307"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}