{"id":52334,"date":"2016-01-19T14:59:19","date_gmt":"2016-01-19T18:59:19","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52334"},"modified":"2016-01-19T14:59:19","modified_gmt":"2016-01-19T18:59:19","slug":"murio-hoy-hamlet-hermann-perez","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/murio-hoy-hamlet-hermann-perez\/","title":{"rendered":"Muri\u00f3 hoy Hamlet Hermann P\u00e9rez"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6097260_20160119141231.jpg\" rel=\"attachment wp-att-52335\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-52335\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6097260_20160119141231.jpg\" alt=\"image_content_6097260_20160119141231\" width=\"693\" height=\"370\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6097260_20160119141231.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6097260_20160119141231-300x160.jpg 300w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><br \/>\n<\/a>Muri\u00f3 hoy a la edad de 81 a\u00f1os a consecuencia de un infarto el ingeniero Hamlet Herman P\u00e9rez.<!--more--><\/p>\n<p>Fue un destacado militante revolucionario que particip\u00f3 en la Guerra de Abril de 1965. En 1973 fue compa\u00f1ero de la guerrilla de Francisco Alberto Caama\u00f1o, de la cual sobrevivi\u00f3 junto a Claudio Caama\u00f1o y Toribio Pe\u00f1a J\u00e1quez.<\/p>\n<p>Naci\u00f3 el 5 de octubre de 1934 en la ciudad de Santo Domingo y fue fundador de la Autoridad Metropolitana de Transporte, durante la primera administraci\u00f3n de Leonel Fern\u00e1ndez.<\/p>\n<p>Procreo tres hijos durante su primer matrimonio con la se\u00f1ora Carmen Rita Morera. En segundas nupcias estuvo casado con la productora de televisi\u00f3n Socorro Castellanos.<\/p>\n<p>Escribi\u00f3 varios textos, entre ellos, una biograf\u00eda de Caama\u00f1o y su estad\u00eda en Europa, sobre la Guerrilla de Caracoles, El general y el Guerrillero, El Fiero: Eberto Lalane Jos\u00e9, con la que fue galardonado con el Premio Nacional Feria del Libro Eduardo Le\u00f3n Jimenes, en el a\u00f1o 2009.<\/p>\n<p>Fue profesor en la Facultad de Econom\u00eda de la Universidad Aut\u00f3noma de Santo Domingo.<\/p>\n<p>Fue articulista en varios peri\u00f3dicos de circulaci\u00f3n nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muri\u00f3 hoy a la edad de 81 a\u00f1os a consecuencia de un infarto el ingeniero Hamlet Herman P\u00e9rez.<\/p>\n","protected":false},"author":12,"featured_media":52335,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-52334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52334"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52334\/revisions"}],"predecessor-version":[{"id":52336,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52334\/revisions\/52336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/52335"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}