{"id":52457,"date":"2016-01-25T09:41:22","date_gmt":"2016-01-25T13:41:22","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52457"},"modified":"2016-01-25T09:41:22","modified_gmt":"2016-01-25T13:41:22","slug":"los-tigres-del-licey-ganan-1ro-en-la-final-beisbol-dominicano-y-evita-barrida","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-tigres-del-licey-ganan-1ro-en-la-final-beisbol-dominicano-y-evita-barrida\/","title":{"rendered":"Los Tigres del Licey ganan 1ro en la final b\u00e9isbol dominicano y evita barrida"},"content":{"rendered":"<div class=\"text\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6117723_20160124215943.jpg\" rel=\"attachment wp-att-52460\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-52460\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6117723_20160124215943.jpg\" alt=\"image_content_6117723_20160124215943\" width=\"693\" height=\"370\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6117723_20160124215943.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/image_content_6117723_20160124215943-300x160.jpg 300w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/a>SANTO DOMINGO. Los Leones del Escogido, que ganaron los primeros cuatro juegos de la serie final en l\u00ednea, deber\u00e1n esperar un sexto partido para optar por la corona.<\/p>\n<p>En el partido dominical los Tigres del Licey, sus archirrivales se impusieron siete carreras a seis para su primera victoria y romper una racha de nueve derrotas. El Escogido llevada 10 triunfos seguidos.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<h2 class=\"lead cita\">El sexto partido de la serie se jugar\u00e1 el martes a partir de las 7:30. El zurdo Nick Additon fue anunciado por los Leones del Escogido mientras que los felinos azules no han anunciado el lanzador del encuentro.<\/h2>\n<div class=\"text\">\n<p>Con las bases llenas Juan Miranda bateo rodada por el paracorto que no pudo dominar Pedro L\u00f3pez y Rymer Liriano, que corri\u00f3 por Navarro, anot\u00f3 la vuelta de la ventaja.<\/p>\n<p>Desde el primer episodio los felinos azules marcaron la ruta final del partido, con una carrera, ventaja que tomaron y no perdieron en toda la ruta.<\/p>\n<p>En el partido los Tigres del Licey iniciaron con el lanzador derecho Ariel Pe\u00f1a, seguido por Gabriel Arias, Braulio Lara, Warner Madrigal, Luis V\u00e1squez, Juan P\u00e9rez, Jos\u00e9 Dom\u00ednguez, mientras que los Leones del Escogido dependieron de Carlos Pimentel, Kevin Villa, Jared Mortensen, Edward Paredes, Rafael Montero, Fernando Rodney y H\u00e9ctor Galv\u00e1.<\/p>\n<p>La victoria fue para Asencio y perdi\u00f3 Galv\u00e1.<\/p>\n<\/div>\n<div class=\"text\">\n<p><b>As\u00ed anotaron<\/b><\/p>\n<p>La primera carrera del partido la hizo el combinado azul en la conclusi\u00f3n del primer episodio cuando Zoilo Almonte que conect\u00f3 triple, anot\u00f3 impulsado por doble de Diory Hern\u00e1ndez.<\/p>\n<p>En la parte baja del tercer episodio los Tigres hicieron un rally de tres carreras para poner la pizarra 4-0. En ese episodio anotaron Logan Moore impulsado por fly de sacrificio de Zoilo Almonte; Leonys Mart\u00edn en jugada de selecci\u00f3n en batazo de Diory Hern\u00e1ndez y Yamaico Navarro remolcado por sencillo de Joey Terdoslavich.<\/p>\n<p>Tres carreras hicieron el combinado de los Leones del Escogido en la parte alta del quinto episodio. Jimmy Paredes anot\u00f3 por fly de sacrificio de Pedro L\u00f3pez; Leury Garc\u00eda peg\u00f3 doble que remolc\u00f3 a Sebasti\u00e1n Valle y a Pedro Ciriaco.<\/p>\n<p>En el sexto Ciriaco peg\u00f3 sencillo que impulso a Mois\u00e9s Sierra que la vuelta que empat\u00f3 el partido.<\/p>\n<p>Los felinos azules tomaron ventaja nuevamente en el partido en la baja del s\u00e9ptimo cuando Engel Beltr\u00e9, que lleg\u00f3 por doble, anot\u00f3 por sencillo de Yamaico Navarro, quien anot\u00f3 luego cuando Mel Rojas Jr., fue golpeado estando las bases llenas.<\/p>\n<p>Alex Valdez anot\u00f3 en jugada se selecci\u00f3n por batazo de Carlos Peguero, que fall\u00f3 por la v\u00eda 1-3 y Lew Ford anot\u00f3 desde segunda por sencillo al cuadro de Mois\u00e9s Sierra.<\/p>\n<p>En el cierre del noveno y con las bases llenas Juan Miranda bateo por el campo corto y Pedro L\u00f3pez dej\u00f3 escapar la bola para que Raymer Liriano anotara desde tercera con la carrera que decidi\u00f3 el partido. Liriano hab\u00eda entrado a correr en segunda por Yamaico Navarro.<\/p>\n<\/div>\n<div class=\"foto_central cutlineShow\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO. Los Leones del Escogido, que ganaron los primeros cuatro juegos de la serie final en l\u00ednea, deber\u00e1n esperar un sexto partido para optar por la corona. En el partido dominical los Tigres del Licey, sus archirrivales se impusieron siete carreras a seis para su primera victoria y romper una racha de nueve derrotas. El Escogido llevada 10 triunfos seguidos.<\/p>\n","protected":false},"author":12,"featured_media":52460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-52457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52457"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52457\/revisions"}],"predecessor-version":[{"id":52461,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52457\/revisions\/52461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/52460"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}