{"id":52463,"date":"2016-01-25T09:53:25","date_gmt":"2016-01-25T13:53:25","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52463"},"modified":"2016-01-25T09:53:25","modified_gmt":"2016-01-25T13:53:25","slug":"recomendaciones-de-la-oms-para-evitar-contagios-con-zika","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/recomendaciones-de-la-oms-para-evitar-contagios-con-zika\/","title":{"rendered":"Recomendaciones de la OMS para evitar contagios con zika"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_mosquito_tangenico.jpg\" rel=\"attachment wp-att-21911\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21911 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_mosquito_tangenico.jpg\" alt=\"mosquito_tangenico\" width=\"466\" height=\"314\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_mosquito_tangenico.jpg 466w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_mosquito_tangenico-300x202.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_mosquito_tangenico-75x52.jpg 75w\" sizes=\"auto, (max-width: 466px) 100vw, 466px\" \/><\/a>El <strong>virus zika<\/strong> es causado por la picadura de un mosquito y se cataloga como un arbovirus perteneciente al g\u00e9nero flavivirus, que son aquellos que animales invertebrados como zancudos y garrapatas le transmiten al ser humano. El zika es similar al dengue, la fiebre amarilla, el virus del Nilo Occidental y la encefalitis japonesa. El virus se identific\u00f3 en 1947 por primera vez en Uganda, espec\u00edficamente en los bosques de Zika.<!--more--><\/p>\n<p>En 2015 se ha detectado transmisi\u00f3n aut\u00f3ctona del virus en varios pa\u00edses de Am\u00e9rica Latina y ya se han detectado al menos dos casos en Catalu\u00f1a en mujeres procedentes de Latinoam\u00e9rica. La <strong>Organizaci\u00f3n Mundial de la Salud<\/strong>(OMS) no recomienda ninguna medida espec\u00edfica sobre planificaci\u00f3n familiar o restricciones de viajes para prevenir el contagio del virus del zika, tal y como pod\u00e9is ver en el v\u00eddeo que encabeza esta entrada:<\/p>\n<p>Seg\u00fan <strong>Christian Lindmeier<\/strong>, portavoz de la OMS, en una rueda de prensa al ser preguntado por las recomendaciones que Colombia y El Salvador han hecho a sus ciudadanas de posponer sus embarazos para evitar las consecuencias de un eventual contagio:<\/p>\n<blockquote><p>Nuestra posici\u00f3n es la misma de siempre (&#8230;). Cada pa\u00eds puede hacer lo que le parezca m\u00e1s conveniente.<\/p><\/blockquote>\n<p>Por ahora, la OMS contabiliza la presencia del virus en 20 pa\u00edses, con brotes de tama\u00f1o considerable en Brasil, Colombia, El Salvador, Panam\u00e1 y Cabo Verde. No hay una vacuna ni un tratamiento espec\u00edfico para el zika, s\u00f3lo un manejo sintom\u00e1tico que consiste en descansar y en tomar acetaminof\u00e9n o paracetamol para el control de la fiebre. <strong>La mayor\u00eda de las personas se recupera y la tasa de hospitalizaci\u00f3n es baja<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El virus zika es causado por la picadura de un mosquito y se cataloga como un arbovirus perteneciente al g\u00e9nero flavivirus, que son aquellos que animales invertebrados como zancudos y garrapatas le transmiten al ser humano. El zika es similar al dengue, la fiebre amarilla, el virus del Nilo Occidental y la encefalitis japonesa. El virus se identific\u00f3 en 1947 por primera vez en Uganda, espec\u00edficamente en los bosques de Zika.<\/p>\n","protected":false},"author":12,"featured_media":21911,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-52463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52463"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52463\/revisions"}],"predecessor-version":[{"id":52464,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52463\/revisions\/52464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/21911"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}