{"id":52480,"date":"2016-01-25T20:43:46","date_gmt":"2016-01-26T00:43:46","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52480"},"modified":"2016-01-25T20:43:46","modified_gmt":"2016-01-26T00:43:46","slug":"el-%c2%a8hombre-de-hielo%c2%a8-de-ee-uu-sobrevive-a-varias-horas-inconsciente-bajo-la-nieve","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-%c2%a8hombre-de-hielo%c2%a8-de-ee-uu-sobrevive-a-varias-horas-inconsciente-bajo-la-nieve\/","title":{"rendered":"El \u00a8Hombre de hielo\u00a8 de EE.UU.: sobrevive a varias horas inconsciente bajo la nieve"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/56a61e98c46188c97d8b457c.jpg\" rel=\"attachment wp-att-52481\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-52481\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/56a61e98c46188c97d8b457c.jpg\" alt=\"56a61e98c46188c97d8b457c\" width=\"750\" height=\"422\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/56a61e98c46188c97d8b457c.jpg 750w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/01\/56a61e98c46188c97d8b457c-300x169.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a>Un joven estadounidense pas\u00f3 horas moribundo bajo la nieve y la temperatura de su cuerpo descendi\u00f3 hasta 20 \u00baC, pero los m\u00e9dicos consiguieron salvar su vida.<!--more--><br \/>\nLa noche del 20 de febrero de 2015 Justin Smith, un hombre de 25 a\u00f1os, regresaba a su casa en McAdoo (Pensilvania, Estados Unidos) cuando tropez\u00f3, cay\u00f3 y qued\u00f3 tendido en la nieve, inconsciente. Al d\u00eda siguiente, su padre lo encontr\u00f3 con el rostro azul y sin signos de vida, seg\u00fan public\u00f3 &#8216;The Washington Post&#8217;.<\/p>\n<p>Los primeros param\u00e9dicos que atendieron a Justin lo dieron por muerto y las autoridades llamaron a un forense. Sin embargo, el doctor Gerald Coleman, del Hospital Lehigh Valley, orden\u00f3 que le realizaran maniobras cardiopulmonares de reanimaci\u00f3n porque \u00abtienes que estar caliente para estar muerto\u00bb.<\/p>\n<p>Los sanitarios trasladaron a Smith a un hospital y lo conectaron a una m\u00e1quina de oxigenaci\u00f3n por membrana extracorporal (ECMO, por sus siglas en ingl\u00e9s), con el objetivo de\u00a0calentar y oxigenar su sangre. En 90 minutos, su temperatura corporal \u2014que estaba por debajo de 20 \u00baC\u2014 comenz\u00f3 a subir y su coraz\u00f3n volvi\u00f3 a latir.<\/p>\n<p>\u00abNing\u00fan ser humano deber\u00eda ser capaz de sobrevivir con una temperatura corporal de 18 \u00baC y sin pulso durante 12 horas\u00bb, asegur\u00f3 el neur\u00f3logo John Castaldo. Sin embargo, el rebautizado como\u00a0&#8216;Hombre de hielo&#8217; ratific\u00f3 que el fr\u00edo puede ser un aliado a la hora de mantenernos con vida.<\/p>\n<p>El secreto radica en el modo en que se comport\u00f3 su organismo. A medida que baja la temperatura, el metabolismo ralentiza su funcionamiento, hasta que se pierde la consciencia y el coraz\u00f3n deja de latir. As\u00ed, s\u00f3lo fue necesario que los m\u00e9dicos elevaran la temperatura de Justin hasta los niveles habituales para que sus par\u00e1metros volvieran a la normalidad.<\/p>\n<p>Tras dos semanas en coma, Smith dej\u00f3 el hospital y se convirti\u00f3 en el caso de hipotermia m\u00e1s extremo jam\u00e1s tratado. El paciente perdi\u00f3 los dedos del pie y los me\u00f1iques de las manos por congelaci\u00f3n, aunque su cerebro no sufri\u00f3 ning\u00fan da\u00f1o. Los m\u00e9dicos\u00a0a\u00fan no est\u00e1n seguros del motivo, pero el doctor Colem\u00e1n asegur\u00f3 que este caso \u00abcambiar\u00e1 la manera de tratar a las personas con hipotermia\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un joven estadounidense pas\u00f3 horas moribundo bajo la nieve y la temperatura de su cuerpo descendi\u00f3 hasta 20 \u00baC, pero los m\u00e9dicos consiguieron salvar su vida.<\/p>\n","protected":false},"author":12,"featured_media":52481,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-52480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52480"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52480\/revisions"}],"predecessor-version":[{"id":52482,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52480\/revisions\/52482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/52481"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}