{"id":52495,"date":"2016-01-26T19:00:07","date_gmt":"2016-01-26T23:00:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52495"},"modified":"2016-01-26T19:00:07","modified_gmt":"2016-01-26T23:00:07","slug":"limpiaron-el-estadio-quisqueya-para-la-serie-del-caribe","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/limpiaron-el-estadio-quisqueya-para-la-serie-del-caribe\/","title":{"rendered":"Limpiaron el Estadio Quisqueya para La Serie del Caribe"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_Estadio_Quisqueya2_1fnghffsd.jpg\" rel=\"attachment wp-att-30018\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-30018 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_Estadio_Quisqueya2_1fnghffsd.jpg\" alt=\"Estadio_Quisqueya2_1fnghffsd\" width=\"352\" height=\"263\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_Estadio_Quisqueya2_1fnghffsd.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_Estadio_Quisqueya2_1fnghffsd-300x225.jpg 300w\" sizes=\"auto, (max-width: 352px) 100vw, 352px\" \/><\/a>El Ayuntamiento del Distrito Nacional (ADN) realiz\u00f3 un operativo de aseo, ornato y embellecimiento en infraestructura de espacios p\u00fablicos en el \u00e1rea interior del complejo deportivo Estadio Quisqueya Juan Marichal, de cara a la celebraci\u00f3n de la Serie de B\u00e9isbol del Caribe, con la participaci\u00f3n de cinco pa\u00edses.<!--more--><\/p>\n<p>El secretario de Gesti\u00f3n Ambiental y Riesgo del cabildo, ingeniero Jos\u00e9 Miguel Mart\u00ednez, explic\u00f3 que brigadas de t\u00e9cnicos y obreros realizaron trabajos de recogido de basura, pintura, fumigaci\u00f3n que permitir\u00e1 que el evento deportivo regional se desarrolle dentro de un ambiente adecuado para los visitantes.<\/p>\n<p>Destac\u00f3 el inter\u00e9s del Alcalde Roberto Salcedo para que los pa\u00edses visitantes a la justa deportiva sean recibidos con el esplendor y la hospitalidad que caracteriza a los dominicanos.<\/p>\n<p>Mart\u00ednez dijo que para las autoridades del cabildo es de suma importancia la cooperaci\u00f3n interinstitucional con la Liga Dominicana de B\u00e9isbol, teniendo en cuenta que ese es el deporte Rey de los dominicanos.<\/p>\n<p>La Serie de B\u00e9isbol del Caribe se iniciar\u00e1 en el Estadio Quisqueya Juan Marichal del primero al siete de febrero, con la participaci\u00f3n de los equipos ganadores de Puerto Rico, Cuba, Venezuela, M\u00e9xico, y el anfitri\u00f3n de Rep\u00fablica Dominicana.<\/p>\n<p><strong>Asimismo, Mart\u00ednez indic\u00f3 que el operativo incluy\u00f3 el coliseo box\u00edstico Carlos Teo Cruz, ubicado pr\u00f3ximo al estadio Quisqueya Juan Marichal, en el ensanche La Fe.<\/strong><\/p>\n<p>Dijo que esa infraestructura es un activo importante para el Distrito Nacional, debido a que all\u00ed se promociona la pr\u00e1ctica del deporte.<\/p>\n<p>Mart\u00ednez se\u00f1al\u00f3 que la promoci\u00f3n del deporte forma parte de una serie de pol\u00edticas que desarrolla el cabildo destinada a preservar la salud de los mun\u00edcipes del Distrito Nacional.<\/p>\n<figure id=\"attachment_249912\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/01\/Entorno-Estadio.jpg\" rel=\"attachment wp-att-249912\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-249912\" src=\"http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/01\/Entorno-Estadio-1024x576.jpg\" sizes=\"auto, (max-width: 587px) 100vw, 587px\" srcset=\"http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/01\/Entorno-Estadio-300x169.jpg 300w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/01\/Entorno-Estadio-768x432.jpg 768w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/01\/Entorno-Estadio-1024x576.jpg 1024w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/01\/Entorno-Estadio-747x420.jpg 747w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/01\/Entorno-Estadio-640x360.jpg 640w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/01\/Entorno-Estadio-681x383.jpg 681w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/01\/Entorno-Estadio.jpg 1256w\" alt=\"Entorno Estadio\" width=\"587\" height=\"330\" \/><\/a><figcaption class=\"wp-caption-text\">Obreros del cabildo trabajan en el ornato del Estadio Quisqueya Juan Marichal y el Coliseo Box\u00edstico Carlos Teo Cruz.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento del Distrito Nacional (ADN) realiz\u00f3 un operativo de aseo, ornato y embellecimiento en infraestructura de espacios p\u00fablicos en el \u00e1rea interior del complejo deportivo Estadio Quisqueya Juan Marichal, de cara a la celebraci\u00f3n de la Serie de B\u00e9isbol del Caribe, con la participaci\u00f3n de cinco pa\u00edses.<\/p>\n","protected":false},"author":12,"featured_media":29881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-52495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52495"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52495\/revisions"}],"predecessor-version":[{"id":52496,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52495\/revisions\/52496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29881"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}