{"id":52638,"date":"2016-02-03T09:49:17","date_gmt":"2016-02-03T13:49:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52638"},"modified":"2016-02-03T09:49:17","modified_gmt":"2016-02-03T13:49:17","slug":"venezuela-8-dominicana-7","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/venezuela-8-dominicana-7\/","title":{"rendered":"Venezuela 8, Dominicana 7"},"content":{"rendered":"<div id=\"ArticleSourceDiv\" class=\"article-body-author\"><b><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/bhg-300x199.jpeg\" rel=\"attachment wp-att-52640\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-52640 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/bhg-300x199.jpeg\" alt=\"bhg-300x199\" width=\"300\" height=\"199\" \/><\/a>Santo Domingo.-\u00a0<\/b>Junior Querecuto dio un sencillo en el cierre del d\u00e9cimo y los Tigres de Aragua dejaron en el terreno a los Leones del Escogido al superaos 8-7 viniendo de atr\u00e1s esta madrugada en la segunda fecha de la Serie del Caribe.<\/div>\n<p><!--more--><\/p>\n<div id=\"ArticleBody\">\n<p>Hern\u00e1n P\u00e9rez abri\u00f3 la entrada con un doblete a costa del relevista Jos\u00e9 Veras y avanz\u00f3 a tercera con un excelente toque de sacrificio de Sandy Le\u00f3n. Veras ponch\u00f3 al emergente Alexis N\u00fa\u00f1ez, pero Querecuto, el primer bate de Venezuela, lo castig\u00f3 con su l\u00ednea de hit por encima del cabeza del segunda base.<\/p>\n<p>Venezuela (2-0) empat\u00f3 en la primera posici\u00f3n con M\u00e9xico (2- 0), mientras que la Rep\u00fablica Dominicana ocupa el s\u00f3tano de la serie con 0-2.<\/p>\n<p>Las carreras Los Leones dominicanos hicieron un rally de cuatro anotaciones en el segundo contra el conocido lanzador Austin Bibens- Dirkx.<\/p>\n<p>Con hombres en primera y segunda y dos outs, la escuadra dominicana dio tres buenos batazos de hit por el jard\u00edn izquierdo.<\/p>\n<p>Junior Lake impuls\u00f3 la primera con sencillo, Carlos Paulino la segunda otro batazo de una base y el oportuno Pedro L\u00f3pez la tercera y la cuarta con doblete por la raya.\u00a0 Los Tigres de Aragua le hicieron una raya en el segundo al derecho Adrian Salcedo y tres en el tercero para empatar el encuentro.<\/p>\n<p>Una de esas carreras fue impulsada por F\u00e9lix P\u00e9rez con l\u00ednea de hit al prado derecho y dos con triple del bateador designado Dariel \u00c1lvarez.<\/p>\n<p>El segundo incogible de Paulino en el partido, que remolc\u00f3 a Mois\u00e9s Sierra, que corr\u00eda en tercera con un out, puso nuevamente al Escogido en ventaja 5-4, pero eso dur\u00f3 poco porque P\u00e9rez tambi\u00e9n impuls\u00f3 su segunda del cotejo con otro inatrapable al center para poner la pizarra 5-5 en el quinto.<\/p>\n<p>Ni Salcedo ni Bibens-Dirkx estuvieron a la altura de las circunstancias y el juego qued\u00f3 en manos del relevo. Luego de dos outs en el sexto, Lake conect\u00f3 un descomunal jonr\u00f3n al zurdo Wil Ledezma para que el colectivo quisqueyano se fuera adelante 6- 5 en la parte alta del sexto.<\/p>\n<p>Los Leones hicieron una importante segunda carrera de ventaja en el s\u00e9ptimo (7-5), cuando capitalizaron dos errores de los venezolanos. Un elevado de sacrificio de P\u00e9rez ante un Wirfin Obispo que anoche se present\u00f3 inefectivo, acerc\u00f3 a los de Aragua 7-6 en el octavo.<\/p>\n<p><strong>CORTOS<\/strong><br \/>\nBestial el bambinazo de Junior Lake y tambi\u00e9n el perreo\u2026 Ver para creer: Lew Ford todav\u00eda no ha dado hit en la serie. Anoche se ponch\u00f3 tres veces\u2026<\/p>\n<p>Un hijo de David Ortiz, uno de Juan Uribe y otro de Francisco Cordero participaron ayer en un mini Derby de Jonrones\u2026 Javier Sotomayor \u201cdebut\u00f3\u201d ayer como fan\u00e1tico de Serie del Caribe\u2026 \u201dEs la primera vez que vengo a una y me siento muy contento con estar disfrutando de este ambiente caribe\u00f1o\u201d, manifest\u00f3 el plusmarquista mundial y ol\u00edmpico de salto alto\u2026 Los Leones descansar\u00e1n hoy y ma\u00f1ana se medir\u00e1n a los Cangrejeros de Santurce con C\u00e9sar Valdez en el box\u2026<\/p>\n<p>Carlos Montesquieu se lanz\u00f3 semidesnudo ayer con la bandera colg\u00e1ndole del cuello y logr\u00f3 su objetivo de alcanzar cinco minutos de fama.<\/p>\n<p>Fuente: Listin Diario<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.-\u00a0Junior Querecuto dio un sencillo en el cierre del d\u00e9cimo y los Tigres de Aragua dejaron en el terreno a los Leones del Escogido al superaos 8-7 viniendo de atr\u00e1s esta madrugada en la segunda fecha de la Serie del Caribe.<\/p>\n","protected":false},"author":12,"featured_media":52640,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-52638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52638"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52638\/revisions"}],"predecessor-version":[{"id":52641,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52638\/revisions\/52641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/52640"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}