{"id":52846,"date":"2016-02-10T21:10:09","date_gmt":"2016-02-11T01:10:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52846"},"modified":"2016-02-10T21:10:09","modified_gmt":"2016-02-11T01:10:09","slug":"la-replica-china-del-titanic-zarpara-en-el-2018-y-su-interior-sera-identico-al-del-original","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-replica-china-del-titanic-zarpara-en-el-2018-y-su-interior-sera-identico-al-del-original\/","title":{"rendered":"La r\u00e9plica china del Titanic zarpar\u00e1 en el 2018, y su interior ser\u00e1 id\u00e9ntico al del original"},"content":{"rendered":"<p class=\"first-text\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/kvv9gqzhk8j59vkscnm1.jpg\" rel=\"attachment wp-att-52851\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-52851\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/kvv9gqzhk8j59vkscnm1.jpg\" alt=\"kvv9gqzhk8j59vkscnm1\" width=\"800\" height=\"410\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/kvv9gqzhk8j59vkscnm1.jpg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/kvv9gqzhk8j59vkscnm1-300x154.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/kvv9gqzhk8j59vkscnm1-768x394.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>La compa\u00f1\u00eda Blue Star Line est\u00e1 empe\u00f1ada en revivir a una de las embarcaciones m\u00e1s m\u00edticas de todos los tiempos, el Titanic. Actualmente se encuentran en proceso de desarrollo, y planean que sea una copia exacta (pero modernizada) del transatl\u00e1ntico. Estas son las primeras im\u00e1genes de su interior.<!--more--><br \/>\nBlue Star Line as\u00ed ha presentado un lote de im\u00e1genes computarizadas de c\u00f3mo lucir\u00e1 el interior del RMS Titanic II una vez est\u00e9 finalizado, y desde\u00a0<a href=\"http:\/\/www.dailymail.co.uk\/travel\/travel_news\/article-3440405\/Titanic-replica-photos-compare-original-ship.html\" target=\"_blank\">Daily Mail<\/a> las comparten. Aunque el nuevo transatl\u00e1ntico tendr\u00e1 motores m\u00e1s modernos que el que se hundi\u00f3 hace m\u00e1s de cien a\u00f1os, su interior ser\u00e1 una copia calcada del original.<\/p>\n<figure class=\"has-media media-large has-image\"><span class=\"lightBoxWrapper\"><span class=\"lightBoxWrapper\"><span class=\"img-border\"><img loading=\"lazy\" decoding=\"async\" class=\" cursor-pointer\" src=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--ghLhOSDA--\/c_scale,fl_progressive,q_80,w_800\/jkyeyjpscytyoehfeowe.jpg\" alt=\"La r\u00e9plica china del Titanic zarpar\u00e1 en el 2018, y su interior ser\u00e1 id\u00e9ntico al del original\" width=\"800\" height=\"399\" data-chomp-id=\"jkyeyjpscytyoehfeowe\" data-asset-url=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--ghLhOSDA--\/c_scale,fl_progressive,q_80,w_800\/jkyeyjpscytyoehfeowe.jpg\" data-format=\"jpg\" \/><\/span><\/span><\/span><figcaption>La habitaci\u00f3n de fumadores del Titanic original a la izquierda, la versi\u00f3n del Titanic II a la derecha.<\/figcaption><\/figure>\n<p>La idea de los responsables de este proyecto es que est\u00e9 finalizado para el a\u00f1o 2018, en el que realizar\u00eda su primer viaje desde Jiangsu, China, hasta la ciudad de Dubai.<\/p>\n<p>El Titanic se hundi\u00f3 en el a\u00f1o 1912 despu\u00e9s de colisionar contra un iceberg, y en este tr\u00e1gico accidente murieron m\u00e1s de 1500 personas. La r\u00e9plica tendr\u00e1 un costo de aproximadamente 430 millones de d\u00f3lares, lo cual es un aumento considerable en comparaci\u00f3n con los casi 8 millones de d\u00f3lares que cost\u00f3 fabricar el original.<\/p>\n<aside class=\"referenced-wide referenced-fullwidth js_inset tmpl_referencedGroupFullWidth clearfix core-decorated-inset\">\n<div class=\"container\"><\/div>\n<\/aside>\n<p>Las im\u00e1genes, aunque computarizadas, prometen que estamos ante una r\u00e9plica casi exacta del Titanic, barco que fuera el m\u00e1s grande del mundo para su momento, pero que actualmente no ser\u00eda tan grande como los transatl\u00e1nticos modernos.<\/p>\n<p>Entre las mayores diferencias del Titanic y el Titanic II se encuentra la presencia de un helipuerto, pero de resto incluso han mantenido los ba\u00f1os turcos y la piscina con el mismo estilo a la del original. [v\u00eda <a href=\"http:\/\/www.dailymail.co.uk\/travel\/travel_news\/article-3440405\/Titanic-replica-photos-compare-original-ship.html\" target=\"_blank\">Daily Mail<\/a>]<\/p>\n<h3>M\u00e1s im\u00e1genes del futuro Titanic II<\/h3>\n<p>Las escaleras principales en el Titanic original:<\/p>\n<figure class=\"has-media media-large has-image\"><span class=\"lightBoxWrapper\"><span class=\"img-border\"><img loading=\"lazy\" decoding=\"async\" class=\" cursor-pointer\" src=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--sX2l9HvC--\/c_scale,fl_progressive,q_80,w_800\/csv66rlrfg6ewt2l0fdd.jpg\" alt=\"La r\u00e9plica china del Titanic zarpar\u00e1 en el 2018, y su interior ser\u00e1 id\u00e9ntico al del original\" width=\"800\" height=\"551\" data-chomp-id=\"csv66rlrfg6ewt2l0fdd\" data-asset-url=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--sX2l9HvC--\/c_scale,fl_progressive,q_80,w_800\/csv66rlrfg6ewt2l0fdd.jpg\" data-format=\"jpg\" \/><\/span><\/span><\/figure>\n<p>La versi\u00f3n del Titanic II:<\/p>\n<figure class=\"has-media media-large has-image\"><span class=\"lightBoxWrapper\"><span class=\"img-border\"><img loading=\"lazy\" decoding=\"async\" class=\" cursor-pointer\" src=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--wA8uGroJ--\/c_scale,fl_progressive,q_80,w_800\/iofalvylrijyvdbcpokl.jpg\" alt=\"La r\u00e9plica china del Titanic zarpar\u00e1 en el 2018, y su interior ser\u00e1 id\u00e9ntico al del original\" width=\"800\" height=\"537\" data-chomp-id=\"iofalvylrijyvdbcpokl\" data-asset-url=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--wA8uGroJ--\/c_scale,fl_progressive,q_80,w_800\/iofalvylrijyvdbcpokl.jpg\" data-format=\"jpg\" \/><\/span><\/span><\/figure>\n<figure class=\"has-media media-large has-image\"><span class=\"lightBoxWrapper\"><span class=\"img-border\"><img loading=\"lazy\" decoding=\"async\" class=\" cursor-pointer\" src=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--nQE2cBZQ--\/c_scale,fl_progressive,q_80,w_800\/cao88binj9mmbqbpuv05.jpg\" alt=\"La r\u00e9plica china del Titanic zarpar\u00e1 en el 2018, y su interior ser\u00e1 id\u00e9ntico al del original\" width=\"800\" height=\"449\" data-chomp-id=\"cao88binj9mmbqbpuv05\" data-asset-url=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--nQE2cBZQ--\/c_scale,fl_progressive,q_80,w_800\/cao88binj9mmbqbpuv05.jpg\" data-format=\"jpg\" \/><\/span><\/span><\/figure>\n<p>El Caf\u00e9 Parisino en el Titanic:<\/p>\n<figure class=\"has-media media-large has-image\"><span class=\"lightBoxWrapper\"><span class=\"img-border\"><img loading=\"lazy\" decoding=\"async\" class=\" cursor-pointer\" src=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--D8S_s0oZ--\/c_scale,fl_progressive,q_80,w_800\/enpfo1snppklzviiknus.jpg\" alt=\"La r\u00e9plica china del Titanic zarpar\u00e1 en el 2018, y su interior ser\u00e1 id\u00e9ntico al del original\" width=\"800\" height=\"514\" data-chomp-id=\"enpfo1snppklzviiknus\" data-asset-url=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--D8S_s0oZ--\/c_scale,fl_progressive,q_80,w_800\/enpfo1snppklzviiknus.jpg\" data-format=\"jpg\" \/><\/span><\/span><\/figure>\n<p>Y en el Titanic II:<\/p>\n<figure class=\"has-media media-large has-image\"><span class=\"lightBoxWrapper\"><span class=\"img-border\"><img loading=\"lazy\" decoding=\"async\" class=\" cursor-pointer\" src=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--Q5g5N4Qu--\/c_scale,fl_progressive,q_80,w_800\/ztycqkgmeczwwzspyqaz.jpg\" alt=\"La r\u00e9plica china del Titanic zarpar\u00e1 en el 2018, y su interior ser\u00e1 id\u00e9ntico al del original\" width=\"800\" height=\"536\" data-chomp-id=\"ztycqkgmeczwwzspyqaz\" data-asset-url=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--Q5g5N4Qu--\/c_scale,fl_progressive,q_80,w_800\/ztycqkgmeczwwzspyqaz.jpg\" data-format=\"jpg\" \/><\/span><\/span><\/figure>\n<p>La piscina original a la izquierda, la nueva a la derecha:<\/p>\n<figure class=\"has-media media-large has-image\"><span class=\"lightBoxWrapper\"><span class=\"img-border\"><img loading=\"lazy\" decoding=\"async\" class=\" cursor-pointer\" src=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--dNguTp3n--\/c_scale,fl_progressive,q_80,w_800\/pahggmn1lqdjbufwdrmg.jpg\" alt=\"La r\u00e9plica china del Titanic zarpar\u00e1 en el 2018, y su interior ser\u00e1 id\u00e9ntico al del original\" width=\"800\" height=\"337\" data-chomp-id=\"pahggmn1lqdjbufwdrmg\" data-asset-url=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--dNguTp3n--\/c_scale,fl_progressive,q_80,w_800\/pahggmn1lqdjbufwdrmg.jpg\" data-format=\"jpg\" \/><\/span><\/span><\/figure>\n<p>La nueva piscina:<\/p>\n<figure class=\"has-media media-large has-image\"><span class=\"lightBoxWrapper\"><span class=\"img-border\"><img loading=\"lazy\" decoding=\"async\" class=\" cursor-pointer\" src=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--i2o_xUa5--\/c_scale,fl_progressive,q_80,w_800\/hd4iqn2obi0eailvujib.jpg\" alt=\"La r\u00e9plica china del Titanic zarpar\u00e1 en el 2018, y su interior ser\u00e1 id\u00e9ntico al del original\" width=\"800\" height=\"449\" data-chomp-id=\"hd4iqn2obi0eailvujib\" data-asset-url=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--i2o_xUa5--\/c_scale,fl_progressive,q_80,w_800\/hd4iqn2obi0eailvujib.jpg\" data-format=\"jpg\" \/><\/span><\/span><\/figure>\n<p>El restaurante principal del barco original:<\/p>\n<figure class=\"has-media media-large has-image\"><span class=\"lightBoxWrapper\"><span class=\"img-border\"><img loading=\"lazy\" decoding=\"async\" class=\" cursor-pointer\" src=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--yJ81y-e4--\/c_scale,fl_progressive,q_80,w_800\/hsuxclq4vmspw4dvuljo.jpg\" alt=\"La r\u00e9plica china del Titanic zarpar\u00e1 en el 2018, y su interior ser\u00e1 id\u00e9ntico al del original\" width=\"800\" height=\"510\" data-chomp-id=\"hsuxclq4vmspw4dvuljo\" data-asset-url=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--yJ81y-e4--\/c_scale,fl_progressive,q_80,w_800\/hsuxclq4vmspw4dvuljo.jpg\" data-format=\"jpg\" \/><\/span><\/span><\/figure>\n<p>La r\u00e9plica:<\/p>\n<figure class=\"has-media media-large has-image\"><span class=\"lightBoxWrapper\"><span class=\"img-border\"><img loading=\"lazy\" decoding=\"async\" class=\" cursor-pointer\" src=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--i5QQ4J3O--\/c_scale,fl_progressive,q_80,w_800\/phyocqcvtpa5owvobr10.jpg\" alt=\"La r\u00e9plica china del Titanic zarpar\u00e1 en el 2018, y su interior ser\u00e1 id\u00e9ntico al del original\" width=\"800\" height=\"552\" data-chomp-id=\"phyocqcvtpa5owvobr10\" data-asset-url=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--i5QQ4J3O--\/c_scale,fl_progressive,q_80,w_800\/phyocqcvtpa5owvobr10.jpg\" data-format=\"jpg\" \/><\/span><\/span><\/figure>\n<p>El nuevo puente de mando (con una r\u00e9plica del original al frente):<\/p>\n<figure class=\"has-media media-large has-image\"><span class=\"lightBoxWrapper\"><span class=\"img-border\"><img loading=\"lazy\" decoding=\"async\" class=\" cursor-pointer\" src=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--krT1h-hG--\/c_scale,fl_progressive,q_80,w_800\/bkfwo4ynjglkqcjdz8w4.jpg\" alt=\"La r\u00e9plica china del Titanic zarpar\u00e1 en el 2018, y su interior ser\u00e1 id\u00e9ntico al del original\" width=\"800\" height=\"449\" data-chomp-id=\"bkfwo4ynjglkqcjdz8w4\" data-asset-url=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--krT1h-hG--\/c_scale,fl_progressive,q_80,w_800\/bkfwo4ynjglkqcjdz8w4.jpg\" data-format=\"jpg\" \/><\/span><\/span><\/figure>\n<p>Las habitaciones m\u00e1s econ\u00f3micas del Titanic II:<\/p>\n<figure class=\"has-media media-large has-image\"><span class=\"lightBoxWrapper\"><span class=\"img-border\"><img loading=\"lazy\" decoding=\"async\" class=\" cursor-pointer\" src=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--vv-nYsVt--\/c_scale,fl_progressive,q_80,w_800\/nvv5yxem0tq6ffkmjorp.jpg\" alt=\"La r\u00e9plica china del Titanic zarpar\u00e1 en el 2018, y su interior ser\u00e1 id\u00e9ntico al del original\" width=\"800\" height=\"449\" data-chomp-id=\"nvv5yxem0tq6ffkmjorp\" data-asset-url=\"http:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/s--vv-nYsVt--\/c_scale,fl_progressive,q_80,w_800\/nvv5yxem0tq6ffkmjorp.jpg\" data-format=\"jpg\" \/><\/span><\/span><\/figure>\n<p><em>Foto de portada: Wikimedia Commons.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La compa\u00f1\u00eda Blue Star Line est\u00e1 empe\u00f1ada en revivir a una de las embarcaciones m\u00e1s m\u00edticas de todos los tiempos, el Titanic. Actualmente se encuentran en proceso de desarrollo, y planean que sea una copia exacta (pero modernizada) del transatl\u00e1ntico. Estas son las primeras im\u00e1genes de su interior.<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-52846","post","type-post","status-publish","format-standard","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52846"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52846\/revisions"}],"predecessor-version":[{"id":52852,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52846\/revisions\/52852"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}