{"id":52881,"date":"2016-02-11T13:41:08","date_gmt":"2016-02-11T17:41:08","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52881"},"modified":"2016-02-11T13:41:08","modified_gmt":"2016-02-11T17:41:08","slug":"sosuenses-reclaman-reparacion-tramo-carretero-sosua-la-union","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/sosuenses-reclaman-reparacion-tramo-carretero-sosua-la-union\/","title":{"rendered":"Sosuenses reclaman reparaci\u00f3n tramo carretero Sos\u00faa, La Uni\u00f3n"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/12688275_1940090372883428_1762007290952311287_n.jpg\" rel=\"attachment wp-att-52882\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-52882 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/12688275_1940090372883428_1762007290952311287_n.jpg\" alt=\"12688275_1940090372883428_1762007290952311287_n\" width=\"167\" height=\"279\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/12688275_1940090372883428_1762007290952311287_n.jpg 248w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/12688275_1940090372883428_1762007290952311287_n-180x300.jpg 180w\" sizes=\"auto, (max-width: 167px) 100vw, 167px\" \/><\/a>Sos\u00faa.- Ciudadanos manifestaron hoy a este redactor su indignaci\u00f3n por el mal estado que presenta el tramo carretero que conduce del Sos\u00faa a La Uni\u00f3n, ch\u00f3feres y transe\u00fantes que usan la referida v\u00eda se refirieron a la alta peligrosidad que contempla el uso de la misma por la gran cantidad de hoyos y abandono que desde hace varios a\u00f1os posee.<\/p>\n<p>Manifestaron que decenas de ciudadanos han perdido la vida al transitar por esta peligrosa v\u00eda, la cual est\u00e1 en total estado de deterioro desde hace varios a\u00f1os y las autoridades no toman la iniciativa de hacer algo por resolver este problema.<\/p>\n<p>Pidieron a las autoridades pertinentes tomar carta en el asunto antes de que m\u00e1s ciudadanos sigan perdiendo la vida en este tramo carretero, problema este que afecta ante la mirada ajena de quienes deben resolver el problema.<\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/12688379_1940090426216756_5256233226347638223_n.jpg\" rel=\"attachment wp-att-52883\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-52883 alignright\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/12688379_1940090426216756_5256233226347638223_n.jpg\" alt=\"12688379_1940090426216756_5256233226347638223_n\" width=\"169\" height=\"282\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/12688379_1940090426216756_5256233226347638223_n.jpg 576w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/12688379_1940090426216756_5256233226347638223_n-180x300.jpg 180w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Adujeron que somos un municipio\u00a0 tur\u00edstico y que por ende con la llegada de los cruceros y los visitantes vienen a disfrutar de la bellezas naturales que adornan la zona se ven compelidos a enfrentar esta v\u00eda llena de hoyos la cual se torna peligrosa.<\/p>\n<p>Declararon que somos uno de los municipios que m\u00e1s aporta al fisco y que da pena que nuestra principal v\u00eda de acceso, presente tal estado por lo que esperan el presidente Medina quien estar\u00e1 este mi\u00e9rcoles en Puerto Plata ordene la reconstrucci\u00f3n de tan importante v\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/sosuadigital.net\/noticias-del-momento\/5722-2016-02-09-04-14-19.html\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa.- Ciudadanos manifestaron hoy a este redactor su indignaci\u00f3n por el mal estado que presenta el tramo carretero que conduce del Sos\u00faa a La Uni\u00f3n, ch\u00f3feres y transe\u00fantes que usan la referida v\u00eda se refirieron a la alta peligrosidad que contempla el uso de la misma por la gran cantidad de hoyos y abandono que desde hace varios a\u00f1os posee. Manifestaron que decenas de ciudadanos han perdido la vida al transitar por esta peligrosa v\u00eda, la cual est\u00e1 en total estado de deterioro desde hace varios a\u00f1os y las autoridades no toman la iniciativa de hacer algo por resolver este problema. Pidieron a las autoridades pertinentes tomar carta en el asunto antes de que m\u00e1s ciudadanos sigan perdiendo la vida en este tramo carretero, problema este que afecta ante la mirada ajena de quienes deben resolver el problema. &nbsp; Adujeron que somos un municipio\u00a0 tur\u00edstico y que por ende con la llegada de los cruceros y los visitantes vienen a disfrutar de la bellezas naturales que adornan la zona se ven compelidos a enfrentar esta v\u00eda llena de hoyos la cual se torna peligrosa. Declararon que somos uno de los municipios que m\u00e1s aporta al fisco y que da pena que nuestra principal v\u00eda de acceso, presente tal estado por lo que esperan el presidente Medina quien estar\u00e1 este mi\u00e9rcoles en Puerto Plata ordene la reconstrucci\u00f3n de tan importante v\u00eda. &nbsp; FUENTE<\/p>\n","protected":false},"author":12,"featured_media":52883,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-52881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52881"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52881\/revisions"}],"predecessor-version":[{"id":52884,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52881\/revisions\/52884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/52883"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}