{"id":52942,"date":"2016-02-12T17:15:07","date_gmt":"2016-02-12T21:15:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=52942"},"modified":"2016-02-12T14:28:25","modified_gmt":"2016-02-12T18:28:25","slug":"como-hacer-en-casa-tu-propio-jabon-liquido-para-las-manos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/como-hacer-en-casa-tu-propio-jabon-liquido-para-las-manos\/","title":{"rendered":"C\u00f3mo hacer en casa tu propio jab\u00f3n l\u00edquido para las manos"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/Jab\u00f3n-l\u00edquido-casero-500x281.jpg\" rel=\"attachment wp-att-52945\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-52945\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/Jab\u00f3n-l\u00edquido-casero-500x281.jpg\" alt=\"Jab\u00f3n-l\u00edquido-casero-500x281\" width=\"500\" height=\"281\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/Jab\u00f3n-l\u00edquido-casero-500x281.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/Jab\u00f3n-l\u00edquido-casero-500x281-300x169.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a>En lugar del aceite esencial de lim\u00f3n, a la hora de elaborar nuestro jab\u00f3n l\u00edquido podemos a\u00f1adirle alguno con propiedades antibacterianas para as\u00ed aprovechar sus beneficios.<!--more--><\/p>\n<p><strong>El jab\u00f3n l\u00edquido para las manos se ha convertido en uno de los productos imprescindibles<\/strong> en la mayor\u00eda de los hogares, ya que con este es muy f\u00e1cil remover las bacterias y suciedad que van adquiriendo por el contacto con diversas superficies.<\/p>\n<p>Aunque hay quienes a\u00fan utilizan la cl\u00e1sica barra, <strong>son muchos los que est\u00e1n prefiriendo la presentaci\u00f3n l\u00edquida<\/strong> por considerar que es m\u00e1s pr\u00e1ctica, higi\u00e9nica y econ\u00f3mica.<\/p>\n<p>En la actualidad se puede adquirir en diversos tama\u00f1os y marcas en el mercado, pero tambi\u00e9n hay sencillas recetas para prepararlo en casa.<\/p>\n<div id=\"beacon_d251834dc9\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/cat.ny.us.criteo.com\/delivery\/lg.php?cppv=1&amp;cpp=nrxePHxPelZaclNXa1B2eWlXandKRW1DL1BieTFDYm5CM3ZKcDVrYlJScUNFMXA5b3h5c3JFTkxXVzc0akdMSkVHcVp6WWpLL1RzNXJHeUZpMUFlc3BxUzd4TTRObTBlY3BLT0R0M3kvMTM2WmlWNURsZGhGZmIzcnlnb2s0QVh0eUFQNmFwN0ZEa3Nrc080bGpyYzhwbkFxMTJ2L1VpN3prNlB5V2V3Y3NrRkxPazk2NkdiOWloaUNQZEFsZ2MzM1R2QjF4ckR5dFNHRE9lTmFkcng2MnZwMTkveHNTUk9uNWd3MmhZa2JIQklpdGN3PXw%3D\" alt=\"\" width=\"0\" height=\"0\" \/><\/div>\n<p>En esta ocasi\u00f3n <strong>queremos compartir un par de f\u00f3rmulas\u00a0f\u00e1ciles\u00a0para que intentes elaborarlos <\/strong>con ingredientes que seguro tienes en tu hogar.<\/p>\n<h2>\u00bfPor qu\u00e9 preparar jab\u00f3n l\u00edquido casero?<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-92804\" src=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2016\/02\/Por-qu%C3%A9-preparar-jab%C3%B3n-l%C3%ADquido-casero-500x334.jpg\" alt=\"Por qu\u00e9 preparar jab\u00f3n l\u00edquido casero\" width=\"500\" height=\"334\" \/><\/p>\n<p>La idea de preparar jab\u00f3n l\u00edquido casero surge de la necesidad de utilizar este producto para el cuidado y la desinfecci\u00f3n de las manos.<\/p>\n<p>Una de las principales ventajas de hacerlo en casa es que <strong>se pueden reutilizar algunos ingredientes <\/strong>que a simple vista parec\u00edan no tener m\u00e1s uso.<\/p>\n<p>Son libres de fragancias o productos qu\u00edmicos propios de los jabones comerciales, los cuales en ocasiones causan alergias e irritaciones.<\/p>\n<p><strong>Los compuestos que utiliza son muy suaves con la piel<\/strong> y reduce la presencia de alteraciones cut\u00e1neas como la sequedad o la dermatitis.<\/p>\n<p>Cabe\u00a0 destacar que tambi\u00e9n son m\u00e1s amigables con el medio ambiente y permiten ahorrar mucho dinero en comparaci\u00f3n con los convencionales.<\/p>\n<h2>Jab\u00f3n l\u00edquido casero de lim\u00f3n para las manos<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-92805\" src=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2016\/02\/Jab%C3%B3n-l%C3%ADquido-casero-de-lim%C3%B3n-para-las-manos-500x334.jpg\" alt=\"Jab\u00f3n l\u00edquido casero de lim\u00f3n para las manos\" width=\"500\" height=\"334\" \/><\/p>\n<p>Esta receta invita a aprovechar esos restos de jab\u00f3n que van quedando cuando la pastilla\u00a0ya est\u00e1 demasiado gastada.<\/p>\n<p>Contiene glicerina, una sustancia que ayuda a <strong>mantener el equilibrio del pH natural de la piel para conservarla suave.<\/strong><\/p>\n<p>En este caso elegimos como fragancia el aceite esencial de lim\u00f3n, aunque tambi\u00e9n se pueden elegir otros aromas que tengan propiedades antibacterianas.<\/p>\n<div class=\"ad-desktop\">\n<div id=\"div-gpt-ad-1443439665272-0\">\n<div id=\"div-gpt-ad-1443439665272-0_ad_container\">\n<div><object data=\"http:\/\/pagead2.googlesyndication.com\/osd\/hbe.swf?id=1~0\" type=\"application\/x-shockwave-flash\" width=\"1\" height=\"1\"><\/object><\/div>\n<div class=\"adm-intext\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<h3>Ingredientes<\/h3>\n<ul>\n<li>2 litros de agua<\/li>\n<li>2 vasos de sobrantes de jab\u00f3n en barra (400 g)<\/li>\n<li>10 gotas de aceite esencial de lim\u00f3n.<\/li>\n<li>1 cucharada de glicerina pura (10 g)<\/li>\n<li>1 botella de pl\u00e1stico con dosificador<\/li>\n<\/ul>\n<h3>\u00bfC\u00f3mo prepararlo?<\/h3>\n<ul>\n<li>Para empezar, toma los restos de jab\u00f3n en barra y r\u00e1llalos en peque\u00f1os copos.<\/li>\n<li>Luego, coloca a hervir la mitad del agua en una cacerola y d\u00e9jala a fuego medio.<\/li>\n<li>Cuando ya est\u00e9 caliente, incorpora el jab\u00f3n rallado y la cucharada de glicerina.<\/li>\n<li>Remueve bien para que todo quede bien disuelto y ap\u00e1galo despu\u00e9s de unos minutos.<\/li>\n<li>Cuando la mezcla se enfr\u00ede, a\u00f1ade el aceite esencial de lim\u00f3n y vuelve a remover.<\/li>\n<li>A continuaci\u00f3n, vierte el l\u00edquido en una botella con dosificador y col\u00f3cala en un lugar fresco y seco.<\/li>\n<li>El jab\u00f3n te durar\u00e1 en perfecto estado hasta seis meses.<\/li>\n<\/ul>\n<h2>Jab\u00f3n l\u00edquido casero de aceite para las manos<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-55726\" src=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2015\/04\/Jabon-casero-500x322.jpg\" alt=\"Jabon-casero\" width=\"500\" height=\"322\" \/><\/p>\n<p>Esta alternativa casera es ideal para <strong>sacarle mucho provecho a esos restos del aceite de oliva o girasol que nos van quedando.<\/strong><\/p>\n<p>Sin embargo, a diferencia de la opci\u00f3n anterior, este solo se ha de utilizar un mes despu\u00e9s de su elaboraci\u00f3n porque contiene sosa c\u00e1ustica, una sustancia que resulta agresiva con la piel cuando no se mezcla con otros ingredientes.<\/p>\n<p>Para manipularla <strong>se debe utilizar guantes, tapabocas y una habitaci\u00f3n bien ventilada<\/strong> que permita disipar los gases que se liberan.<\/p>\n<p>Una recomendaci\u00f3n es medir su pH antes de utilizarlo para comprobar que es el id\u00f3neo para la piel.<\/p>\n<h3>Ingredientes<\/h3>\n<ul>\n<li>3 litros de agua<\/li>\n<li>1 \u00bd\u00a0taza de aceite de girasol u oliva usado (375 ml)<\/li>\n<li>7 \u00bd cucharadas de sosa c\u00e1ustica (75 g)<\/li>\n<li>1 cucharadita de sal (5 g)<\/li>\n<li>Aceite esencial (aroma al gusto)<\/li>\n<\/ul>\n<h3>Preparaci\u00f3n<\/h3>\n<ul>\n<li>Mezcla la sosa c\u00e1ustica con el agua, teniendo mucho cuidado para no inhalar los gases que libera y tampoco entrar en contacto con la mezcla en reacci\u00f3n.<\/li>\n<li>Remueve bien con una cuchara de palo hasta que las escamas de sosa que se forman queden bien disueltas.<\/li>\n<li>Incorpora poco a poco el aceite usado (previamente colado) y remueve, siempre en el mismo sentido.<\/li>\n<li>A\u00f1ade la sal y tambi\u00e9n algunas gotas del aceite esencial que elegiste como aroma.<\/li>\n<li>Introduce la mezcla en un frasco con dosificador, ag\u00edtala dos veces al d\u00eda y d\u00e9jala destapada en un lugar fresco y sin luz.<\/li>\n<li>Pasado el tiempo aconsejado (un mes) se le puede agregar m\u00e1s aceite esencial para resaltar su olor.<\/li>\n<\/ul>\n<p>\u00bfTe gustaron estas recetas? No dudes en ponerte manos a la obra para que las pruebes en tu hogar. Sigue todas las recomendaciones dadas y comprueba que son una gran alternativa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En lugar del aceite esencial de lim\u00f3n, a la hora de elaborar nuestro jab\u00f3n l\u00edquido podemos a\u00f1adirle alguno con propiedades antibacterianas para as\u00ed aprovechar sus beneficios.<\/p>\n","protected":false},"author":12,"featured_media":52945,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-52942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=52942"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52942\/revisions"}],"predecessor-version":[{"id":52946,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/52942\/revisions\/52946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/52945"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=52942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=52942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=52942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}