{"id":53098,"date":"2016-02-17T16:03:01","date_gmt":"2016-02-17T20:03:01","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=53098"},"modified":"2016-02-17T16:03:01","modified_gmt":"2016-02-17T20:03:01","slug":"belinda-incomoda-al-papa-francisco-en-morelia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/belinda-incomoda-al-papa-francisco-en-morelia\/","title":{"rendered":"Belinda incomoda al Papa Francisco en Morelia"},"content":{"rendered":"<div id=\"attachment_53099\" style=\"width: 438px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/belinda_twitter_papa_destacada.jpg\" rel=\"attachment wp-att-53099\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-53099\" class=\" wp-image-53099\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/belinda_twitter_papa_destacada.jpg\" alt=\"Belinda al lado del gobernador de Morelia, Silvano Aureoles (Foto: Twitter)\" width=\"428\" height=\"227\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/belinda_twitter_papa_destacada.jpg 660w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/belinda_twitter_papa_destacada-300x159.jpg 300w\" sizes=\"auto, (max-width: 428px) 100vw, 428px\" \/><\/a><p id=\"caption-attachment-53099\" class=\"wp-caption-text\">Belinda al lado del gobernador de Morelia, Silvano Aureoles (Foto: Twitter)<\/p><\/div>\n<p>La cantante mexicana Belinda asisti\u00f3 al aeropuerto de Morelia para despedir al Papa Francisco, quien fue incomodado por dicha presencia ya que el lugar donde se encontraba estaba dispuesto para personas enfermas o con alguna discapacidad.<!--more--><\/p>\n<p>Durante la transmisi\u00f3n en vivo de la despedida del Papa de Morelia, la periodista Valentina Alazraki coment\u00f3 \u201calgo molest\u00f3 al Santo Padre, parece que vio a una persona ocupando un lugar que no deber\u00eda (mientras se observaba como Belinda sosten\u00eda la mano al Papa)\u201d.<\/p>\n<p>Alazraki se\u00f1al\u00f3 que Belinda ocupaba un lugar que estaba destinado especialmente para personas enfermas o con alguna discapacidad, cuesti\u00f3n que incomod\u00f3 al Papa y mostr\u00f3 su rechazo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cantante mexicana Belinda asisti\u00f3 al aeropuerto de Morelia para despedir al Papa Francisco, quien fue incomodado por dicha presencia ya que el lugar donde se encontraba estaba dispuesto para personas enfermas o con alguna discapacidad.<\/p>\n","protected":false},"author":12,"featured_media":53099,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-53098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=53098"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53098\/revisions"}],"predecessor-version":[{"id":53100,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53098\/revisions\/53100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/53099"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=53098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=53098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=53098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}