{"id":53181,"date":"2016-02-19T18:45:29","date_gmt":"2016-02-19T22:45:29","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=53181"},"modified":"2016-02-19T18:45:29","modified_gmt":"2016-02-19T22:45:29","slug":"alex-la-pesadilla-dominicana-garcia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/alex-la-pesadilla-dominicana-garcia\/","title":{"rendered":"Alex \u201cLa Pesadilla Dominicana\u201d Garcia"},"content":{"rendered":"<p><span class=\"notranslate\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/PortadaAlexGarcia-1024x359.jpg\" rel=\"attachment wp-att-53182\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-53182\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/PortadaAlexGarcia-1024x359.jpg\" alt=\"PortadaAlexGarcia-1024x359\" width=\"850\" height=\"298\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/PortadaAlexGarcia-1024x359.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/PortadaAlexGarcia-1024x359-300x105.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/PortadaAlexGarcia-1024x359-768x269.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/a>El primer dominicano en poner pie dentro del\u00a0oct\u00e1gono de la UFC (Ultimate Fighting Championship). Alex \u00a0\u201cLa pesadilla Dominicana\u201d Garc\u00eda dice que est\u00e1 listo para la batalla contra Sean Strickland.\u00a0<\/span> <span class=\"notranslate\">Cuenta que sigue\u00a0entrenando duro para hacer un buen trabajo en el oct\u00e1gono de UFC y dar la victoria a todos los Dominicanos que estar\u00e1n atentos a la lucha el 21 de febrero en Pittsburgh, Pennsylvania EE.UU..<\/span><!--more--><\/p>\n<blockquote><p><span class=\"notranslate\">\u201c<\/span>Me siento muy c\u00f3modo con los entrenamientos, estoy satisfecho por todo el apoyo que me est\u00e1n dando mi equipo de\u00a0Tristar Gym\u00a0y Tomas So\u00f1e (Papo). Estoy listo para obtener los mejores resultados y\u00a0dar lo mejor de mi en el ring el pr\u00f3ximo 21 de febrero.\u201d\u00a0<span class=\"notranslate\">\u2013 Alex Garc\u00eda\u00a0<\/span><\/p><\/blockquote>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/Alex-Garcia-UFC-2-1-727x1024.jpg\" rel=\"attachment wp-att-53183\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-53183\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/Alex-Garcia-UFC-2-1-727x1024.jpg\" alt=\"Alex-Garcia-UFC-2-1-727x1024\" width=\"727\" height=\"1024\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/Alex-Garcia-UFC-2-1-727x1024.jpg 727w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/Alex-Garcia-UFC-2-1-727x1024-213x300.jpg 213w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/><\/a><\/p>\n<p><span class=\"notranslate\">Alex \u201cLa Pesadilla Dominicana\u201d Garcia vive y entrena en Montreal, Canad\u00e1 desde que comenz\u00f3 su carrera de artes marciales mixtas (MMA).<\/span> <span class=\"notranslate\">\u201cLa pesadilla Dominicana\u201d hizo su debut en el verano de 2009 en contra de Joel Vales en la AFC (Fighting Championship de Australia), pelea que gano por sumisi\u00f3n en el primer asalto.<\/span> <span class=\"notranslate\">Se entrena con el combatiente de peso welter de Canad\u00e1, y leyenda de MMA, <strong>Georges St-Pierre<\/strong> en Tristar Gym.<\/span> <span class=\"notranslate\">Como un verdadero artista de artes marciales tiene una mezcla de estilos de pelea\u00a0que incorpora en el oct\u00e1gono incluyendo el boxeo, Jiu Jitsu, lucha libre y Muay Thai.<\/span>\u00a0Ha g<span class=\"notranslate\">anado medallas en torneos de Jiu-Jitsu brasile\u00f1o y logro\u00a0convertirse en Campe\u00f3n Nacional en la AFC.<\/span> <span class=\"notranslate\">Luciendo un r\u00e9cord de trece victorias y dos derrotas, con la primera derrota\u00a0en 2011 contra Seth Baczynski (esta victoria le gan\u00f3 a Baczynski un boleto para el UFC).<\/span> <span class=\"notranslate\">Afirma que esta p\u00e9rdida fue una gran experiencia de aprendizaje que le permiti\u00f3 evolucionar a\u00a0un peleador\u00a0m\u00e1s redondeado, profesional y capaz de\u00a0controlar gran parte de sus herramientas como un luchador mas efectivamente.<\/span> <span class=\"notranslate\">Sus victorias se dividen en 5 a modo de sumisi\u00f3n, 5 TKO \/ KO y 3 decisiones, lo que demuestra lo bien redondeado que es y como\u00a0sigue creciendo.<\/span><\/p>\n<p><span class=\"notranslate\"><strong>Su pr\u00f3xima pelea contra Sean Strickland ser\u00e1 transmitido por el canal oficial de la UFC, Fox Sports 1 (FS1) y en su natal Rep\u00fablica Dominicana se puede ver en el canal de Claro TV -UFC red 641 para SD y el canal UFC Red HD 1641. Tambi\u00e9n por Telecable Tricom \u2013 Fox Sport 2 canales 361 para SD y HD canal de UFC 470.<\/strong><\/span><\/p>\n<h3><span class=\"notranslate\">Una peque\u00f1a mirada a qui\u00e9n es Alex \u201cThe Nightmare Dominicana\u201d Garc\u00eda<\/span><\/h3>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/Alex-Garcia-UFC-1-1-1024x683.jpg\" rel=\"attachment wp-att-53184\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-53184\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/Alex-Garcia-UFC-1-1-1024x683.jpg\" alt=\"Alex-Garcia-UFC-1-1-1024x683\" width=\"1024\" height=\"683\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/Alex-Garcia-UFC-1-1-1024x683.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/Alex-Garcia-UFC-1-1-1024x683-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/Alex-Garcia-UFC-1-1-1024x683-768x512.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p><span class=\"notranslate\">Alex Garc\u00eda es un peleador\u00a0de MMA profesional firmado por Ultimate Fighting Championship <strong>(UFC). <\/strong>El 8\u00a0De octubre de, 2013 se anunci\u00f3 que Garc\u00eda firm\u00f3 con el UFC y har\u00eda su debut en el UFC Fight Night 33.<\/span><\/p>\n<p>Nacido el 14 de julio de 1987, en Santiago y criado en Cabarete. comenz\u00f3 a luchar desde los 19 a\u00f1os, practicando Jiu Jitsu brasile\u00f1o en la Academia Jiu Jitsu de la Costa en Cabarete ; gan\u00f3 medallas en los torneos de JIU JITSU Brasile\u00f1o y fue el Campe\u00f3n Nacional en Australian Fighting Championship (AFC). Mide 5 pies 9 pulgadas y un peso de 170 Libras. El agarre y la t\u00e9cnica preferida del dominicano son el Triangulo y Nocaut respectivamente.\u00a0<span class=\"notranslate\">Que compite en la divisi\u00f3n de peso welter y es entrenado por Firas Zahabi, John Chaimberg, Peter Sisomphou, Eric O\u2019Keefe.<\/span> <span class=\"notranslate\">Tambi\u00e9n ha entrenado por Bruno Fernandes, Victor Zilberman y Tomas So\u00f1e (Papo).<\/span><\/p>\n<p><span class=\"notranslate\">Para seguirlo en los medios sociales:<\/span><\/p>\n<p>Instagram: <a href=\"http:\/\/www.instagram.com\/Alexgarciamma\" target=\"_blank\">@Alexgarciamma<\/a><br \/>\nFacebook: <a href=\"https:\/\/www.facebook.com\/AlexGarciaMMA\/\" target=\"_blank\">Alexgarciamma<\/a><br \/>\nTwitter: <a href=\"http:\/\/www.twitter.com\/Alexgarciamma\" target=\"_blank\">@Alexgarciamma<br \/>\n<\/a><a href=\"http:\/\/www.ufc.com\/fighter\/Alex-Garcia\" target=\"_blank\">www.ufc.com\/fighter\/Alex-Garcia<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El primer dominicano en poner pie dentro del\u00a0oct\u00e1gono de la UFC (Ultimate Fighting Championship). Alex \u00a0\u201cLa pesadilla Dominicana\u201d Garc\u00eda dice que est\u00e1 listo para la batalla contra Sean Strickland.\u00a0 Cuenta que sigue\u00a0entrenando duro para hacer un buen trabajo en el oct\u00e1gono de UFC y dar la victoria a todos los Dominicanos que estar\u00e1n atentos a la lucha el 21 de febrero en Pittsburgh, Pennsylvania EE.UU..<\/p>\n","protected":false},"author":12,"featured_media":53184,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,3],"tags":[],"class_list":["post-53181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=53181"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53181\/revisions"}],"predecessor-version":[{"id":53186,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53181\/revisions\/53186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/53184"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=53181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=53181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=53181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}