{"id":53318,"date":"2016-02-23T10:26:49","date_gmt":"2016-02-23T14:26:49","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=53318"},"modified":"2016-02-23T10:26:49","modified_gmt":"2016-02-23T14:26:49","slug":"a-prision-dueno-de-club-nocturno-del-este-que-vendia-a-rd-como-destino-sexual","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/a-prision-dueno-de-club-nocturno-del-este-que-vendia-a-rd-como-destino-sexual\/","title":{"rendered":"A prisi\u00f3n due\u00f1o de club nocturno del Este que vend\u00eda a RD como destino sexual"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/JUICIO.jpg\" rel=\"attachment wp-att-53322\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53322 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/JUICIO.jpg\" alt=\"JUICIO\" width=\"401\" height=\"267\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/JUICIO.jpg 580w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/JUICIO-300x200.jpg 300w\" sizes=\"auto, (max-width: 401px) 100vw, 401px\" \/><\/a>SANTO DOMINGO (Rep. Dominicana)<\/strong>.-Una jueza de la provincia La Altagracia impuso tres meses de prisi\u00f3n preventiva en contra de ocho hombres, incluyendo el propietario del\u00a0night\u00a0club Ladies Factory, acusado por el Ministerio P\u00fablico de dedicarse al proxenetismo y al lavado de activos.<!--more--><\/p>\n<p>La medida cautelar fue impuesta por la Oficina Judicial de Servicios de Atenci\u00f3n Permanente de La Altagracia en contra de los imputados Lorenzo Arech\u00e9 Melo (propietario del\u00a0night\u00a0club) y a sus empleados Joaqu\u00edn Guerrero Garrido, Miguel Polanco V\u00e1squez, Amos Jean Pierre, Juan Isidro Rosario Batista, V\u00edctor Luis Pinales, Edwin P\u00e9rez y Juan Manuel Herrera Espinosa.<em>\u00a0<\/em><\/p>\n<p>Durante un allanamiento realizado en el establecimiento nigth club Ladies Factory, conocido como \u201cLas Conejitas\u201d, que funciona en la calle Los Tainos, Friusa, Distrito Municipal Ver\u00f3n-B\u00e1varo, las autoridades encontraron a 31 mujeres que supuestamente se encontraban en dicho lugar contratadas para ejercer presumiblemente la prostituci\u00f3n.<\/p>\n<p>La investigaci\u00f3n es llevada a cabo por la Procuradur\u00eda Especializada contra el Tr\u00e1fico Il\u00edcito de Migrantes y Trata de Personas y la Procuradur\u00eda Especializada Antilavado de Activos en coordinaci\u00f3n con la Fiscal\u00eda de la provincia La Altagracia.<\/p>\n<p>El imputado Lorenzo Arech\u00e9 Melo alegadamente promov\u00eda a Rep\u00fablica Dominicana como un destino sexual en el exterior, incluso colocando vallas en distintas zonas de la provincia La Altagracia. Seg\u00fan la Procuradur\u00eda, con el negocio el imputado obtuvo muchos bienes provenientes del proxenetismo.<\/p>\n<p>El Ministerio P\u00fablico estuvo representado en la medida de coerci\u00f3n por los magistrados Jonathan Bar\u00f3 Guti\u00e9rrez, titular de la procuradur\u00eda especializada, y el fiscal titular de La Altagracia Edwin Encarnaci\u00f3n, as\u00ed como por Belkis Ulloa Uceta, Idalia Peralta y Aneuris Castillo, quienes presentaron diferentes elementos de pruebas que vinculan a los procesados con los delitos que se les imputan.<\/p>\n<p>La jueza del Tribunal de Atenci\u00f3n Permanente, Francis Vilorio, dispuso que la medida cautelar sea cumplida en el Centro de Correcci\u00f3n y Rehabilitaci\u00f3n Anamuya de esa provincia.<\/p>\n<p>El Ministerio P\u00fablico le ha otorgado al presente hecho la calificaci\u00f3n jur\u00eddica de proxenetismo agravado, los cuales se encuentran tipificados y sancionados en las disposiciones de los art\u00edculos 334 y 334-1 del C\u00f3digo Penal Dominicano y en la Ley 72-02 sobre Lavado de Activos Provenientes del Tr\u00e1fico Il\u00edcito de Drogas y Sustancias Controladas y otras Infracciones Graves), establecido en los art\u00edculos 1 (numeral 7), 3 (literal a) y 18, en perjuicio del Estado dominicano.<\/p>\n<p><a href=\"http:\/\/www.7dias.com.do\/portada\/2016\/02\/23\/i205822_prision-dueno-club-nocturno-del-este-que-vendia-como-destino-sexual.html#.VsxqwfJ96M9\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO (Rep. Dominicana).-Una jueza de la provincia La Altagracia impuso tres meses de prisi\u00f3n preventiva en contra de ocho hombres, incluyendo el propietario del\u00a0night\u00a0club Ladies Factory, acusado por el Ministerio P\u00fablico de dedicarse al proxenetismo y al lavado de activos.<\/p>\n","protected":false},"author":12,"featured_media":53322,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-53318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=53318"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53318\/revisions"}],"predecessor-version":[{"id":53323,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53318\/revisions\/53323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/53322"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=53318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=53318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=53318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}