{"id":53406,"date":"2016-02-24T21:45:47","date_gmt":"2016-02-25T01:45:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=53406"},"modified":"2016-02-24T21:45:47","modified_gmt":"2016-02-25T01:45:47","slug":"cuidando-hasta-tu-salud-si-tienes-mascotas-te-enfermas-menos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cuidando-hasta-tu-salud-si-tienes-mascotas-te-enfermas-menos\/","title":{"rendered":"\u00a1Cuidando hasta tu salud! Si tienes mascotas, te enfermas menos"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-long field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>\u201cNo dejes que tu beb\u00e9 est\u00e9 cerca de los perros, se pueden enfermar\u201d. De acuerdo con un estudio, esta frase est\u00e1 alejada de la realidad, ya que las mascotas cuidan tu <label>salud<\/label>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"field field-name-field-image field-type-image field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/baby-dog_por_fernando_garcia.jpg\" rel=\"attachment wp-att-53415\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-53415\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/baby-dog_por_fernando_garcia.jpg\" alt=\"baby-dog_por_fernando_garcia\" width=\"637\" height=\"622\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/baby-dog_por_fernando_garcia.jpg 637w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/baby-dog_por_fernando_garcia-300x293.jpg 300w\" sizes=\"auto, (max-width: 637px) 100vw, 637px\" \/><\/a><\/div>\n<\/div>\n<\/div>\n<div class=\"content\">\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Varias investigaciones demuestran que las mascotas pueden ser una opci\u00f3n muy saludable para los ni\u00f1os. Y si se trata de elegir, los perros son los que suelen generar m\u00e1s beneficios.<\/p>\n<p>Algunas personas opinan que las mascotas transmiten enfermedades a los ni\u00f1os; otras en cambio piensan que es saludable para ellos tener la compa\u00f1\u00eda de tan fieles amigos; y otros se preguntan qu\u00e9 hacer con ellas cuando est\u00e1 por llegar un beb\u00e9.<\/p>\n<p>Si bien es cierto que los animales pueden transmitir algunas enfermedades (como la toxoplasmosis contagiada por los gatos), es igualmente cierto que son cada vez m\u00e1s los estudios que comprueban las ventajas de tener un animal en <label>casa<\/label>.<\/p>\n<p>Una investigaci\u00f3n llevada a cabo por cient\u00edficos del Hospital de la Universidad de Kuopio, Finlandia, encontr\u00f3 que los beb\u00e9s que viven con perros y gatos durante el primer a\u00f1o de su <label>vida<\/label> podr\u00edan ser menos susceptibles a las infecciones respiratorias, como es el caso del resfriado com\u00fan.<\/p>\n<p>En general, seg\u00fan el estudio publicado en la revista Pediatrics, los ni\u00f1os que hab\u00edan tenido cierta exposici\u00f3n a los perros o a los gatos en casa pasaron menos semanas con tos, infecciones de o\u00eddo y escurrimiento nasal, y necesitaron tomar menos antibi\u00f3ticos que los ni\u00f1os que no hab\u00edan compartido sus primeros a\u00f1os con una mascota.<\/p>\n<p>Recuerda que un animal es un ser viviente que demandar\u00e1 <label>cuidados<\/label> y cari\u00f1o, y que se convertir\u00e1 en un integrante m\u00e1s de la familia; por eso la decisi\u00f3n de tener una mascota debe ser compartida por todos los miembros . Entonces s\u00ed, si todos est\u00e1n de acuerdo\u2026 \u00a1a disfrutar la compa\u00f1\u00eda de esos peque\u00f1os traviesos!<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"http:\/\/bienestar.salud180.com\/salud-dia-dia\/si-tienes-mascotas-te-enfermas-menos\">Salud 180<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cNo dejes que tu beb\u00e9 est\u00e9 cerca de los perros, se pueden enfermar\u201d. De acuerdo con un estudio, esta frase est\u00e1 alejada de la realidad, ya que las mascotas cuidan tu salud.<\/p>\n","protected":false},"author":12,"featured_media":53415,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-53406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=53406"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53406\/revisions"}],"predecessor-version":[{"id":53416,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53406\/revisions\/53416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/53415"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=53406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=53406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=53406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}