{"id":53446,"date":"2016-02-25T10:31:23","date_gmt":"2016-02-25T14:31:23","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=53446"},"modified":"2016-02-25T10:31:23","modified_gmt":"2016-02-25T14:31:23","slug":"tony-parker-anota-25-spurs-mantienen-su-dominio-sobre-kings","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/tony-parker-anota-25-spurs-mantienen-su-dominio-sobre-kings\/","title":{"rendered":"Tony Parker anota 25, Spurs mantienen su dominio sobre Kings"},"content":{"rendered":"<div class=\"text\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/image_content_6264542_20160225062850.jpg\" rel=\"attachment wp-att-53447\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53447 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/image_content_6264542_20160225062850.jpg\" alt=\"image_content_6264542_20160225062850\" width=\"390\" height=\"208\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/image_content_6264542_20160225062850.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/02\/image_content_6264542_20160225062850-300x160.jpg 300w\" sizes=\"auto, (max-width: 390px) 100vw, 390px\" \/><\/a>SACRAMENTO, California.Tony Parker encest\u00f3 12 de sus 25 puntos en el \u00faltimo cuarto y los Spurs de San Antonio Spurs derrotaron a los Kings de Sacramento el mi\u00e9rcoles por 108-92 para anotarse su tercera victoria consecutiva.<!--more--><\/p>\n<p>Los Spurs tomaron ventaja definitivamente a solo 4 minutos del final del tercer cuarto y ampliaron la brecha en el \u00faltimo parcial para su noveno triunfo en 10 fechas. San Antonio mantiene su dominio sobre los Kings, a los que ha ganado en 35 de sus 39 \u00faltimos enfrentamientos.<\/p>\n<p>Kawhi Leonard aport\u00f3 18 tantos y Danny Green tuvo 16 para los Spurs. Kyle Anderson anot\u00f3 14, mientras que LaMarcus Aldridge tuvo problemas en ataque pero despleg\u00f3 una s\u00f3lida defensa sobre DeMarcus Cousins y termin\u00f3 con nueve rebotes y cinco bloqueos.<\/p>\n<p>Cousins logr\u00f3 21 de sus 22 puntos en la segunda mitad y aport\u00f3 10 rebotes para los Kings, que vieron como se frenaba una seguidilla de tres victorias.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"text\">\n<p><b>LeBron ayuda a victoria de Cleveland<\/b><\/p>\n<p>El alero LeBron James y el base Kyrie Irving aportaron 23 puntos cada uno en el triunfo de los Cavaliers de Cleveland por 114-103 sobre los Hornets de Charlotte.<\/p>\n<p>Los Cavaliers (41-15), l\u00edderes en la Divisi\u00f3n Central, sumaron su s\u00e9ptimo triunfo en los \u00faltimos 10 partidos y se mantienen con la mejor marca en la Conferencia Este.<\/p>\n<p>Los Hornets (29-27) sufrieron la tercera derrota consecutiva, pero siguen terceros en la Divisi\u00f3n Sureste y en el octavo lugar de la Conferencia Este, que les da derecho a estar en la fase final.<b><\/b><\/p>\n<p><b><\/b><b><\/b><b>Perdi\u00f3 Minnesota<\/b><\/p>\n<p>El escolta DeMar DeRozan logr\u00f3 31 puntos y el base Kyle Lowry agreg\u00f3 21 que ayudaron a los Raptors de Toronto a ganar 114-105 a los Timberwolves de Minnesota.<\/p>\n<p>Los Raptors (38-18) sumaron tres triunfos consecutivos y empataron marca de franquicia al conseguir su novena victoria seguida en su campo del Air Canada Centre.<\/p>\n<p>El alero canadiense Andrew Wiggins anot\u00f3 26 puntos y encabez\u00f3 el ataque de los Timberwolves (18-40), \u00faltimos en la Divisi\u00f3n Noroeste, que est\u00e1n ya eliminados de la fase final.<\/p>\n<\/div>\n<div class=\"text\">\n<p><b>Gran ofensiva de Kevin Durant<\/b><\/p>\n<p>El alero Kevin Durant y el base Russell Westbrook encestaron 24 puntos cada uno para los visitantes Thunder de Oklahoma City, que vencieron 103-116 a los Mavericks de Dallas, en duelo de equipos ganadores de la Conferencia Oeste.<\/p>\n<p>Los Thunder (41-16), con siete triunfos en los \u00faltimos 10 partidos, son l\u00edderes en la Divisi\u00f3n Noroeste.<\/p>\n<p>Los Mavericks (30-28), terceros en la Divisi\u00f3n Suroeste, llegaron a seis derrotas en los \u00faltimos 10 partidos disputados y ocupan el s\u00e9ptimo lugar de la Conferencia Oeste.<\/p>\n<p>El alero Matt Barnes logr\u00f3 25 puntos, su mejor marca de temporada, y los Grizzlies de Memphis vencieron por 128-119 a los Lakers de Los \u00c1ngeles, en el \u00faltimo partido del escolta Kobe Bryant en Memphis.<\/p>\n<p><b>Grizzlies en racha victoriosa<\/b><\/p>\n<p>Los Grizzlies (33-23), que marchan segundos en la Divisi\u00f3n Suroeste, sumaron su s\u00e9ptimo triunfo en los \u00faltimos 10 partidos disputados y siguen ganando a pesar de la baja por lo que resta de temporada del p\u00edvot espa\u00f1ol Marc Gasol.<\/p>\n<p>Los Lakers (11-48) sufrieron la s\u00e9ptima derrota seguida y tienen la peor marca de la Conferencia Oeste, mientras siguen con la gira de despedida de Bryant, que aport\u00f3 13 puntos.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SACRAMENTO, California.Tony Parker encest\u00f3 12 de sus 25 puntos en el \u00faltimo cuarto y los Spurs de San Antonio Spurs derrotaron a los Kings de Sacramento el mi\u00e9rcoles por 108-92 para anotarse su tercera victoria consecutiva.<\/p>\n","protected":false},"author":12,"featured_media":53447,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-53446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=53446"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53446\/revisions"}],"predecessor-version":[{"id":53449,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53446\/revisions\/53449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/53447"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=53446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=53446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=53446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}