{"id":53838,"date":"2016-03-11T08:00:52","date_gmt":"2016-03-11T12:00:52","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=53838"},"modified":"2016-03-11T08:00:52","modified_gmt":"2016-03-11T12:00:52","slug":"el-ultimo-juego-entre-kobe-y-lebron","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-ultimo-juego-entre-kobe-y-lebron\/","title":{"rendered":"El \u00faltimo juego entre Kobe y LeBron"},"content":{"rendered":"<p>LeBron James y Kobe Bryant se enfrentaron el jueves por \u00faltima vez en sus carreras en la NBA, en un duelo de titanes que se inclin\u00f3 a favor de la m\u00e1s joven estrella de los Cleveland Cavaliers, al vencer 120-106 a los locales Los Angeles Lakers.<!--more--><\/p>\n<p>La gira de despedida de Kobe Bryant tuvo su momento culminante en el Staples Center angelino con el choque entre los dos jugadores m\u00e1s conocidos de la actualidad.<\/p>\n<p>En poco m\u00e1s de un mes, el 13 de abril por la noche, Bryant colgar\u00e1 las zapatillas a los 37 a\u00f1os, despu\u00e9s de veinte temporadas con los Lakers, cinco t\u00edtulos de la NBA y un trofeo de Jugador M\u00e1s Valioso.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/fxz4RmSlln8?rel=0&amp;showinfo=0\" width=\"100%\" height=\"338\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>LeBron termin\u00f3 con 24 puntos y siete asistencias, y a la ofensiva fue respaldado por Kyrie Irvin con 26 cartones, Channing Frye con 21 y Tristan Thompson con 10 unidades y 14 rebotes.<\/p>\n<p>De su lado, los San Antonio Spurs archivaron su 31\u00aa victoria consecutiva como locales para seguir firmes en el segundo lugar de la Conferencia Oeste de la NBA, misma posici\u00f3n que mantuvieron los Toronto Raptors al vencer este jueves a los Phoenix Suns.<\/p>\n<p>El alero Kawhi Leonard anot\u00f3 29 puntos y LaMarcus Aldridge aport\u00f3 26 cartones y 10 rebotes, para que los San Antonio Spurs vencieran 109-101 a unos Chicago Bulls que parecen un hospital ambulante debido a la gran cantidad de lesionados.<\/p>\n<p>El franc\u00e9s Tony Parker a\u00f1adi\u00f3 20 tantos y 12 asistencias para los Spurs, que mantienen el mejor comienzo en su historia tras 65 partidos, con un r\u00e9cord de 55-10, tres juegos detr\u00e1s de los campeones Golden State (57-6).<\/p>\n<p>El base Derrick Rose y el espa\u00f1ol Pau Gasol coleccionaron 21 puntos cada uno por los Bulls, mientras E\u2019Twaun Moore agreg\u00f3 20 puntos, 12 de ellos con cuatro triples.<\/p>\n<p>Chicago no pudo contar con los lesionados Jimmy Butler, Joakim Noah y Cameron Bairstow.<\/p>\n<p>Tim Duncan cerr\u00f3 con siete puntos y tres rebotes y se convirti\u00f3 en el sexto jugador en la historia de la NBA en capturar 15.000 rebotes o m\u00e1s.<\/p>\n<p>Por los Spurs, el argentino Manu Gin\u00f3bili aport\u00f3 cuatro cartones, un rebote y dos asistencias.<\/p>\n<p>En Toronto, DeMar DeRozan encest\u00f3 30 puntos y los Raptors vencieron 104-96 a los Atlanta Hawks.<\/p>\n<p>Toronto tuvo un p\u00e9simo inicio al cometer nueve p\u00e9rdidas de balones, pero reagrup\u00f3 su defensa en el resto del encuentro para conseguir su segunda victoria seguida y la 14\u00aa en 15 partidos como locales.<\/p>\n<p>Kyle Lowry a\u00f1adi\u00f3 19 puntos y siete asistencias y el argentino Luis Scola colabor\u00f3 con 10 tantos y 12 rebotes en 21:57 minutos de acci\u00f3n.<\/p>\n<p>La derrota fren\u00f3 la racha de tres triunfos consecutivos de los Hawks, que tuvieron en el dominicano Al Horford a su mejor canastero con 20 puntos, cuatro rebotes y tres asistencias.<\/p>\n<p>En Denver, el novato congole\u00f1o Emmanuel Mudiay encest\u00f3 30 puntos, la mayor cantidad de su carrera, y gui\u00f3 a los Nuggets locales a un triunfo de 116-98 sobre los Phoenix Suns.<\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/Kobe-vs-Lebron-640x535.jpg\" rel=\"attachment wp-att-53839\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-53839\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/Kobe-vs-Lebron-640x535.jpg\" alt=\"Kobe-vs-Lebron-640x535\" width=\"640\" height=\"535\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/Kobe-vs-Lebron-640x535.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/Kobe-vs-Lebron-640x535-300x251.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>Devin Booker, el tambi\u00e9n novato de Phoenix, estableci\u00f3 un r\u00e9cord personal con 35 cartones, 25 de ellos en la segunda mitad, para firmar su 27\u00ba partido con cifras de dos d\u00edgitos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LeBron James y Kobe Bryant se enfrentaron el jueves por \u00faltima vez en sus carreras en la NBA, en un duelo de titanes que se inclin\u00f3 a favor de la m\u00e1s joven estrella de los Cleveland Cavaliers, al vencer 120-106 a los locales Los Angeles Lakers.<\/p>\n","protected":false},"author":12,"featured_media":53839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-53838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=53838"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53838\/revisions"}],"predecessor-version":[{"id":53840,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53838\/revisions\/53840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/53839"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=53838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=53838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=53838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}