{"id":53929,"date":"2016-03-15T08:26:41","date_gmt":"2016-03-15T12:26:41","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=53929"},"modified":"2016-03-15T08:26:41","modified_gmt":"2016-03-15T12:26:41","slug":"la-repudiable-muerte-de-aquino-febrillet","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-repudiable-muerte-de-aquino-febrillet\/","title":{"rendered":"La repudiable muerte de Aquino Febrillet"},"content":{"rendered":"<p>No existe raz\u00f3n v\u00e1lida o explicaci\u00f3n dial\u00e9ctica que justifique en su m\u00e1s m\u00ednima expresi\u00f3n la muerte de una persona de manera tan irresponsable como la del Ex Rector de la UASD Mateo Aquino Febrillet. Me dirig\u00eda camino a la universidad para asistir a mis estudios de maestr\u00eda cu\u00e1ndo por un grupo de \u201cchat\u201d informan de tan lamentable noticia. Qued\u00e9 paralizado, completamente estupefacto de lo que acababa de leer, solo atine a llamar a mi madre y comentarle el suceso que r\u00e1pidamente me exclamo: \u00a1 Mi hijo y qu\u00e9 es lo que est\u00e1 pasando en este pa\u00eds !<!--more--><\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/Aquino-F-.jpg\" rel=\"attachment wp-att-53930\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-53930\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/Aquino-F-.jpg\" alt=\"Aquino-F-\" width=\"589\" height=\"449\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/Aquino-F-.jpg 589w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/Aquino-F--300x229.jpg 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/a><\/p>\n<p>En mi mente pasaron tantos pensamientos de c\u00f3mo andamos como sociedad que me sent\u00ed preocupado, turbado y record\u00e9 que apenas han transcurrido tres meses de la muerte de Juan de los Santos y otro hecho violento de alta transcendencia sacude la colectividad dominicana. Luego un gran asombro me invadi\u00f3 al momento de enterarme que el reconocido dirigente Blas Peralta (Presidente de FENATRADO) est\u00e1 involucrado en el crimen\u2026 entonces Yo me pregunto: \u00bfC\u00f3mo podr\u00eda llam\u00e1rsele a esto?, la \u00fanica forma de definir este horrendo delito es categorizarlo como la \u201cDisgregaci\u00f3n Nauseabunda Nacional\u201d que atraviesa esta isla del caribe.<\/p>\n<p>No he podido acertar desde el pasado viernes con la sem\u00e1ntica reglamentaria para describir toda mi aflicci\u00f3n, coraje y descontento, tendr\u00eda que utilizar de tres a cuatro idiomas para manifestar en su generalidad lo que se ha convertido este \u201cbendito\u201d pa\u00eds. Estamos en camino a la deriva, hacia un precipicio anti-moral, anti-\u00e9tico, inhumano, poco sociable, lleno de avaricias y en contra de las costumbres del cristianismo que ponen en una situaci\u00f3n de inseguridad a nuestros hijos y su futura descendencia. Estamos en frente de un demonio de siete cabezas totalmente adiestrado, preparado para devorarnos y defecar todos nuestros valores, ese demonio llamado \u201cCorrupci\u00f3n\u201d no se detendr\u00e1 hasta encontrar un muro social construido de personas valientes, perseverantes y honestas que defiendan al dominicano.<\/p>\n<p><strong>\u00bf100,000 firmas para qu\u00e9?<\/strong><\/p>\n<p>La Casa Blanca brind\u00f3 el apoyo total al Embajador James Brewster, un diplom\u00e1tico que por su preferencia sexual est\u00e1 siendo objeto de infinitas cr\u00edticas. Que Yo no est\u00e9 de acuerdo con su exhibicionismo gay, es totalmente cierto, pero tampoco comparto una propaganda de recolectar 100,000 firmas para solicitar al congreso americano que lo retire como representante de Estados Unidos, cien mil firmas que deber\u00edan de estar siendo reunidas para exigir al Gobierno Dominicano un plan efectivo en contra de la delincuencia, para que sanee la Justicia de nuestro pa\u00eds. Ese \u201cinter\u00e9s\u201d para que \u201cfirmen\u201d que nunca se present\u00f3 como forma para protestar por el famoso aquel \u201cNo Ha Lugar\u201d, firmas que nunca se han reunido para sacar los verdaderos corruptos que todos los conocen<\/p>\n<p>. Vivimos en una doble moral que nos consume, que nos ridiculiza y nos coloca como \u201cSubnormales e Indios Retrasados\u201d delante de toda la comunidad internacional que hace mucho empez\u00f3 a empoderarse\u2026 \u00a1Sino preg\u00fantenle a los Brasile\u00f1os!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No existe raz\u00f3n v\u00e1lida o explicaci\u00f3n dial\u00e9ctica que justifique en su m\u00e1s m\u00ednima expresi\u00f3n la muerte de una persona de manera tan irresponsable como la del Ex Rector de la UASD Mateo Aquino Febrillet. Me dirig\u00eda camino a la universidad para asistir a mis estudios de maestr\u00eda cu\u00e1ndo por un grupo de \u201cchat\u201d informan de tan lamentable noticia. Qued\u00e9 paralizado, completamente estupefacto de lo que acababa de leer, solo atine a llamar a mi madre y comentarle el suceso que r\u00e1pidamente me exclamo: \u00a1 Mi hijo y qu\u00e9 es lo que est\u00e1 pasando en este pa\u00eds !<\/p>\n","protected":false},"author":12,"featured_media":53930,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-53929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=53929"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53929\/revisions"}],"predecessor-version":[{"id":53931,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53929\/revisions\/53931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/53930"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=53929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=53929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=53929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}