{"id":53942,"date":"2016-03-15T12:28:47","date_gmt":"2016-03-15T16:28:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=53942"},"modified":"2016-03-15T12:28:47","modified_gmt":"2016-03-15T16:28:47","slug":"dia-mundial-de-los-derechos-del-consumidor","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dia-mundial-de-los-derechos-del-consumidor\/","title":{"rendered":"D\u00eda Mundial de los Derechos del Consumidor"},"content":{"rendered":"<div><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/PROCONSUMIDOR-730x374.jpg\" rel=\"attachment wp-att-53943\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53943 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/PROCONSUMIDOR-730x374.jpg\" alt=\"PROCONSUMIDOR-730x374\" width=\"455\" height=\"233\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/PROCONSUMIDOR-730x374.jpg 730w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/PROCONSUMIDOR-730x374-300x154.jpg 300w\" sizes=\"auto, (max-width: 455px) 100vw, 455px\" \/><\/a>Todos los consumidores o usuarios del pa\u00eds deben empoderarse y \u00a0hacer valer sus derechos, exhort\u00f3 hoy Pro Consumidor al conmemorarse este 15 de marzo el D\u00eda Mundial de los Derechos del Consumidor.<\/div>\n<p><!--more--><\/p>\n<div><\/div>\n<div>La entidad \u00a0que dirige la doctora Anina Del Castillo, dijo que en \u00a0la Ley No. 358-05 de Protecci\u00f3n al Consumidor, se establecen como derecho a los consumidores o usuarios la protecci\u00f3n a la vida, la salud, seguridad f\u00edsica y la educaci\u00f3n en el consumo o uso de bienes y servicios.<\/div>\n<div><\/div>\n<div>A recibir de los proveedores una informaci\u00f3n veraz, clara, oportuna, suficiente, verificable y escrita en idioma espa\u00f1ol de los productos que se oferten en el mercado.<\/div>\n<div><\/div>\n<div>Los consumidores o usuarios tienen derecho a \u00a0la protecci\u00f3n de los intereses econ\u00f3micos mediante un trato equitativo, no discriminatorio o abusivo por parte de los proveedores y a la reparaci\u00f3n oportuna con las condiciones t\u00e9cnicas adecuadas.<\/div>\n<div><\/div>\n<div>Tambi\u00e9n a asociarse y constituir agrupaciones de consumidores como \u00a0acceder a los \u00f3rganos jurisdiccionales correspondientes para la protecci\u00f3n de sus derechos y leg\u00edtimos intereses, mediante un procedimiento breve y gratuito.<\/div>\n<div><\/div>\n<div>A la vez de acceder a proveedores y a una variedad de productos o servicios a libre elecci\u00f3n \u00a0y vivir y trabajar en un medio ambiente digno y sano que no afecte el bienestar ni le sea peligroso.<\/div>\n<div><\/div>\n<div><strong>Campa\u00f1a<\/strong>\n<\/div>\n<div>A prop\u00f3sito de que los consumidores y usuarios comiencen a \u00a0empoderarse de sus derechos, la entidad \u00a0lanz\u00f3 la campa\u00f1a \u201cEn Semana Santa: \u00a1ll\u00e9vate tus derechos!\u201d, \u00a0que a trav\u00e9s de una gu\u00eda ofrece orientaciones preventivas para en este asueto en cuanto a la protecci\u00f3n de la salud, seguridad y los intereses econ\u00f3micos de los consumidores y usuarios.<\/div>\n<div>La campa\u00f1a tiene como finalidad orientar a la ciudadan\u00eda \u00a0sobre los \u00a0derechos que le asisten en los servicios de hospedaje, transporte, alimentaci\u00f3n, \u00a0a \u00a0su vez \u00a0de las obligaciones que tienen los proveedores de cumplir sus deberes ante la promoci\u00f3n y \u00a0venta de un producto o servicio.<\/div>\n<div><\/div>\n<div><strong>Antibi\u00f3ticos fuera del men\u00fa<\/strong><\/div>\n<div><\/div>\n<div>Pro Consumidor, como organizaci\u00f3n miembro de Consumers International se une a la campa\u00f1a \u00a0\u201cAntibi\u00f3ticos fuera del men\u00fa\u201d.<\/div>\n<div><\/div>\n<div>La entidad ha asumido este compromiso, en busca de que los establecimientos de comida r\u00e1pida paren la venta de carne de animales que hayan sido habitualmente tratados con antibi\u00f3ticos destinados a los seres humanos.<\/div>\n<div><\/div>\n<div>Consumers International informa que alrededor de la mitad de los antibi\u00f3ticos producidos en el mundo se utilizan en la agricultura, y gran parte de ellos se utilizan para promover el crecimiento m\u00e1s r\u00e1pido de los animales y prevenir, en lugar de tratar una enfermedad.<\/div>\n<div><\/div>\n<div>Por lo que llama a los consumidores a jugar un papel clave en persuadir a las empresas de alimentos para que hagan los cambios que se necesitan, en busca de poner fin a esta amenaza para la salud p\u00fablica mundial y proteger nuestras medicinas para el futuro.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Todos los consumidores o usuarios del pa\u00eds deben empoderarse y \u00a0hacer valer sus derechos, exhort\u00f3 hoy Pro Consumidor al conmemorarse este 15 de marzo el D\u00eda Mundial de los Derechos del Consumidor.<\/p>\n","protected":false},"author":12,"featured_media":53943,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-53942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=53942"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53942\/revisions"}],"predecessor-version":[{"id":53944,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53942\/revisions\/53944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/53943"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=53942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=53942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=53942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}