{"id":53980,"date":"2016-03-16T09:20:49","date_gmt":"2016-03-16T13:20:49","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=53980"},"modified":"2016-03-16T09:20:49","modified_gmt":"2016-03-16T13:20:49","slug":"danilo-medina-dispone-medidas-para-los-ultimos-dos-meses-de-campana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/danilo-medina-dispone-medidas-para-los-ultimos-dos-meses-de-campana\/","title":{"rendered":"Danilo Medina dispone medidas para los \u00faltimos dos meses de campa\u00f1a"},"content":{"rendered":"<div>\n<div><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/danilo-medina1.jpg\" rel=\"attachment wp-att-44725\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-44725 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/danilo-medina1.jpg\" alt=\"danilo medina\" width=\"304\" height=\"202\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/danilo-medina1.jpg 620w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/danilo-medina1-300x199.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/06\/danilo-medina1-105x70.jpg 105w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/><\/a>SANTO DOMINGO.\u00a0A dos meses de las elecciones presidenciales, congresuales y municipales, el presidente Danilo Medina dispuso que los funcionarios p\u00fablicos designados por el Poder Ejecutivo, cuyos cargos no sean por elecci\u00f3n, que aspiren a alguna posici\u00f3n en las pr\u00f3ximas elecciones del 15 de mayo, deber\u00e1n tomar licencia hasta pasado el proceso electoral.<!--more--><\/p>\n<p>La licencia de los funcionarios hab\u00eda sido planteada por el candidato presidencial del Partido Revolucionario Moderno (PRM), Luis Abinader, organizaci\u00f3n que consider\u00f3 tard\u00eda e insuficiente la medida, ya que no incluye al propio mandatario, quien es el candidato presidencial del Partido de la Liberaci\u00f3n Dominicana (PLD).<\/p>\n<\/div>\n<div>La medida fue ordenada a trav\u00e9s del ministro Administrativo de la Presidencia, Jos\u00e9 Ram\u00f3n Peralta, y dada a conocer por el vocero de la Presidencia de la Rep\u00fablica, Roberto Rodr\u00edguez Marchena.<\/p>\n<\/div>\n<div>La disposici\u00f3n tiene efecto inmediato y hasta el 16 de mayo, contempla, adem\u00e1s, la congelaci\u00f3n de las n\u00f3minas correspondientes a la contrataci\u00f3n de personal temporal en la administraci\u00f3n p\u00fablica central y descentralizada.<\/p>\n<\/div>\n<div>Sin embargo, excluye las sustituciones de cargos que ya est\u00e9n creados, y que cuenten con su asignaci\u00f3n presupuestaria.<\/p>\n<\/div>\n<div>El documento en el que est\u00e1 contenida la medida, en cumplimiento de la ley 275-97, explica que tiene \u201cel objetivo de garantizar la administraci\u00f3n responsable de las instituciones del Estado, la igualdad de oportunidades y la transparencia en el desarrollo de los pr\u00f3ximos comicios\u201d.<\/p>\n<\/div>\n<\/div>\n<p><strong>Las cr\u00edticas<\/strong><\/p>\n<div>\n<div>La medida fue respaldada por el vicepresidente de la Fundaci\u00f3n Institucionalidad y Justicia (Finjus), Servio Tulio Casta\u00f1os, quien la estim\u00f3 positiva, ya que la campa\u00f1a no tiene regulaciones legales suficientes.<\/p>\n<\/div>\n<div>\u201cYo creo que ese es un paso positivo, sobre todo ya que a\u00fan no contamos con una Ley de Partidos pol\u00edticos y que a\u00fan no hemos ni siquiera reformado todo lo que tiene que ver con el r\u00e9gimen electoral conforme a lo que establece la Constituci\u00f3n del 2010\u201d, expres\u00f3.<\/p>\n<\/div>\n<div>Casta\u00f1os dijo que se han visto a funcionarios p\u00fablicos participando en actividades proselitistas en horario laboral, lo que est\u00e1 prohibido por la ley de funci\u00f3n p\u00fablica.<\/p>\n<\/div>\n<div>Pero la medida fue criticada por el presidente en funciones del PRM, Orlando Jorge Mera, quien consider\u00f3 inaceptable que Medina no se incluya, estando en campa\u00f1a cinco d\u00edas en la semana.<\/p>\n<\/div>\n<div>El polit\u00f3logo Rafael Toribio manifest\u00f3 que esa medida debi\u00f3 se ejecutada en el inicio de la campa\u00f1a electoral. \u201cSimplemente se acoge a lo que est\u00e1 establecido en la Ley Electoral\u201d, indic\u00f3.<\/p>\n<\/div>\n<div>El candidato a senador del Distrito Nacional por el PRM, diputado Alberto Atallah, consider\u00f3 \u201cuna burla, un chiste de mal gusto, cuando todo el gobierno y los recursos p\u00fablicos est\u00e1n al servicio de sus campa\u00f1as reeleccionistas.<\/p>\n<\/div>\n<div>Asegur\u00f3 que \u201c el efecto boomerang de estos excesos se ver\u00e1 reflejado en las elecciones del pr\u00f3ximo 15 de mayo \u201c<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.\u00a0A dos meses de las elecciones presidenciales, congresuales y municipales, el presidente Danilo Medina dispuso que los funcionarios p\u00fablicos designados por el Poder Ejecutivo, cuyos cargos no sean por elecci\u00f3n, que aspiren a alguna posici\u00f3n en las pr\u00f3ximas elecciones del 15 de mayo, deber\u00e1n tomar licencia hasta pasado el proceso electoral.<\/p>\n","protected":false},"author":12,"featured_media":44725,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-53980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=53980"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53980\/revisions"}],"predecessor-version":[{"id":53981,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/53980\/revisions\/53981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/44725"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=53980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=53980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=53980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}