{"id":54046,"date":"2016-03-18T12:00:12","date_gmt":"2016-03-18T16:00:12","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=54046"},"modified":"2016-03-18T12:00:12","modified_gmt":"2016-03-18T16:00:12","slug":"violan-disposicion-y-trasladan-a-blas-peralta-a-otra-carcel","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/violan-disposicion-y-trasladan-a-blas-peralta-a-otra-carcel\/","title":{"rendered":"Violan disposici\u00f3n y trasladan a Blas Peralta a otra c\u00e1rcel"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/u_Zg_FB_g_H8p_Kiw_xi_EAPPrsn_Nc_KBm_Rpr_k7_O7_NYs_GVe_Hrv96t.jpg\" rel=\"attachment wp-att-54047\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54047 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/u_Zg_FB_g_H8p_Kiw_xi_EAPPrsn_Nc_KBm_Rpr_k7_O7_NYs_GVe_Hrv96t.jpg\" alt=\"u_Zg_FB_g_H8p_Kiw_xi_EAPPrsn_Nc_KBm_Rpr_k7_O7_NYs_GVe_Hrv96t\" width=\"320\" height=\"212\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/u_Zg_FB_g_H8p_Kiw_xi_EAPPrsn_Nc_KBm_Rpr_k7_O7_NYs_GVe_Hrv96t.jpg 320w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/u_Zg_FB_g_H8p_Kiw_xi_EAPPrsn_Nc_KBm_Rpr_k7_O7_NYs_GVe_Hrv96t-300x199.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a>En horas de la ma\u00f1ana de este jueves fue trasladado a la c\u00e1rcel de Anamuya en Hig\u00fcey el imputado Blas Peralta,\u00a0donde deber\u00e1 cumplir un a\u00f1o de prisi\u00f3n preventiva, en atenci\u00f3n a la orden de coerci\u00f3n dictada por el juez Alejandro Vargas por su presunta participaci\u00f3n en el asesinato del exrector de la Universidad Aut\u00f3noma de Santo Domingo (UASD), Mateo Aquino Febrillet.<!--more--><\/p>\n<p>La informaci\u00f3n fue confirmada a elCaribe por una fuente vinculada al Nuevo Modelo Penitenciario, quien asegur\u00f3 que Peralta fue trasladado solo al mencionado recinto, mientras que\u00a0Franklin Vanega, Geraldo F\u00e9lix Batista y Rafael Herrera Pe\u00f1a, s\u00ed fueron enviados a La Romana.<\/p>\n<p>No obstante, con este traslado se viol\u00f3 la disposici\u00f3n del juez Vargas quien orden\u00f3, a trav\u00e9s de la sentencia, que Blas Peralta cumpliera la medida, junto a los otros tres imputados\u00a0en la c\u00e1rcel de La Romana, tal y como hab\u00eda sido solicitado por el Ministerio P\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En horas de la ma\u00f1ana de este jueves fue trasladado a la c\u00e1rcel de Anamuya en Hig\u00fcey el imputado Blas Peralta,\u00a0donde deber\u00e1 cumplir un a\u00f1o de prisi\u00f3n preventiva, en atenci\u00f3n a la orden de coerci\u00f3n dictada por el juez Alejandro Vargas por su presunta participaci\u00f3n en el asesinato del exrector de la Universidad Aut\u00f3noma de Santo Domingo (UASD), Mateo Aquino Febrillet.<\/p>\n","protected":false},"author":12,"featured_media":54047,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-54046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=54046"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54046\/revisions"}],"predecessor-version":[{"id":54048,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54046\/revisions\/54048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/54047"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=54046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=54046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=54046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}