{"id":54049,"date":"2016-03-18T12:07:54","date_gmt":"2016-03-18T16:07:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=54049"},"modified":"2016-03-18T12:07:54","modified_gmt":"2016-03-18T16:07:54","slug":"cancelan-maestra-y-policia-por-pelea-de-ninos-en-escuela-de-boca-chica","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cancelan-maestra-y-policia-por-pelea-de-ninos-en-escuela-de-boca-chica\/","title":{"rendered":"Cancelan maestra y polic\u00eda por pelea de ni\u00f1os en escuela de Boca Chica"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/unnamed_1.jpg\" rel=\"attachment wp-att-54050\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-54050\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/unnamed_1.jpg\" alt=\"unnamed_1\" width=\"320\" height=\"210\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/unnamed_1.jpg 320w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/unnamed_1-300x197.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a>El Ministerio de Educaci\u00f3n inform\u00f3 que cancel\u00f3 este jueves el nombramiento de la profesora Ana Elia Mateo Abad, de la Escuela Marta Rosa Castillo, de Boca Chica, porque se determin\u00f3 que ella y una sargento de la Polic\u00eda Escolar incitaron una pelea en plena aula entre dos ni\u00f1os, la cual fue grabada en video y dada a conocer a trav\u00e9s de las redes sociales.<!--more--><\/p>\n<div class=\"fluid-width-video-wrapper\"><iframe loading=\"lazy\" id=\"fitvid661768\" src=\"https:\/\/www.youtube.com\/embed\/Wh55h_MNsNQ?feature=oembed\" width=\"630\" height=\"350\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<p class=\"x_MsoNormal\">En cuanto al caso de La Romana, donde se report\u00f3 el fallecimiento de la estudiante Mary Elizabeth Severino Morla, estudiante de la escuela B\u00e1sica Nery Cueto, el Ministerio de Educaci\u00f3n dispuso la intervenci\u00f3n del centro por la Direcci\u00f3n Distrital de Educaci\u00f3n y la suspensi\u00f3n de la directora del centro de estudios. Educaci\u00f3n inform\u00f3 que est\u00e1 a la espera de los resultados de la autopsia que se practica al cad\u00e1ver de la infante para fijar una posici\u00f3n al respecto.<\/p>\n<p class=\"x_MsoNormal\">La sargento Olquidea Medina F\u00e9liz, que ostentaba el mismo rango en la Polic\u00eda Nacional y que tambi\u00e9n aparece en el video, fue dada de baja de las filas de la instituci\u00f3n por el mismo motivo. Como miembro de la Polic\u00eda Escolar, Medina F\u00e9liz hab\u00eda sido cancelada de la entidad al d\u00eda siguiente de haberse dado a conocer la pelea entre los dos alumnos sin que las dos mujeres intervinieran.<\/p>\n<p class=\"x_MsoNormal\">El telefonema de cancelaci\u00f3n de Medina F\u00e9liz, dirigido al Subdirector Adjunto de Recursos Humanos de la Direcci\u00f3n Central de Protecci\u00f3n escolar de la Polic\u00eda Nacional, est\u00e1 firmado por el ingeniero Alejandro Dipr\u00e9 Sierra, General de Brigada subjefe de la Polic\u00eda Nacional.<\/p>\n<p class=\"x_MsoNormal\">El caso estaba bajo investigaci\u00f3n por una comisi\u00f3n del Ministerio de Educaci\u00f3n, de la que formaron parte funcionarios de los departamentos de Recursos Humanos, Participaci\u00f3n Comunitaria y de Orientaci\u00f3n y Sicolog\u00eda de la cartera educativa.<\/p>\n<p class=\"x_MsoNormal\">Educaci\u00f3n dispuso la intervenci\u00f3n de la escuela donde ocurri\u00f3 la pelea por parte del Distrito Escolar 10-05 y la suspensi\u00f3n y puesta a disposici\u00f3n de la Direcci\u00f3n Regional 10 del director del centro, H\u00e9ctor D\u00b4Oleo Alc\u00e1ntara.<\/p>\n<p class=\"x_MsoNormal\">En cuanto a la separaci\u00f3n de la profesora\u00a0 Mateo Abad, su cancelaci\u00f3n le fue comunicada mediante Acci\u00f3n de Personal firmada por la Directora General de Recursos Humanos, Vivian B\u00e1ez B\u00e1ez, dirigida a Sobeyda S\u00e1nchez P\u00e9rez, Directora de la Regional 10 de Educaci\u00f3n y a Mar\u00eda Elisa Su\u00e1rez Alcal\u00e1, Directora del Distrito Educativo 10-05, se indica que la medida fue tomada por la comisi\u00f3n de una falta de tercer grado, contenida en el art\u00edculo 34, literal \u201ca,f, h y o\u201d; al art\u00edculo 35, Literal h-i del Estatuto Docente, y art\u00edculo 84, numerales 2,4 y 20 de la Ley n\u00famero 41-08 de Funci\u00f3n P\u00fablica.<\/p>\n<p class=\"x_MsoNormal\">Originalmente, la docente destituida se desempe\u00f1aba como profesora de Inicial de la Escuela Mar\u00eda Caro, reubicada en la Escuela Primaria Marta Rosa Castillo de la Cruz. Los art\u00edculos violados obligan a respetar, cumplir y hacer cumplir la Ley General de Educaci\u00f3n 6697, los Reglamentos y las disposiciones vigentes y observar en su actuaci\u00f3n docente un comportamiento digno y honesto.<\/p>\n<p class=\"x_MsoNormal\">Mandan tambi\u00e9n a respetar la personalidad e integridad del ni\u00f1o, la ni\u00f1a y adolescentes y dirigir con amor el indeclinable sentido de la responsabilidad, su formaci\u00f3n intelectual, moral y f\u00edsica.<\/p>\n<p class=\"x_MsoNormal\">A continuaci\u00f3n, copia del oficio con la Acci\u00f3n de Personal donde se comunica la medida en contra de la profesora Mateo Abad:<\/p>\n<p class=\"x_MsoNormal\">\u201cCort\u00e9smente, nos cumple informarle para su conocimiento y fines de lugar que, usted ha sido destituida de sus funciones como Maestra de Inicial, Escuela Primaria\u00a0 Maria Caro, \u00a0(Reubicada en\u00a0 la Escuela\u00a0 Primaria Marta Rosa Castillo de la Cruz, J.E.),\u00a0 con efectividad a partir de la fecha,\u00a0 por violaci\u00f3n\u00a0 \u00a0al \u00a0Art\u00edculo 34, literal \u201ca, f, h y o\u201d;\u00a0 Art. 35, Literal h-i del \u00a0Estatuto Docente y \u00a0Art. 84, numerales \u201c2, 4 y 20\u201d de la Ley No. 41-08 de funci\u00f3n P\u00fablica. Cito: Art. 34, literal \u201ca, f, h y o\u201d y Art. 35, Literal h-i del Estatuto Docente, respectivamente: \u201c<span lang=\"ES\">Sin perjuicio de los dem\u00e1s deberes que establezca la reglamentaci\u00f3n y los consensuados entre las partes en virtud del ejercicio de las funciones encomendadas, el docente tendr\u00e1 los siguientes deberes<\/span>: \u00f1)- <span lang=\"ES\">\u201cRespetar, cumplir y hacer cumplir la Ley General de Educaci\u00f3n 6697, los Reglamentos y las disposiciones generales vigentes\u201d; \u00a0f)-\u201cObservar en su actuaci\u00f3n docente un comportamiento Digno y honesto\u201d; \u00a0h)-Ejercer debidamente la autoridad que le haya sido conferida en funci\u00f3n de su cargo y categor\u00eda\u201d ; \u00a0o)-\u201cConocer \u00a0y respetar la personalidad e integridad del ni\u00f1o, la ni\u00f1a y adolescentes y dirigir con amor el indeclinable sentido de la responsabilidad, su formaci\u00f3n intelectual, moral y f\u00edsica\u201d; Art. 35, Literal h-i: \u201cLos docentes estar\u00e1n sujetos a los siguientes compromisos\u201d: h)-\u201cVelar por la seguridad de los alumnos\u201d; \u00a0i)-\u201cAbstenerse de ejercer maltratos f\u00edsicos, morales y acoso sexual a sus estudiantes, compa\u00f1eros de trabajo y personal bajo su responsabilidad, si fuese el caso\u201d.\u00a0 <\/span>Art 84, numeral 4 y 20 , Ley No. 41-08: \u201cConstituyen faltas de tercer grado cuya comisi\u00f3n dar\u00e1 lugar a la destituci\u00f3n del cargo, las acciones indicadas a continuaci\u00f3n cometidas por cualquier servidor de la administraci\u00f3n p\u00fablica; 4)-\u201cIncurrir en la falta de probidad, v\u00edas de hecho, injuria, difamaci\u00f3n o conducta inmoral en el trabajo, o realizar alg\u00fan acto lesivo al buen nombre del Estado o algunos de sus \u00f3rganos o entidades; y 20)-Cometer cualesquiera otras faltas similares a las anteriores por su naturaleza o gravedad, a juicio de la autoridad\u00a0sancionadora\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Educaci\u00f3n inform\u00f3 que cancel\u00f3 este jueves el nombramiento de la profesora Ana Elia Mateo Abad, de la Escuela Marta Rosa Castillo, de Boca Chica, porque se determin\u00f3 que ella y una sargento de la Polic\u00eda Escolar incitaron una pelea en plena aula entre dos ni\u00f1os, la cual fue grabada en video y dada a conocer a trav\u00e9s de las redes sociales.<\/p>\n","protected":false},"author":12,"featured_media":54050,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-54049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=54049"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54049\/revisions"}],"predecessor-version":[{"id":54051,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54049\/revisions\/54051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/54050"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=54049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=54049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=54049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}