{"id":54110,"date":"2016-03-19T16:26:06","date_gmt":"2016-03-19T20:26:06","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=54110"},"modified":"2016-03-19T16:26:06","modified_gmt":"2016-03-19T20:26:06","slug":"cuanto-vales-interesante-reflexion-de-los-sabios","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cuanto-vales-interesante-reflexion-de-los-sabios\/","title":{"rendered":"\u00bfCu\u00e1nto vales? Interesante reflexi\u00f3n de los sabios"},"content":{"rendered":"<p>Ya lo dec\u00eda Arist\u00f3teles: \u201cSomos lo que hacemos d\u00eda a d\u00eda; de modo que la excelencia no es un acto, es un h\u00e1bito\u201d.<!--more--><\/p>\n<p>Pero, \u00bfc\u00f3mo adquirir el h\u00e1bito de la excelencia si en ocasiones no confiamos en nosotros e incluso hemos dejado de tener la seguridad de que estamos haciendo bien cada uno de los actos que realizamos siempre.<\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/PARABOLA4.jpg\" rel=\"attachment wp-att-54111\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-54111\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/PARABOLA4.jpg\" alt=\"PARABOLA4\" width=\"837\" height=\"557\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/PARABOLA4.jpg 975w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/PARABOLA4-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/PARABOLA4-768x511.jpg 768w\" sizes=\"auto, (max-width: 837px) 100vw, 837px\" \/><\/a><\/p>\n<p>El escritor y terapeuta argentino, Jorge Bucay, escribi\u00f3 una interesante reflexi\u00f3n en su cuento <em>El verdadero valor del anillo<\/em>, sobre la falta de confianza y la autoestima, cuando no sabemos cu\u00e1nto valemos como personas y nos interesamos por cosas mundanas o que poco aportan a nuestro crecimiento. Este cuento te har\u00e1 entender cu\u00e1nto vales, una interesante reflexi\u00f3n de sabidur\u00eda:<\/p>\n<blockquote><p>\u201cUn joven concurri\u00f3 a un sabio en busca de ayuda.<\/p>\n<p>\u2013 Vengo, maestro, porque me siento tan poca cosa que no tengo fuerzas para hacer nada. Me dicen que no sirvo, que no hago nada bien, que soy torpe y bastante tonto. \u00bfC\u00f3mo puedo mejorar maestro? \u00bfQu\u00e9 puedo hacer para que me valoren m\u00e1s?<\/p>\n<p>El maestro, sin mirarlo, le dijo:<\/p>\n<p>\u2013 \u00a1Cu\u00e1nto lo siento muchacho, no puedo ayudarte, debo resolver primero mis propios problemas. Quiz\u00e1 despu\u00e9s\u2026 Si quisieras ayudarme t\u00fa a m\u00ed, yo podr\u00eda resolver este tema con m\u00e1s rapidez y despu\u00e9s tal vez te pueda ayudar.<\/p>\n<p>\u2013 Encantado, maestro -titube\u00f3 el joven pero sinti\u00f3 que otra vez era desvalorizado y sus necesidades postergadas.<\/p><\/blockquote>\n<p><a class=\"full-img\" href=\"http:\/\/www.recreoviral.com\/wp-content\/uploads\/2016\/03\/PARABOLA.jpg\" rel=\"attachment wp-att-97558\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-97558\" src=\"http:\/\/www.recreoviral.com\/wp-content\/uploads\/2016\/03\/PARABOLA-768x576.jpg\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" alt=\"ESCENAS DE LA PELICULA APRENDIZ DE BRUJO\" width=\"730\" height=\"548\" \/><\/a><\/p>\n<blockquote><p>\u2013 Bien, -asinti\u00f3 el maestro- Se quit\u00f3 un anillo que llevaba en el dedo peque\u00f1o de la mano izquierda y d\u00e1ndoselo al muchacho agreg\u00f3: Toma el caballo que est\u00e1 all\u00ed afuera y cabalga hasta el mercado. Debo vender este anillo para pagar una deuda. Es necesario que obtengas por \u00e9l la mayor suma posible, pero no aceptes menos de una moneda de oro. Vete y regresa con esa moneda lo m\u00e1s r\u00e1pido que puedas.<\/p>\n<p>El joven tom\u00f3 el anillo y parti\u00f3. Apenas lleg\u00f3, empez\u00f3 a ofrecer el anillo a los mercaderes. Estos lo miraban con alg\u00fan inter\u00e9s hasta que el joven dec\u00eda lo que pretend\u00eda por el anillo. Cuando el joven mencionaba la moneda de oro, algunos re\u00edan, otros le daban vuelta la cara y s\u00f3lo un viejito fue tan amable como para tomarse la molestia de explicarle que una moneda de oro era muy valiosa para entregarla a cambio de un anillo.<\/p>\n<p>En af\u00e1n de ayudar, alguien le ofreci\u00f3 una moneda de plata y un cacharro de cobre, pero el joven ten\u00eda instrucciones de no aceptar menos de una moneda de oro, as\u00ed que rechaz\u00f3 la oferta.<\/p>\n<p>Despu\u00e9s de ofrecer su joya a toda persona que se cruzaba en el mercado -m\u00e1s de cien personas- y abatido por su fracaso, mont\u00f3 su caballo y regres\u00f3.<\/p>\n<p>\u00a1Cu\u00e1nto hubiese deseado el joven tener \u00e9l mismo esa moneda de oro! Podr\u00eda hab\u00e9rsela entregado al maestro para liberarlo de su preocupaci\u00f3n y recibir entonces su consejo y su ayuda.<\/p>\n<p>\u2013 Maestro -dijo- lo siento, no es posible conseguir lo que me pediste. Quiz\u00e1s pudiera conseguir 2 \u00f3 3 monedas de plata, pero no creo que yo pueda enga\u00f1ar a nadie respecto del verdadero valor del anillo.<\/p><\/blockquote>\n<p><a class=\"full-img\" href=\"http:\/\/www.recreoviral.com\/wp-content\/uploads\/2016\/03\/PARABOLA2.jpg\" rel=\"attachment wp-att-97559\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-97559\" src=\"http:\/\/www.recreoviral.com\/wp-content\/uploads\/2016\/03\/PARABOLA2-768x322.jpg\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" alt=\"PARABOLA DE JORGE BUCAY\" width=\"730\" height=\"306\" \/><\/a><\/p>\n<blockquote><p>\u2013 \u00a1Qu\u00e9 importante lo que dijiste, joven amigo! -contest\u00f3 sonriente el maestro-. Debemos saber primero el verdadero valor del anillo. Vuelve a montar y vete al joyero. \u00bfQui\u00e9n mejor que \u00e9l para saberlo?. Dile que quisieras vender el anillo y preg\u00fantale cu\u00e1nto da por \u00e9l. Pero no importa lo que ofrezca, no se lo vendas. Vuelve aqu\u00ed con mi anillo.<\/p>\n<p>El joven volvi\u00f3 a cabalgar. El joyero examin\u00f3 el anillo a la luz del candil, lo mir\u00f3 con su lupa, lo pes\u00f3 y luego le dijo:<\/p>\n<p>\u2013 Dile al maestro, muchacho, que si lo quiere vender ya, no puedo darle m\u00e1s que 58 monedas de oro por su anillo.<\/p>\n<p>\u2013 \u00bf\u00bf\u00bf\u00bf58 monedas???? -exclam\u00f3 el joven.<\/p>\n<p>\u2013 S\u00ed, -replic\u00f3 el joyero. Yo s\u00e9 que con tiempo podr\u00edamos obtener por \u00e9l cerca de 70 monedas, pero no s\u00e9, si la venta es urgente\u2026<\/p><\/blockquote>\n<p><a class=\"full-img\" href=\"http:\/\/www.recreoviral.com\/wp-content\/uploads\/2016\/03\/PARABOLA3.jpg\" rel=\"attachment wp-att-97560\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-97560\" src=\"http:\/\/www.recreoviral.com\/wp-content\/uploads\/2016\/03\/PARABOLA3-768x432.jpg\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" alt=\"PARABOLA JORGE BUCAY ILUSTRADA CON LA PEL\u00cdCULA EL APRENDIZ DE BRUJO\" width=\"730\" height=\"411\" \/><\/a><\/p>\n<blockquote><p>El joven corri\u00f3 emocionado a casa del maestro a contarle lo sucedido.<\/p>\n<p>\u2013 Si\u00e9ntate, dijo el maestro despu\u00e9s de escucharlo. T\u00fa eres como este anillo: una joya \u00fanica y valiosa. Y como tal, s\u00f3lo puede evaluarte verdaderamente un experto. \u00bfQu\u00e9 haces por la vida pretendiendo que cualquiera descubra tu verdadero valor?\u00a0Y diciendo esto, volvi\u00f3 a ponerse el anillo en el dedo peque\u00f1o de su mano izquierda\u201d.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Ya lo dec\u00eda Arist\u00f3teles: \u201cSomos lo que hacemos d\u00eda a d\u00eda; de modo que la excelencia no es un acto, es un h\u00e1bito\u201d.<\/p>\n","protected":false},"author":12,"featured_media":54111,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-54110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=54110"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54110\/revisions"}],"predecessor-version":[{"id":54112,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54110\/revisions\/54112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/54111"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=54110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=54110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=54110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}