{"id":54132,"date":"2016-03-20T20:23:04","date_gmt":"2016-03-21T00:23:04","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=54132"},"modified":"2016-03-20T20:23:04","modified_gmt":"2016-03-21T00:23:04","slug":"diez-anos-de-twitter-la-historia-de-la-red-social-que-cambio-nuestras-vidas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/diez-anos-de-twitter-la-historia-de-la-red-social-que-cambio-nuestras-vidas\/","title":{"rendered":"Diez a\u00f1os de Twitter: la historia de la red social que cambi\u00f3 nuestras vidas"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/twitter-birds-pajaros.jpg\" rel=\"attachment wp-att-54135\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-54135\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/twitter-birds-pajaros.jpg\" alt=\"twitter-birds-pajaros\" width=\"610\" height=\"371\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/twitter-birds-pajaros.jpg 610w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/03\/twitter-birds-pajaros-300x182.jpg 300w\" sizes=\"auto, (max-width: 610px) 100vw, 610px\" \/><\/a>En estos diez a\u00f1os, Twitter ha sido el lugar de ocurrencias de miles de trending topics, de cientos de miles hashtags, donde algunos memes pasaban por su juventud tras nacer en 4chan o Reddit, y antes de morir en Facebook o Instagram.<!--more--><\/p>\n<p>Con el paso de los a\u00f1os, su puesto destacado ha ido diluy\u00e9ndose. Mantiene el pulso del d\u00eda a d\u00eda p\u00fablico, mientras acab\u00f3 perdiendo el personal ante las plataformas de mensajer\u00eda. Los nuevos usuarios optan por Instagram o Snapchat, y la masa opta por Facebook. <strong>No por menos relevante hoy, la historia de Twitter es menos importante.<\/strong><\/p>\n<h3>La prehistoria<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-928426\" src=\"http:\/\/i0.wp.com\/hipertextual.com\/files\/2016\/03\/twttr.png?resize=610%2C426\" alt=\"twttr\" width=\"610\" height=\"426\" \/><\/p>\n<p>Twitter, entonces llamado \u201ctwttr\u201d, se cre\u00f3 como un producto dentro de Odeo, una compa\u00f1\u00eda de podcasting que pas\u00f3 m\u00e1s o menos desapercibida, aunque muchos mantuvimos cuenta y us\u00e1bamos con inter\u00e9s la plataforma. B\u00e1sicamente, era un SoundCloud rudimentario.<\/p>\n<p><strong>Noah Glass crea el nombre \u00abTwitter\u00bb<\/strong>, aunque gracias a la moda de Silicon Valley, comienzan llam\u00e1ndose \u201ctwttr\u201d. Es poco despu\u00e9s cuando Jack Dorsey, el actual CEO, env\u00eda el primer tweet.<\/p>\n<p><iframe id=\"twitter-widget-0\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Tweet de Twitter\" width=\"300\" height=\"150\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"20\"><\/iframe><\/p>\n<p>El tiempo pasa, y los usuarios son b\u00e1sicamente empleados de Odeo y amigos de los mismos, va creciendo por el boca a boca. El 15 de julio del mismo a\u00f1o tienen su primera cobertura en la prensa, a trav\u00e9s de dos art\u00edculos en<a title=\"Abre en una nueva ventana\" href=\"http:\/\/techcrunch.com\/2006\/07\/15\/is-twttr-interesting\/\" target=\"_blank\">TechCrunch<\/a> y <a title=\"Abre en una nueva ventana\" href=\"https:\/\/gigaom.com\/2006\/07\/15\/valleys-all-twttr\/\" target=\"_blank\">GigaOm<\/a>. Mientras que el post de Om Malik es bastante favorable, calificando a Twttr de algo \u201cviral\u201d, \u201cubicuo\u201d y \u201cadictivo\u201d mientras que Michael Arrington lo define como \u201cun rollo total\u201d aunque califica la idea de \u201cbuena\u201d y \u201cviral\u201d. <strong>Ver\u00e9is, j\u00f3venes amigos, viral era la palabra de moda entonces. Todo era viral, incluso los virus.<\/strong><\/p>\n<p>Varios empleados de Odeo, entre ellos los cuatro fundadores, Biz Stone, Evan Williams, Jack Dorsey y Noah Glass, deciden fundar la \u201cObvious Corporation\u201d y comprar la empresa para la que trabajan, Odeo, incluyendo todos sus activos, incluyendo el dominio <a class=\"vglnk\" href=\"http:\/\/twitter.com\/\" target=\"_blank\" rel=\"nofollow\">Twitter.com<\/a>, que ya hab\u00eda mutado su nombre para entonces.<\/p>\n<h3>La explosi\u00f3n geek<\/h3>\n<p>En marzo de 2007, hay una explosi\u00f3n de usuarios. Twitter alcanza el mill\u00f3n de usuarios. Es todo un \u00e9xito y la comidilla durante la convenci\u00f3n South by Southwest de 2007, en Texas. La chispa prende la blogosfera y la gente \u201cgeek\u201d se abre cuentas en masa.<\/p>\n<p>El mes siguiente, Twitter sale de Obvious Corporation y se establece como su propia empresa, y <strong>recibe su primera ronda de inversi\u00f3n: 5 millones de d\u00f3lares<\/strong> con una valoraci\u00f3n total de 20 millones. Poco <a href=\"http:\/\/hipertextual.com\/2008\/07\/twitter-compra-summize\">despu\u00e9s compran Summize<\/a>, un motor de b\u00fasqueda que hab\u00eda nacido al calor de la pasi\u00f3n por Twitter.<\/p>\n<h3>Creaci\u00f3n del hashtag, la menci\u00f3n y el retweet<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-928410\" src=\"http:\/\/i0.wp.com\/hipertextual.com\/files\/2016\/03\/twitter-engagement-610x343.jpg?resize=610%2C343\" alt=\"twitter-engagement\" width=\"610\" height=\"343\" \/><\/p>\n<p>Lo cre\u00e1is o no, amigos, Twitter no naci\u00f3 con el hashtag bajo el brazo, ni la menci\u00f3n, ni el retweet. <strong>Fuimos los usuarios los que creamos eso.<\/strong><\/p>\n<p>La primera menci\u00f3n la realiz\u00f3 Robert Andersen en noviembre de 2006:<\/p>\n<p><iframe id=\"twitter-widget-1\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Twitter Tweet\" width=\"300\" height=\"150\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"55281\"><\/iframe><\/p>\n<p>Los retweets no tardar\u00edan en llegar, ya tras la explosi\u00f3n de usuarios. Y s\u00ed amigos, ten\u00edas que hacerlo \u00a1A MANO!, copiando y pegando el tweet. Aunque poco a poco los clientes no oficiales fueron a\u00f1adiendo soporte para hacerlo m\u00e1s f\u00e1cil.<\/p>\n<p><iframe id=\"twitter-widget-2\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Twitter Tweet\" width=\"300\" height=\"150\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"31669791\"><\/iframe><\/p>\n<p>El primer hashtag lo realizo Chris Messina mucho m\u00e1s tarde, en agosto de 2007<\/p>\n<p><iframe id=\"twitter-widget-3\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Twitter Tweet\" width=\"300\" height=\"150\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"223115412\"><\/iframe><\/p>\n<h3>\u201dEsto de Twitter no est\u00e1 tan mal\u2026\u201d<\/h3>\n<div id=\"attachment_928413\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-928413\" src=\"http:\/\/i0.wp.com\/hipertextual.com\/files\/2016\/03\/2010-fifa-world-cup-twitter-tweetspersecond-were-much-higher-than-average-during-the-match_50290ae26cb72_w1500.jpg?resize=610%2C342\" alt=\"Twitter durante la final del mundial de 2010. Uno de los momentos clave en la red social.\" width=\"610\" height=\"342\" \/><\/p>\n<p class=\"wp-caption-text\">Twitter durante la final del mundial de 2010. Uno de los momentos clave de la red social.<\/p>\n<\/div>\n<p>Jack Dorsey deja de ser el CEO de la compa\u00f1\u00eda y se va a hacer yoga y meditar. Luego acabar\u00eda fundando Square, una compa\u00f1\u00eda que permite a comercios aceptar pagos por tarjeta de forma f\u00e1cil y c\u00f3moda. Evan Williams le sustituye y empieza la era dorada de Twitter, y se empieza a ver el valor de la red social.<\/p>\n<p>Los Juegos Ol\u00edmpicos de Pek\u00edn, la Eurocopa de f\u00fatbol, el Mundial de 2010 y varias Superbowl <strong>hacen destacar la inmediatez de la informaci\u00f3n fluyendo por Twitter,<\/strong> y la hacen la herramienta favorita de los medios de comunicaci\u00f3n.<\/p>\n<p><strong>Ashton Kutcher consigue ser el primer usuario en alcanzar el mill\u00f3n de followers<\/strong> en una sprint final muy justo entre \u00e9l y la CNN.<\/p>\n<p><iframe id=\"twitter-widget-4\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Twitter Tweet\" width=\"300\" height=\"150\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"1540145225\"><\/iframe><iframe id=\"twitter-widget-5\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Twitter Tweet\" width=\"300\" height=\"150\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"1540140813\"><\/iframe><\/p>\n<p>Twitter tiene que instalar servidores concretos para macro-estrellas de la red social como \u00e9l, Justin Bieber, Katy Perry y muchos m\u00e1s. Hoy en d\u00eda Kutcher tiene m\u00e1s de 17 millones de seguidores. A\u00f1os m\u00e1s tarde, Caitlyn Jenner tardar\u00eda solo cuatro horas en conseguir <a title=\"Abre en una nueva ventana\" href=\"https:\/\/twitter.com\/Caitlyn_Jenner\/status\/605507298849656833\" target=\"_blank\">su primer mill\u00f3n de followers desde que crea su cuenta<\/a>, el anterior r\u00e9cord lo ten\u00eda el presidente de Estados Unidos en @POTUS que tard\u00f3 casi 5h, pero durante tiempo el r\u00e9cord era de Robert Downey Jr. que hab\u00eda tardado 23 horas, un a\u00f1o antes.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/ma8AcfKGaEI\" width=\"610\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h3>Fail Whale<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-928414\" src=\"http:\/\/i0.wp.com\/hipertextual.com\/files\/2016\/03\/twitter-fail-whale.jpg?resize=610%2C458\" alt=\"twitter-fail-whale\" width=\"610\" height=\"458\" \/><\/p>\n<p>Durante su \u00e9poca dorada, los problemas de crecimiento eran agudos, con interrupciones constantes del servicio que manten\u00edan a los usuarios enfadados tanto por la ca\u00edda del servicio como por la manifiesta adicci\u00f3n que ten\u00edan del mismo.<\/p>\n<p>Twitter crea la Fail Whale, <a title=\"Abre en una nueva ventana\" href=\"http:\/\/www.yiyinglu.com\/sc\/illustration\/\" target=\"_blank\">una ilustraci\u00f3n de Yiying Lu<\/a>, que pronto se convirti\u00f3 en casi un icono mismo de la plataforma. <a title=\"Abre en una nueva ventana\" href=\"http:\/\/www.yiyinglu.com\/?portfolio=lifting-a-dreamer-aka-twitter-fail-whale\" target=\"_blank\">Con camisetas, memes y chistes<\/a>. <strong>El nombre, como todo, surgi\u00f3 <a title=\"Abre en una nueva ventana\" href=\"https:\/\/twitter.com\/qrush\/statuses\/822613478\" target=\"_blank\">de la propia comunidad<\/a>.<\/strong><\/p>\n<p><iframe id=\"twitter-widget-6\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Twitter Tweet\" width=\"300\" height=\"150\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"843506119\"><\/iframe><\/p>\n<p>Los directivos de Twitter no dudaron en subirse a la ola de la popularidad.<\/p>\n<h3>Llega Costolo<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-136003\" src=\"http:\/\/i0.wp.com\/hipertextual.com\/files\/2011\/09\/dick-costolo.jpg?resize=610%2C346\" alt=\"Dick Costolo\" width=\"610\" height=\"346\" \/><\/p>\n<p>Evan Williams se baja del carro, y Dick Costolo, que ven\u00eda de Google (tras crear FeedBurner), se pone al mando de Twitter como nuevo CEO. Bajo su batuta,<strong>Twitter llega a su apogeo.<\/strong><\/p>\n<p>Twitter consigue <strong>una ronda de financiaci\u00f3n especialmente alta, de 800 millones de d\u00f3lares<\/strong> con una valoraci\u00f3n total de 8.000 millones. La compa\u00f1\u00eda supera los 100 millones de usuarios activos.<\/p>\n<h3>Del amor al odio con los desarrolladores<\/h3>\n<div id=\"attachment_182028\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-182028\" src=\"http:\/\/i2.wp.com\/hipertextual.com\/files\/2012\/10\/Captura-de-pantalla-2012-10-22-a-las-15.48.46.jpg?resize=610%2C473\" alt=\"Tweetbot fue uno de los servicios que m\u00e1s sufri\u00f3 el l\u00edmite de usuarios.\" width=\"610\" height=\"473\" \/><\/p>\n<p class=\"wp-caption-text\">Tweetbot fue uno de los servicios que m\u00e1s sufri\u00f3 el l\u00edmite de usuarios.<\/p>\n<\/div>\n<p>Twitter estaba dando el estir\u00f3n, y empezaron a llegar problemas. A nivel interno tuvieron que <a title=\"Abre en una nueva ventana\" href=\"https:\/\/blog.twitter.com\/2010\/announcing-snowflake\" target=\"_blank\">implementar SnowFlake<\/a>, un sencillo algoritmo que creaba identificadores \u00fanicos para cada tweet en un entorno distribuido, ante la avalancha de tweets durante momentos clave.<\/p>\n<p>Pero para los usuarios, los cambios empezaron cuando Twitter <strong><a href=\"http:\/\/hipertextual.com\/2010\/04\/twitter-compra-tweetie-la-hace-gratis-y-la-ofrece-como-aplicacion-oficial-para-el-iphone\">decide adquirir la famosa Tweetie<\/a>, convirti\u00e9ndola en cliente oficial y ofreci\u00e9ndola gratis.<\/strong>Twitter ten\u00eda que controlar la plataforma y no dejar la experiencia final en manos de desarrolladores ajenos. Poco a poco Android, BlackBerry, Mac fueron recibiendo sus apps oficiales. Un a\u00f1o despu\u00e9s <a href=\"http:\/\/hipertextual.com\/2011\/05\/twitter-adquiere-tweetdeck-por-40-millones-de-dolares\">la compra de TweetDeck<\/a>, el cliente preferido de muchos usuarios y empresas, dejaba clara la apuesta, pero nadie esperaba lo que ocurrir\u00eda despu\u00e9s: con un bot\u00f3n, <a title=\"Abre en una nueva ventana\" href=\"http:\/\/thenextweb.com\/twitter\/2012\/08\/17\/twitter-4\/\" target=\"_blank\">Twitter destruy\u00f3 casi todo el inter\u00e9s de los desarrolladores<\/a> limitando el n\u00famero m\u00e1ximo de usuarios que pod\u00edan usar cada aplicaci\u00f3n, <strong>eliminando de un plumazo toda la innovaci\u00f3n que estaba teniendo lugar sobre la plataforma.<\/strong><\/p>\n<p>Fue ese momento en el que, <strong>en retrospectiva, se empezaron a notar los problemas de la red social<\/strong>. Hoy podemos decir <a href=\"http:\/\/hipertextual.com\/2015\/08\/twitter-se-muere\">que Twitter se muere<\/a>. Lleva un a\u00f1o sin crecer y <a href=\"http:\/\/hipertextual.com\/2016\/02\/resultados-financieros-twitter\">recientemente empez\u00f3 a perder usuarios<\/a>, un signo que ninguna red social ha sabido invertir.<\/p>\n<h3>La \u00e9poca dorada<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-119534\" src=\"http:\/\/i1.wp.com\/hipertextual.com\/files\/2011\/05\/Jlu-S%C3%A1nchez-DR-Madrid-15M.png?resize=610%2C403\" alt=\"Jlu-S\u00e1nchez-DR-Madrid-15M\" width=\"610\" height=\"403\" \/><\/p>\n<p>Twitter se convierte en una herramienta que realmente mide el pulso de la humanidad, al menos de la humanidad con acceso a Internet, claro.<\/p>\n<p>Cientos de protestas mundiales son instant\u00e1neamente compartidas y organizadas a trav\u00e9s de Twitter. Entre ellas destacan los movimientos de la Primavera \u00c1rabe en Egipto, el 15M en Espa\u00f1a, el movimiento Occupy en Estados Unidos, las protestas en Grecia por la situaci\u00f3n econ\u00f3mica, la invasi\u00f3n de Ucrania y el movimiento BlackLivesMatter en Estados Unidos y JeSuisCharlie en Francia, las protestas post-electorales en Ir\u00e1n, y muchos, muchos m\u00e1s movimientos. <strong>Twitter fue sin duda instrumental en la creaci\u00f3n, difusi\u00f3n y organizaci\u00f3n de todos ellos.<\/strong><\/p>\n<h3>Momentos hist\u00f3ricos<\/h3>\n<p>Durante los diez a\u00f1os, miles de momentos clave han pasado por la red social. Varias muertes, en especial la de <a title=\"Abre en una nueva ventana\" href=\"http:\/\/www.dailymail.co.uk\/sciencetech\/article-1195651\/How-Michael-Jacksons-death-shut-Twitter-overwhelmed-Google--killed-Jeff-Goldblum.html\" target=\"_blank\">Michael Jackson<\/a>, <a title=\"Abre en una nueva ventana\" href=\"https:\/\/twitter.com\/RealPaulWalker\/statuses\/406984510367350784\" target=\"_blank\">Paul Walker<\/a>, <a title=\"Abre en una nueva ventana\" href=\"https:\/\/twitter.com\/justinbieber\/statuses\/251039231160492033\" target=\"_blank\">Avalanna<\/a>, una fan de Justin Bieber que muri\u00f3 de c\u00e1ncer con seis a\u00f1os, <a title=\"Abre en una nueva ventana\" href=\"https:\/\/twitter.com\/msleamichele\/statuses\/361895025073856512\" target=\"_blank\">Cory Monteith<\/a>, <a title=\"Abre en una nueva ventana\" href=\"https:\/\/twitter.com\/BillGates\/status\/121746029308678145\" target=\"_blank\">Steve Jobs<\/a> y muchos m\u00e1s famosos marcaron los d\u00edas posteriores en la red social. Pero m\u00e1s all\u00e1 de eso, hubo varios tweets hist\u00f3ricos por su propio peso.<\/p>\n<p>Un avi\u00f3n se estrella en el r\u00edo Hudson de Nueva York, la imagen en Twitter acapara portadas de todo el mundo. Por entonces Twitter no permit\u00eda subir im\u00e1genes, y los usuarios utilizaban servicios alternativos como TwitPic, <a title=\"Abre en una nueva ventana\" href=\"https:\/\/blog.twitpic.com\/2014\/10\/twitpics-future\/\" target=\"_blank\">ahora difunto<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-928417\" src=\"http:\/\/i0.wp.com\/hipertextual.com\/files\/2016\/03\/1827262-1.jpg?resize=610%2C446\" alt=\"1827262\" width=\"610\" height=\"446\" \/><\/p>\n<p><iframe id=\"twitter-widget-7\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Twitter Tweet\" width=\"300\" height=\"150\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"1121915133\"><\/iframe><\/p>\n<p>Mientras Estados Unidos intentaba captura a Bin Laden en Pakistan, <strong>alguien tuite\u00f3 lo extra\u00f1o que era escuchar helic\u00f3pteros en Abotabad a esas horas de la noche.<\/strong><\/p>\n<p><iframe id=\"twitter-widget-8\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Twitter Tweet\" width=\"300\" height=\"150\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"64780730286358528\"><\/iframe><\/p>\n<p>La NASA declara que encuentra hielo, de agua, en Marte.<\/p>\n<p><iframe id=\"twitter-widget-9\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Twitter Tweet\" width=\"300\" height=\"150\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"839088619\"><\/iframe><\/p>\n<p>Mike Massimino tuitea desde el espacio.<\/p>\n<p><iframe id=\"twitter-widget-10\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Twitter Tweet\" width=\"300\" height=\"150\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"1777093627\"><\/iframe><\/p>\n<p>Barack Obama public\u00f3 un tweet para se\u00f1alar que hab\u00eda ganado las elecciones a presidente de Estados Unidos.<\/p>\n<p><iframe id=\"twitter-widget-11\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Twitter Tweet\" width=\"300\" height=\"150\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"266031293945503744\"><\/iframe><\/p>\n<p>Durante los premios Oscar de 2014, Bradley Cooper y varios artistas m\u00e1s se toman una fotograf\u00eda y posterior tweet que, debido a la audiencia del evento y la instantaneidad de la plataforma, r\u00e1pidamente se convierte en lo m\u00e1s compartido en la historia de Twitter.<\/p>\n<p><iframe id=\"twitter-widget-12\" class=\"twitter-tweet twitter-tweet-rendered\" title=\"Tweet de Twitter\" width=\"300\" height=\"150\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"440322224407314432\"><\/iframe><\/p>\n<h3>\u00a1A bolsa!<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-928420\" src=\"http:\/\/i0.wp.com\/hipertextual.com\/files\/2016\/03\/131107095647-investing-twitter-ipo-nyse-00000510-1024x576.jpg?resize=610%2C343\" alt=\"131107095647-investing-twitter-ipo-nyse-00000510-1024x576\" width=\"610\" height=\"343\" \/><\/p>\n<p>Costolo saca <a href=\"http:\/\/hipertextual.com\/2013\/11\/ipo-twitter-accion\">la red social a bolsa<\/a>, la compa\u00f1\u00eda triplica su valor en bolsa en cuatro meses. Este movimiento fue mayormente visto como algo <a href=\"http:\/\/hipertextual.com\/2013\/11\/exito-twitter-bolsa\">bueno en su momento<\/a>, pero que ha llevado los vaivenes de la red social a un entorno p\u00fablico. La acci\u00f3n hoy se sit\u00faa en un precio mucho inferior a su salida a bolsa, y es fruto de constantes rumores de venta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-928411\" src=\"http:\/\/i1.wp.com\/hipertextual.com\/files\/2016\/03\/twitter-acciones.png?resize=610%2C397\" alt=\"twitter acciones\" width=\"610\" height=\"397\" \/><\/p>\n<p>Google y Twitter mantuvieron negociaciones, pero finalmente no llegaron a nada, y la red social permaneci\u00f3 independiente.<\/p>\n<h3>Vine y Periscope<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-384106\" src=\"http:\/\/i2.wp.com\/hipertextual.com\/files\/2015\/08\/DSC07977.jpeg?resize=610%2C405\" alt=\"Vine S6 Edge Samsung Alex\" width=\"610\" height=\"405\" \/><\/p>\n<p>Tras no conseguir comprar Instagram, <strong>Dick Costolo realiz\u00f3 dos compras que definir\u00edan el futuro de la compa\u00f1\u00eda.<br \/>\n<\/strong><br \/>\nTras su fundaci\u00f3n en verano de 2012, y antes incluso de lanzar al p\u00fablico,<a href=\"http:\/\/hipertextual.com\/archivo\/2013\/01\/twitter-vine-compartir-videos\/\">Costolo compra Vine en octubre de 2012<\/a> por 30 millones de d\u00f3lares. La plataforma sigue mintiendo el mismo esp\u00edritu y forma: v\u00eddeos de 6 segundos, que se han popularizado incre\u00edblemente con el paso de los a\u00f1os, especialmente entre los j\u00f3venes urbanos de Estados Unidos.<\/p>\n<p>Vine pasar\u00eda a crear una nueva generaci\u00f3n de actores y m\u00fasicos que alcanzar\u00edan cuotas inimaginables de popularidad y ser\u00edan catapultados a Hollywood debido a su \u00e9xito creando v\u00eddeos en Vine.<\/p>\n<p>La otra <a href=\"http:\/\/hipertextual.com\/2015\/04\/por-que-amamos-periscope\">gran compra fue Periscope<\/a>, y tambi\u00e9n fue otro gran acierto de Dick Costolo que se adelant\u00f3 compr\u00e1ndola antes de su lanzamiento p\u00fablico. Tras una competencia dura inicial con Meerkat, <strong>Periscope acab\u00f3 quedando como la plataforma de streaming en directo por excelencia <\/strong>gracias a la integraci\u00f3n con el propio Twitter.<\/p>\n<h3>Hola de nuevo, Jack<\/h3>\n<div id=\"attachment_920825\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-920825\" src=\"http:\/\/i2.wp.com\/hipertextual.com\/files\/2016\/02\/jack-dorsey.jpg?resize=610%2C406\" alt=\"Jack Dorsey \/ Scott Eisen\" width=\"610\" height=\"406\" \/><\/p>\n<p class=\"wp-caption-text\">Jack Dorsey \/ Scott Eisen<\/p>\n<\/div>\n<p>Costolo deja la compa\u00f1\u00eda y uno de sus fundadores, <strong>Jack Dorsey vuelve como CEO<\/strong> temporal mientras buscan uno permanente. Dorsey mantendr\u00eda su puesto como CEO en Square, la compa\u00f1\u00eda de pagos que cre\u00f3 al dejar la red social.<a href=\"http:\/\/hipertextual.com\/2015\/10\/jack-dorsey-ceo-twitter-oficial\">Unos meses despu\u00e9s la junta decide que Jack es el CEO permanente que buscaban<\/a>, en una medida controvertida porque muchos piensan que Dorsey no podr\u00eda mantener las dirigir de forma efectiva ambas empresas.<\/p>\n<p>Poco despu\u00e9s Twitter lanza \u201cMoments\u201d para rivalizar con otros servicios curando historias y acontecimientos, ante el desinter\u00e9s mayoritario de la base de usuarios.<\/p>\n<h3>El futuro<\/h3>\n<div id=\"attachment_928422\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-928422\" src=\"http:\/\/i0.wp.com\/hipertextual.com\/files\/2016\/03\/shutterstock_313677632.jpg?resize=610%2C407\" alt=\"Denys Prykhodov \/ Shutterstock.com\" width=\"610\" height=\"407\" \/><\/p>\n<p class=\"wp-caption-text\"><a title=\"Abre en una nueva ventana\" href=\"http:\/\/www.shutterstock.com\/gallery-695464p1.html?cr=00&amp;pl=edit-00\" target=\"_blank\">Denys Prykhodov<\/a> \/ <a title=\"Abre en una nueva ventana\" href=\"http:\/\/www.shutterstock.com\/editorial?cr=00&amp;pl=edit-00\" target=\"_blank\">Shutterstock.com<\/a><\/p>\n<\/div>\n<p>La <a href=\"http:\/\/hipertextual.com\/2016\/02\/twitter-timeline-algoritmo\">implementaci\u00f3n del algoritmo<\/a> crear\u00e1 problemas con los usuarios muy activos del medio, las aplicaciones de terceros cada versi\u00f3n a\u00f1aden menos funcionalidad al no poder expandir su base de usuarios e ingresos. Las diferencias entre los clientes oficiales y de terceros se agrandan.<\/p>\n<p>Twitter dar\u00e1 alas a una gran expansi\u00f3n publicitaria para paliar su descenso de usuarios. Pero la plataforma seguir\u00e1 aportando valor, de momento.<\/p>\n<p>Nadie sabe a ciencia cierta qu\u00e9 puede hacer Twitter para impedir su probable descenso continuado de usuarios, pero lo m\u00e1s preocupante: <strong>\u00bfpuede un director ejecutivo que gasta la mitad de sus energ\u00edas en otra empresa tambi\u00e9n en una \u00e9poca clave, llevar el tim\u00f3n de forma efectiva?<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En estos diez a\u00f1os, Twitter ha sido el lugar de ocurrencias de miles de trending topics, de cientos de miles hashtags, donde algunos memes pasaban por su juventud tras nacer en 4chan o Reddit, y antes de morir en Facebook o Instagram.<\/p>\n","protected":false},"author":12,"featured_media":54135,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-54132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=54132"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54132\/revisions"}],"predecessor-version":[{"id":54136,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54132\/revisions\/54136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/54135"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=54132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=54132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=54132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}