{"id":54594,"date":"2016-04-08T12:36:58","date_gmt":"2016-04-08T16:36:58","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=54594"},"modified":"2016-04-08T12:41:01","modified_gmt":"2016-04-08T16:41:01","slug":"por-que-es-importante-el-cifrado-de-whatsapp","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/por-que-es-importante-el-cifrado-de-whatsapp\/","title":{"rendered":"\u00bfPor qu\u00e9 es importante el cifrado de WhatsApp?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/5706c9e2c361884b648b457b.jpg\" rel=\"attachment wp-att-54595\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-54595\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/5706c9e2c361884b648b457b.jpg\" alt=\"5706c9e2c361884b648b457b\" width=\"750\" height=\"422\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/5706c9e2c361884b648b457b.jpg 750w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/5706c9e2c361884b648b457b-300x169.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a>La aplicaci\u00f3n, que se blinda y hace inaccesibles sus mensajes, representa un avance en la confidencialidad de sus usuarios, pero un posible problema si su uso acaba en malas manos. <!--more--><\/p>\n<p>El pasado 5 de abril, la compa\u00f1\u00eda de mensajer\u00eda instant\u00e1nea WhatsApp\u00a0anunci\u00f3\u00a0su decisi\u00f3n y aplicaci\u00f3n para cifrar sus mensajes y llamadas a trav\u00e9s del cifrado de extremo a extremo, lo que proporciona una absoluta confidencialidad entre el emisor y el receptor en el campo de las telecomunicaciones, hecho que ha analizado la revista\u00a0Wired.<\/p>\n<p>La idea de cifrar y codificar las comunicaciones por WhatsApp empez\u00f3 a gestarse en 2013 en la cabeza del programador, emprendedor y cofundador de la aplicaci\u00f3n, Brian Acton. Pero fue en 2014 cuando el experto en seguridad y creador de Open Whisper Systems, Moxie Marlinspike, se uni\u00f3 WhatsApp y se empez\u00f3 a desarrollar el proyecto de cifrado.<\/p>\n<p>Pero,\u00a0<strong>\u00bfhasta qu\u00e9 punto es importante esta medida?<\/strong>\u00a0Como explic\u00f3 Raj Samani, directivo de Intel Security, \u00abesto ofrece la garant\u00eda de que los mensajes no sean interceptados por terceras partes no autorizadas e indeseadas, ni siquiera el propio WhatsApp podr\u00e1 acceder a los mensajes, llamadas, documentos, im\u00e1genes o videos que compartamos\u00bb. As\u00ed, los millones de usuarios de esta aplicaci\u00f3n\u00a0\u00abtienen la confianza de saber que \u00fanicamente los destinatarios est\u00e1n leyendo el mensaje\u00bb, opina.<\/p>\n<p><a class=\"read-more__link\" href=\"https:\/\/actualidad.rt.com\/actualidad\/202041-eeuu-buscar-acceder-datos-whatsapp\" target=\"_blank\"><img decoding=\"async\" class=\"read-more__cover\" src=\"https:\/\/esp.rt.com\/actualidad\/public_images\/2016.03\/thumbnail\/56e6ec88c36188624f8b4628.jpg\" alt=\"Una imagen ilustrativa\" \/><\/a><\/p>\n<p>A su vez, Brian Acton considera que desarrollar un producto con una protecci\u00f3n de esas caracter\u00edsticas har\u00e1 la vida m\u00e1s segura en todo el mundo, ya que cualquier persona puede chatear con su m\u00e9dico, hacer negocios entre empresas o gestiones dentro de las mismas, por ejemplo, sin peligro de fugas ni de perder la confidencialidad, ya que el cifrado de extremo a extremo es indescifrable. Asimismo, Marlinspike afirma que \u00abde alg\u00fan modo, el cifrado es un intento de regresar a un pasado cercano en el que Internet a\u00fan era libre, donde los correos personales no eran objeto de an\u00e1lisis de masas como lo son ahora\u00bb.<\/p>\n<p>La otra cara de la moneda es la reacci\u00f3n de los gobiernos y el riesgo que puede acarrear esta aplicaci\u00f3n de mensajer\u00eda en manos del hampa y de organizaciones terroristas. En diciembre pasado, Brasil\u00a0suspendi\u00f3\u00a0el servicio de WhatsApp por 48 horas al negarse la empresa a proporcionar \u00a1nformaci\u00f3n para una investigaci\u00f3n policial vinculada al narcotr\u00e1fico.<\/p>\n<p>De momento, ni el FBI ni el Ministerio de Justicia de EE.UU. han comentado nada respecto al nuevo sistema de cifrado de WhatsApp, que aparece en medio del\u00a0conflicto\u00a0entre Silicon Valley y el Gobierno estadounidense en materia de privacidad, ya que el mismo Ministerio prepara una\u00a0demandada\u00a0contra la empresa de telecomunicaci\u00f3n instant\u00e1nea igual que se hizo con\u00a0Apple\u00a0tras los\u00a0atentados\u00a0terroristas de San Bernardino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La aplicaci\u00f3n, que se blinda y hace inaccesibles sus mensajes, representa un avance en la confidencialidad de sus usuarios, pero un posible problema si su uso acaba en malas manos.<\/p>\n","protected":false},"author":9,"featured_media":54595,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-54594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=54594"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54594\/revisions"}],"predecessor-version":[{"id":54596,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54594\/revisions\/54596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/54595"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=54594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=54594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=54594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}