{"id":54603,"date":"2016-04-08T16:39:00","date_gmt":"2016-04-08T20:39:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=54603"},"modified":"2016-04-08T16:50:39","modified_gmt":"2016-04-08T20:50:39","slug":"como-aprendemos-a-hablar-cuando-somos-bebes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/como-aprendemos-a-hablar-cuando-somos-bebes\/","title":{"rendered":"\u00bfC\u00f3mo aprendemos a hablar cuando somos beb\u00e9s?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/bebe.jpg\" rel=\"attachment wp-att-54604\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-54604\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/bebe.jpg\" alt=\"bebe\" width=\"610\" height=\"371\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/bebe.jpg 610w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/bebe-300x182.jpg 300w\" sizes=\"auto, (max-width: 610px) 100vw, 610px\" \/><\/a>\u00bfComo puede ser que un beb\u00e9 aprenda a hablar? El lenguaje es una herramienta esencial de nuestra naturaleza. Pero tambi\u00e9n es un arte sutil y complejo que ha definido lo que somos desde hace varios milenios.<!--more--><\/p>\n<p>Nuestra especie no ser\u00eda lo que es si no pudi\u00e9ramos comunicarnos. Hablar es algo tan com\u00fan que normalmente despreciamos, sin querer, una idea muy simple: \u00bfsabes <strong>lo dif\u00edcil que es aprender a hablar<\/strong>? Este proceso es uno de los m\u00e1s importantes de nuestra vida. Y no es nada, pero nada sencillo. Para poder comprenderlo, muchos investigadores han ido la fuente m\u00e1s importante que existe para entender c\u00f3mo aprendemos a hablar: los beb\u00e9s.<\/p>\n<h2>800 fonemas<\/h2>\n<p><q class=\"alignleft\">En el mundo, todas las lenguas existentes est\u00e1n constituidos por la combinaci\u00f3n de 800 fonemas<\/q>Nuestra fisiolog\u00eda, nuestra laringe, lengua y boca, es capaz de articular 800 fonemas. Fonema es la palabra que identifica a los sonidos que producimos para comunicarnos. En el mundo, todas las lenguas existentes est\u00e1n constituidos por <strong>la combinaci\u00f3n de estos 800 fonemas. Pero con tan solo cuarenta ya se puede hablar una lengua<\/strong>. Imaginemos a un beb\u00e9. Acaba de cumplir el medio a\u00f1o de vida. De pronto su cerebro se activa y comienza a prestar una incre\u00edble atenci\u00f3n a los sonidos de su alrededor. Y no solo a los que produce la naturaleza. Absorbe con especial inter\u00e9s cualquier sonido que provenga de sus padres y los adultos que le rodean. A partir de los seis meses los beb\u00e9s se vuelven sensibles a los fonemas, comenzando a captar los detalles. Al principio su cerebro solo capta las vocales. A partir de los nueve meses comienzan a distinguir las consonantes. El ni\u00f1o ya est\u00e1 aprendiendo a hablar. Y lo hace por aptitud innata, porque su cerebro est\u00e1 programado para ello.<\/p>\n<h2>El cerebro estad\u00edstico<\/h2>\n<p>Una vez que el proceso ha empezado el beb\u00e9 va adquiriendo los detalles de c\u00f3mo se usan ciertos fonemas en concreto. Para eso, se sospecha, emplea diversos mecanismos neuronales, como las neuronas espejo, que permiten <strong>imitar las posiciones bucales y otros aspectos concretos<\/strong>. Adem\u00e1s, tambi\u00e9n juegan un papel fundamental otras \u00e1reas del cerebro dedicadas en exclusiva al lenguaje. Poco a poco se despierta en el beb\u00e9 una segunda fase de aprendizaje. A los ocho y diez meses de edad el ni\u00f1o no es capaz de entender qu\u00e9 se dice. Sin embargo, es extremadamente sensible a la frecuencia con la que aparecen estos sonidos, los fonemas. Su cerebro va capturando la cantidad de veces que aparecen estos en una conversaci\u00f3n. Esto es important\u00edsimo porque cada lenguaje tiene un n\u00famero estad\u00edsticamente distinto de cada fonema.<\/p>\n<div id=\"attachment_928062\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-928062\" src=\"http:\/\/i1.wp.com\/hipertextual.com\/files\/2016\/03\/cerebro.jpg?resize=610%2C366\" alt=\"cerebro\" width=\"610\" height=\"366\" \/><\/div>\n<p>Su cerebro es tremendamente pl\u00e1stico y las palabras, con el n\u00famero de veces que aparecen los sonidos, van dejando una huella indeleble. Esta es la base indispensable para aprender un lenguaje. Con el tiempo, el cerebro pasa a una siguiente fase. El ni\u00f1o <strong>ya no solo detecta el n\u00famero de veces que aparece un fonema sino que es capaz de detectar la \u00abcombinaci\u00f3n\u00bb<\/strong> m\u00e1s frecuente de estos fonemas. Efectivamente, la combinaci\u00f3n de sonidos no es otra cosa que las palabras. Poco a poco reconoce las palabras por el hecho de aparecer con m\u00e1s asiduidad. Aqu\u00ed comienza la \u00faltima de las fases para aprender a hablar: entender el significado.<\/p>\n<h2>Aprendizaje social<\/h2>\n<p>Pero, aunque todos tenemos una habilidad innata para aprender a hablar, \u00e9sta no es suficiente. No. Seg\u00fan los \u00faltimos estudios, es imprescindible la interacci\u00f3n social para permitir que un beb\u00e9 aprenda a hablar correctamente. En concreto, es indispensable el papel de los padres. Ese <strong>lenguaje t\u00edpicamente entra\u00f1able, con unas inflexiones muy pronunciadas y casi rid\u00edculas<\/strong>, sonidos muy abiertos y detalles marcados juega un papel fundamental para ense\u00f1ar las reglas de entonaci\u00f3n y ritmo en el lenguaje. Pero es que, adem\u00e1s, una demostraci\u00f3n de nuestra incre\u00edble naturaleza social se muestra en la necesidad de enlazar el lenguaje a un miembro real, a una persona. Varios experimentos han demostrado que se aprende mucho mejor (o incluso es la \u00fanica manera de hacerlo) cuando existe interacci\u00f3n entre una persona real y el beb\u00e9.<\/p>\n<div id=\"attachment_922327\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-922327\" src=\"http:\/\/i0.wp.com\/hipertextual.com\/files\/2016\/02\/tablets-ni\u00f1os.jpg?resize=610%2C407\" alt=\"tablets para ni\u00f1os\" width=\"610\" height=\"407\" \/><\/p>\n<p class=\"wp-caption-text\">\n<\/div>\n<p>Probablemente sean esas inflexiones exageradas y varios detalles de interacci\u00f3n personal (caricias, miradas&#8230;) las que disparen la impronta en el cerebro. Algunos investigadores llaman a este aspecto \u00abresorte social\u00bb. En cualquier caso, los investigadores han descubierto que sea en el lenguaje que sea, <strong>los beb\u00e9s se percatan de que el lenguaje que se emplea con ellos es diferente<\/strong> al que usan los adultos entre s\u00ed. Otro aspecto importante es que los ni\u00f1os aprenden mejor en presencia de sus iguales, aunque este mecanismo todav\u00eda no est\u00e1 claro. En definitiva, para que aprendamos a hablar es necesario que lo hagamos junto a otros miembros de nuestra especie porque tenemos mecanismos especializados para ello.<\/p>\n<h2>Multilenguaje<\/h2>\n<p>Otra pregunta que se han hecho en m\u00faltiples ocasiones los investigadores es qu\u00e9 aprenden los ni\u00f1os expuestos a varias lenguas en sus primeros a\u00f1os de vida. Se sabe desde tiempo atr\u00e1s que los beb\u00e9s aprenden f\u00e1cilmente dos o m\u00e1s lenguas, lo que puede ser muy beneficioso para ellos. Efectivamente, <strong>el mismo proceso de aprendizaje se produce para dos o m\u00e1s lenguas en las primeras etapas<\/strong>. Esto quiere decir que un beb\u00e9 aprender\u00e1 los fonemas, su identificaci\u00f3n y las palabras con mayor facilidad. Seg\u00fan los estudios, un beb\u00e9 expuesto a dos lenguajes puede mantener su etapa de aprendizaje, f\u00e1cilmente, hasta los siete a\u00f1os. Sin embargo, no ocurre lo mismo con ni\u00f1os ya crecidos y adultos. El hecho de que nos cueste m\u00e1s aprender un lenguaje radica, precisamente, en la falta de plasticidad necesaria para aprender fonemas y palabras nuevas.<\/p>\n<p><q class=\"alignleft\">Seg\u00fan los estudios, un beb\u00e9 expuesto a dos lenguajes puede mantener su etapa de aprendizaje, f\u00e1cilmente, hasta los siete a\u00f1os<\/q>El proceso, tras esos primeros meses de vida es \u00abforzado\u00bb, mucho m\u00e1s dificultoso y no innato, como al comienzo de nuestra vida. Por supuesto, existen otros procedimientos de aprendizaje que nos permiten adquirir nuevas lenguas. De hecho, <strong>cuantas m\u00e1s lenguas conocemos, m\u00e1s f\u00e1cil es adquirir una nueva<\/strong>. Pero nunca ser\u00e1 tan f\u00e1cil como cuando somos beb\u00e9s. Todo este af\u00e1n de conocer como podemos aprender a hablar no es balad\u00ed. Adem\u00e1s de resolver cuestiones sobre nuestra propia naturaleza, tiene una finalidad pr\u00e1ctica: saber m\u00e1s sobre los m\u00e9todos de aprendizaje. Este conocimiento nos ayudar\u00e1 a \u00abense\u00f1ar mejor\u00bb y tratar problemas did\u00e1cticos. Tambi\u00e9n puede ayudarnos a adquirir conocimientos m\u00e1s r\u00e1pidos en la edad adulta. Al fin y al cabo, como dec\u00edamos, somos una especie social donde la comunicaci\u00f3n juega un papel inseparable de nuestra naturaleza<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfComo puede ser que un beb\u00e9 aprenda a hablar? El lenguaje es una herramienta esencial de nuestra naturaleza. Pero tambi\u00e9n es un arte sutil y complejo que ha definido lo que somos desde hace varios milenios.<\/p>\n","protected":false},"author":9,"featured_media":54604,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-54603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=54603"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54603\/revisions"}],"predecessor-version":[{"id":54605,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54603\/revisions\/54605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/54604"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=54603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=54603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=54603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}