{"id":54638,"date":"2016-04-10T21:47:00","date_gmt":"2016-04-11T01:47:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=54638"},"modified":"2016-04-10T21:47:00","modified_gmt":"2016-04-11T01:47:00","slug":"pared-perez-destaca-sensates-de-medios-al-no-pasar-material-injurioso-contra-danilo-y-el-pld","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/pared-perez-destaca-sensates-de-medios-al-no-pasar-material-injurioso-contra-danilo-y-el-pld\/","title":{"rendered":"Pared P\u00e9rez destaca sensat\u00e9s de medios al no pasar material \u201cinjurioso\u201d contra Danilo y el PLD"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-54639 size-medium alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/pared-perez-habla-300x188.jpg\" alt=\"pared perez habla\" width=\"300\" height=\"188\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/pared-perez-habla-300x188.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/pared-perez-habla.jpg 733w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Santo Domingo, D.N.-El Secretario General del Partido de la Liberaci\u00f3n Dominicana (PLD) Reinaldo Pared P\u00e9rez agradeci\u00f3 a Dios y a los medios de comunicaci\u00f3n del pa\u00eds que \u201cfueron muy sensatos al no difundir un material altamente injurioso preparado por el candidato opositor Luis Abinader y su equipo, en contra del presidente y candidato del PLD, Danilo Medina\u201d.<!--more--><\/p>\n<p>\u201cComo una manera de protegerse y muy sensatamente y responsable los medios de comunicaci\u00f3n se abstuvieron de dar a conocer el contenido de ese material\u201d, dijo textualmente el candidato a senador del PLD, Reinaldo Pared P\u00e9rez.<\/p>\n<p>Reinaldo volvi\u00f3 a reiterar que el PLD hab\u00eda advertido de esa campa\u00f1a sucia que osquestaban los opositores del PRM contra el candidato pelede\u00edsta Danilo Medina.<\/p>\n<p>\u201cGracias a Dios que los medios de comunicaci\u00f3n han sido sensatos y no han dado acogida al mismo\u201d, precis\u00f3 Reinaldo Pared.<\/p>\n<p>De esta manera Reinaldo respondi\u00f3 al candidato opositor Luis Abinader quien junto a su equipo denunciaron que supuestamente se habr\u00eda presionado a los propietarios de medios para que no difundieran un video.<\/p>\n<p>Respondi\u00f3 preguntas al respecto cuando recorria el barrio Capotillo donde concit\u00f3 un gran apoyo.<\/p>\n<p><strong>Recorre El Capotillo<\/strong><\/p>\n<p>Ensanche Capotillo recibe a Reinaldo Pared con j\u00fabilo y al grito de cuatro a\u00f1os m\u00e1s<\/p>\n<p>Este domingo el senador de la capital Reinaldo Pared P\u00e9rez volvi\u00f3 a ser tendencia noticiosa al recorrer calles y aceras del sector El Capotillo donde una multitud le acompa\u00f1\u00f3 en un mano a mano que se convirti\u00f3 en una marcha y toques de banderas y afiches.<\/p>\n<p>Pared P\u00e9rez acompa\u00f1ado de candidatas y candidatos a diputadas y diputados, comparti\u00f3 con vecinos de esa populosa barriada en medio de la multitud que le aclamaba por cuatro a\u00f1os m\u00e1s.<\/p>\n<p>Ni\u00f1os, j\u00f3venes, adultos y adultos mayores esperaban en las puertas de las casas a Pared P\u00e9rez a todo lo largo de las calles destinadas a ser visitadas por el senador de la capital y candidato a esa posici\u00f3n por el PLD.<\/p>\n<p>A la llegada de Reinaldo a cada grupo le aguardaba una algarab\u00eda de v\u00edtores y aplausos y era notorio el af\u00e1n de los ciudadanos y ciudadanas apretujarse unos a otros por saludar al legislador y candidato a senador del Distrito Nacional.<\/p>\n<p>En el recorrido por el ensanche Capotillo, Pared P\u00e9rez estuvo acompa\u00f1ado de los candidatos a diputados y diputadas, dirigentes de la circunscripci\u00f3n n\u00famero 3 y los miembros de su equipo, entre las que se destacan Margarita Pimentel.<\/p>\n<p>Reinaldo Pared lleg\u00f3 a Capotillo acompa\u00f1ado de su esposa Ingrid Mendoza de Pared quien participa en los mano a mano liderando el equipo de redes conformados por el grupo de mujeres NOSOTRAS con Reinaldo.<\/p>\n<p><strong>Las Redes de Reinaldo<\/strong><\/p>\n<p>La presencia de Pared P\u00e9rez en el ensanche Capotillo era destacada simult\u00e1neamente por el equipo de Redes de Reinaldo que coordina su esposa Ingrid Mendoza de Pared.<\/p>\n<p>De esta manera eran difundidas a trav\u00e9s de la Internet, cientos de fotograf\u00edas de Pared P\u00e9rez cuando saludaba a los residentes y el gesto de estos al ver la figura del legislador de la capital.<\/p>\n<p>Tambi\u00e9n mensajes de texto de apoyo a las im\u00e1genes de \u201cReinaldo con su gente\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, D.N.-El Secretario General del Partido de la Liberaci\u00f3n Dominicana (PLD) Reinaldo Pared P\u00e9rez agradeci\u00f3 a Dios y a los medios de comunicaci\u00f3n del pa\u00eds que \u201cfueron muy sensatos al no difundir un material altamente injurioso preparado por el candidato opositor Luis Abinader y su equipo, en contra del presidente y candidato del PLD, Danilo Medina\u201d.<\/p>\n","protected":false},"author":9,"featured_media":54639,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-54638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=54638"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54638\/revisions"}],"predecessor-version":[{"id":54640,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54638\/revisions\/54640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/54639"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=54638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=54638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=54638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}