{"id":54665,"date":"2016-04-11T08:02:22","date_gmt":"2016-04-11T12:02:22","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=54665"},"modified":"2016-04-11T08:02:22","modified_gmt":"2016-04-11T12:02:22","slug":"que-piensas-del-nuevo-diseno-de-central-park-que-proponen-fotos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/que-piensas-del-nuevo-diseno-de-central-park-que-proponen-fotos\/","title":{"rendered":"\u00bfQue piensas del nuevo dise\u00f1o de Central Park que proponen? (Fotos)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-54667 size-full\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/central-park-nueva-york-700x329.jpg\" alt=\"central-park-nueva-york-700x329\" width=\"700\" height=\"329\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/central-park-nueva-york-700x329.jpg 700w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/central-park-nueva-york-700x329-300x141.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/>El famoso Central Park de Nueva York es un pulm\u00f3n de la ciudad, un parque urbano que da tranquilidad a las personas en una de las ciudades m\u00e1s bulliciosas del mundo. <strong>Pero ahora se pretende que sea m\u00e1s profundo y que se rescate su belleza natural.<\/strong><!--more--><\/p>\n<p>Los dise\u00f1adores que han planteado una innovadora idea son Titan Sun y Wu Jianshi. Pretenden que el Central Park se hunda hasta la roca madre del parque. Quieren crear una estructura de 300 metros de altura, con una profundidad de 30 metros, y una superficie total de 11 kil\u00f3metros, que es <strong>80 veces mayor al Empire State Building<\/strong>.<\/p>\n<p>\u201cLa ambici\u00f3n es revertir la relaci\u00f3n tradicional entre el paisaje y la arquitectura, de modo que cada espacio est\u00e9 conectado directamente con la naturaleza\u201d, seg\u00fan expresaron los autores de la propuesta que fue galardonada como el primer lugar en la competencia anunal de rascacielos eVolo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62090\" src=\"http:\/\/www.planetacurioso.com\/wp-content\/uploads\/2016\/03\/central-park-nueva-york.jpg\" alt=\"central-park-nueva-york\" width=\"880\" height=\"567\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62091\" src=\"http:\/\/www.planetacurioso.com\/wp-content\/uploads\/2016\/03\/central-park-nueva-york-2.jpg\" alt=\"central-park-nueva-york-2\" width=\"880\" height=\"595\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62092\" src=\"http:\/\/www.planetacurioso.com\/wp-content\/uploads\/2016\/03\/central-park-nueva-york-3.jpg\" alt=\"central-park-nueva-york-3\" width=\"880\" height=\"621\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62093\" src=\"http:\/\/www.planetacurioso.com\/wp-content\/uploads\/2016\/03\/central-park-nueva-york-4.jpg\" alt=\"central-park-nueva-york-4\" width=\"880\" height=\"1932\" \/><\/p>\n<p><strong>La cubierta de cristal altamente reflejante en todos los lados, crear\u00e1n una ilusi\u00f3n de infinito, dando un nuevo horizonte a Nueva York.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El famoso Central Park de Nueva York es un pulm\u00f3n de la ciudad, un parque urbano que da tranquilidad a las personas en una de las ciudades m\u00e1s bulliciosas del mundo. Pero ahora se pretende que sea m\u00e1s profundo y que se rescate su belleza natural.<\/p>\n","protected":false},"author":9,"featured_media":54667,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-54665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=54665"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54665\/revisions"}],"predecessor-version":[{"id":54668,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54665\/revisions\/54668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/54667"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=54665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=54665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=54665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}