{"id":54681,"date":"2016-04-13T09:52:25","date_gmt":"2016-04-13T13:52:25","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=54681"},"modified":"2016-04-13T09:52:25","modified_gmt":"2016-04-13T13:52:25","slug":"la-chilindrina-anuncio-su-retiro-de-los-escenarios","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-chilindrina-anuncio-su-retiro-de-los-escenarios\/","title":{"rendered":"\u00abLa Chilindrina\u00bb anunci\u00f3 su retiro de los escenarios"},"content":{"rendered":"<p>La actriz mexicana Mar\u00eda Antonieta de las Nieves anunci\u00f3 que su personaje <strong>\u2018La Chilindrina\u2019<\/strong> se retirar\u00e1 de los escenarios.<!--more--><\/p>\n<p>\u201cMe voy, se acaba <strong>\u2018La Chilindrina\u2019<\/strong>. Imag\u00ednate lo que es para toda Latinoam\u00e9rica, va a ser un golpe duro, eso s\u00ed es noticia\u201d, dijo la actriz al diario El Universal.<\/p>\n<p>De otro lado, <strong>\u2018La Chilindrina\u2019<\/strong> se refiri\u00f3 a Florida Meza, quien hab\u00eda declarado que <strong>Ram\u00f3n Vald\u00e9s<\/strong> consum\u00eda drogas.<\/p>\n<p>\u201cEs algo muy feo lo que est\u00e1n tratando de hacer, es borrar una imagen tan bonita\u2026 Solamente uno sabe de esas cosas (si consum\u00eda drogas) cuando uno se junta con los dem\u00e1s a hacer lo mismo, entonces, si ella se junt\u00f3 con Ram\u00f3n para hacer eso, es la \u00fanica que puede decirlo, porque ninguno de nosotros lo supimos, a pesar que vivimos con \u00e9l las 24 horas del d\u00eda durante 24 a\u00f1os y jam\u00e1s nos dimos cuenta\u201d, manifest\u00f3.<\/p>\n<p>Con respecto a una posible reuni\u00f3n que propiciar\u00eda Florinda Meza con los actores que integraron la serie <em>El Chavo del 8<\/em>, Mar\u00eda Antonieta de las Nieves asegur\u00f3 que ve imposible ese reencuentro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-54682 size-full\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/chilindrina.jpg\" alt=\"chilindrina\" width=\"620\" height=\"347\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/chilindrina.jpg 620w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/chilindrina-300x168.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>\u201cUna cosa es lo que ella quiera y otra es lo que queramos los dem\u00e1s, y lo que podamos hacer los dem\u00e1s, entonces, por mi parte lo veo muy dif\u00edcil\u201d, concluy\u00f3.<\/p>\n<p>Fuente: Peru21.pe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actriz mexicana Mar\u00eda Antonieta de las Nieves anunci\u00f3 que su personaje \u2018La Chilindrina\u2019 se retirar\u00e1 de los escenarios.<\/p>\n","protected":false},"author":9,"featured_media":54682,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-54681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=54681"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54681\/revisions"}],"predecessor-version":[{"id":54684,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54681\/revisions\/54684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/54682"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=54681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=54681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=54681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}