{"id":54775,"date":"2016-04-16T10:05:28","date_gmt":"2016-04-16T14:05:28","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=54775"},"modified":"2016-04-16T10:05:28","modified_gmt":"2016-04-16T14:05:28","slug":"bartolo-colon-consigue-victoria-219-de-su-carrera-y-empata-con-pedro-martinez","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/bartolo-colon-consigue-victoria-219-de-su-carrera-y-empata-con-pedro-martinez\/","title":{"rendered":"Bartolo Col\u00f3n consigue victoria 219 de su carrera y empata con Pedro Mart\u00ednez"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-54781 size-full aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/AB2C3E19-F87C-4EA6-9135-41CA7614C562.jpg__778__440__CROPz3x778y440.jpg\" alt=\"AB2C3E19-F87C-4EA6-9135-41CA7614C562.jpg__778__440__CROPz3x778y440\" width=\"778\" height=\"440\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/AB2C3E19-F87C-4EA6-9135-41CA7614C562.jpg__778__440__CROPz3x778y440.jpg 778w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/AB2C3E19-F87C-4EA6-9135-41CA7614C562.jpg__778__440__CROPz3x778y440-300x170.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/AB2C3E19-F87C-4EA6-9135-41CA7614C562.jpg__778__440__CROPz3x778y440-768x434.jpg 768w\" sizes=\"auto, (max-width: 778px) 100vw, 778px\" \/>Cleveland.- \u00a0El dominicano Bartolo Col\u00f3n lanz\u00f3 pelota de dos carreras, permiti\u00f3 ocho imparables, abanic\u00f3 a cinco contrarios en 5.1 entradas, para anotarse su primera victoria de la temporada y la 219 de su carrera, empatando con su compatriota Pedro Mart\u00ednez, en triunfo 6-5 de los Mets de Nueva York ante los Indios de Cleveland.<!--more--><\/p>\n<p>Con esta haza\u00f1a Col\u00f3n (1-1) se coloc\u00f3 junto a Mart\u00ednez en el lugar n\u00famero cuatro entre los lanzadores latinos con 200 o m\u00e1s victorias en las Grandes Ligas.<\/p><\/div>\n<div>\nLos cinco lanzadores latinos con 200 o m\u00e1s juegos ganados son: Dennis Mart\u00ednez, Nicaragua, 245; Juan Marichal, Dominicana, 243; Luis Tiant, Cuba, 229; Pedro Mart\u00ednez, Dominicana, 219 Col\u00f3n Dominicana, 219.<\/div>\n<div>\nEn su primera salida el s\u00e1bado, 9 de abril, Col\u00f3n limit\u00f3 a los Phillies de Philadelphia a una sola carrera en seis entradas, pero la ofensiva de los Mets no logr\u00f3 remontar el 1-0.<\/div>\n<div>\nEsta vez la ofensiva si respaldo a Bartolo, Michael Conforto peg\u00f3 un jonr\u00f3n solitario en la primera entrada. \u00a0Luego en el quinto episodio el dominicano Alejandro De Aza, Yoenis C\u00e9spedes y Neil Walker tambi\u00e9n la sacaron del parque.<\/div>\n<div>\nEl nativo de Altamira, que con 43 a\u00f1os, es el jugador m\u00e1s viejo en la actualidad en las Mayores, jug\u00f3 sus primeras seis temporadas en Grandes Ligas precisamente con los indios de Cleveland Cleveland (1997 a 2002), donde acumul\u00f3 una marca de 75-45 con ERA de 3.95 en 169 aperturas.<\/div>\n<div>El salvamento fue para Jeurys Familia, su n\u00famero tres de la temporada<\/div>\n<div>\nWILLY MATOS MEDINA<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cleveland.- \u00a0El dominicano Bartolo Col\u00f3n lanz\u00f3 pelota de dos carreras, permiti\u00f3 ocho imparables, abanic\u00f3 a cinco contrarios en 5.1 entradas, para anotarse su primera victoria de la temporada y la 219 de su carrera, empatando con su compatriota Pedro Mart\u00ednez, en triunfo 6-5 de los Mets de Nueva York ante los Indios de Cleveland.<\/p>\n","protected":false},"author":9,"featured_media":54781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-54775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=54775"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54775\/revisions"}],"predecessor-version":[{"id":54782,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54775\/revisions\/54782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/54781"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=54775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=54775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=54775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}