{"id":54849,"date":"2016-04-19T19:21:43","date_gmt":"2016-04-19T23:21:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=54849"},"modified":"2016-04-19T19:21:43","modified_gmt":"2016-04-19T23:21:43","slug":"alertan-de-un-falso-servicio-de-videollamadas-para-whatsapp","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/alertan-de-un-falso-servicio-de-videollamadas-para-whatsapp\/","title":{"rendered":"Alertan de un falso servicio de videollamadas para Whatsapp"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/n_WHATSAPP_570.jpg\" rel=\"attachment wp-att-54850\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54850 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/n_WHATSAPP_570.jpg\" alt=\"n_WHATSAPP_570\" width=\"230\" height=\"240\" \/><\/a>La Oficina de Seguridad del Internauta ha alertado de la propagaci\u00f3n a trav\u00e9s de Whatsapp de un servicio de videollamadas fraudulento. Los mensajes de esta nueva campa\u00f1a ofrecen a los usuarios activar videollamadas para el sistema de mensajer\u00eda instant\u00e1nea, pero en realidad se trata de una promoci\u00f3n fraudulenta que se propaga a trav\u00e9s de los tel\u00e9fonos m\u00f3viles<!--more--> \u2014no es posible acceder a las mismas desde un ordenador\u2014 con mensajes que contienen un enlace que dirige a una web (wsx.xo) que trata de suplantar la identidad de Whatsapp.<\/p>\n<p>Una vez en la web, si el usuario pincha en \u201cActivar Videollamadas ahora\u201d, aparecer\u00e1n pantallas que simular\u00e1n estar \u201cverificando la versi\u00f3n de WhatsApp\u201d del usuario o generando alg\u00fan tipo de falsas actualizaciones, tal y como informa la OSI. Despu\u00e9s se muestra la pantalla de verificaci\u00f3n del usuario y se le pide que comparta la informaci\u00f3n de activaci\u00f3n de videollamadas y el enlace a la web con otros usuarios, para as\u00ed propagar el mensaje fraudulento (si no se propaga a otros usuarios, no permite seguir).<\/p>\n<p>Una vez compartido el mensaje con contactos o grupos de WhatsApp del usuario, si se hace clic en \u201cDescargar Videollamadas\u201d, el sistema informar\u00e1 al usuario de que su tel\u00e9fono est\u00e1 desactualizado y le solicitar\u00e1 que lo actualice. Al pulsar \u201cActualizar Ahora\u201d, el usuario ser\u00e1 enviado a una web donde se le pedir\u00e1 que introduzca su n\u00famero de tel\u00e9fono y su operadora de telefon\u00eda. Si se pulsa \u201cenviar\u201d se intentar\u00e1 subscribir al usuario a un servicio SMS Premium.<\/p>\n<p>A aquellos que hayan sido v\u00edctimas de este enga\u00f1o, la Oficina de Seguridad del Internauta les recomienda permanecer atentos y monitorizar peri\u00f3dicamente la informaci\u00f3n que hay publicada sobre ellos en Internet para evitar que sus datos privados est\u00e9n siendo utilizados sin su consentimiento. Si se descubre algo sospechoso, el afectado puede reivindicar sus derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n u oposici\u00f3n (ARCO) al tratamiento de sus datos personales. La Agencia Espa\u00f1ola de Protecci\u00f3n de Datos proporciona las pautas para que los pueda ejercer.<\/p>\n<p>Si adem\u00e1s se ha facilitado el n\u00famero de tel\u00e9fono m\u00f3vil tras compartir la falsa campa\u00f1a, lo recomendable es contactar con la operadora de telefon\u00eda m\u00f3vil para que bloquee los n\u00fameros SMS Premium.<\/p>\n<p>Para evitar este tipo de fraudes, la oficina recomienda no introducir datos personales ni el n\u00famero de tel\u00e9fono m\u00f3vil en promociones online de las que no se est\u00e9 seguro de su legitimidad. Adicionalmente, se recomienda prestar especial atenci\u00f3n, y evitar en la medida de lo posible, participar en cualquier tipo de promoci\u00f3n o campa\u00f1a de marketing online donde se pida al usuario compartir la promoci\u00f3n en redes sociales o aplicaciones de mensajer\u00eda instant\u00e1nea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Oficina de Seguridad del Internauta ha alertado de la propagaci\u00f3n a trav\u00e9s de Whatsapp de un servicio de videollamadas fraudulento. Los mensajes de esta nueva campa\u00f1a ofrecen a los usuarios activar videollamadas para el sistema de mensajer\u00eda instant\u00e1nea, pero en realidad se trata de una promoci\u00f3n fraudulenta que se propaga a trav\u00e9s de los tel\u00e9fonos m\u00f3viles<\/p>\n","protected":false},"author":12,"featured_media":54850,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-54849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=54849"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54849\/revisions"}],"predecessor-version":[{"id":54851,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54849\/revisions\/54851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/54850"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=54849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=54849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=54849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}