{"id":54893,"date":"2016-04-22T07:23:34","date_gmt":"2016-04-22T11:23:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=54893"},"modified":"2016-04-22T07:23:34","modified_gmt":"2016-04-22T11:23:34","slug":"adios-a-prince-genio-de-la-musica-e-icono-del-pop","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/adios-a-prince-genio-de-la-musica-e-icono-del-pop\/","title":{"rendered":"Adi\u00f3s a Prince, genio de la m\u00fasica e icono del pop"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/prince.jpeg\" rel=\"attachment wp-att-54894\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-54894\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/prince.jpeg\" alt=\"prince\" width=\"521\" height=\"540\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/prince.jpeg 521w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/04\/prince-289x300.jpeg 289w\" sizes=\"auto, (max-width: 521px) 100vw, 521px\" \/><\/a>El cantante estadounidense Prince, genio de la m\u00fasica e icono del pop, falleci\u00f3 este jueves a los 57 a\u00f1os, dejando hu\u00e9rfanas a miles de personas que crecieron bailando sus m\u00edticos temas como \u00abPurple Rain\u00bb, \u00abGirls &amp; Boys\u00bb o \u00abKiss\u00bb.<!--more--><\/p>\n<p>\u00abCon profunda tristeza confirmo que el legendario e ic\u00f3nico artista Prince Rogers Nelson falleci\u00f3 en su residencia de Paisley Park (Minneapolis, noreste) esta ma\u00f1ana\u00bb, se\u00f1al\u00f3 su publicista Yvette Noel-Schure en un comunicado enviado a la AFP.<\/p>\n<p>La web especializada en celebridades TMZ, que dio la noticia de su muerte en exclusiva, asegur\u00f3 que el artista fue tratado de una sobredosis seis d\u00edas antes de morir.<\/p>\n<p>Ese d\u00eda, el viernes 15 de abril, el avi\u00f3n privado de Prince tuvo que hacer un aterrizaje de emergencia porque la fuerte gripe que sufr\u00eda desde hac\u00eda semanas se agrav\u00f3 en pleno vuelo, seg\u00fan dijeron sus representantes.<\/p>\n<p>El cantante acababa de dar un concierto en Atlanta (Georgia, sureste) y se dirig\u00eda a su casa en Minneapolis (Minnesota, noreste).<\/p>\n<p>TMZ dijo, citando a varias fuentes an\u00f3nimas, que Prince recibi\u00f3 \u00abuna inyecci\u00f3n\u00bb para contrarrestar los efectos de las drogas.<\/p>\n<p>Los m\u00e9dicos aconsejaron al cantante quedarse ingresado al menos 24 horas, pero el artista decidi\u00f3 firmar el alta voluntaria tres horas despu\u00e9s cuando supo que no podr\u00eda quedarse en una habitaci\u00f3n privada.<\/p>\n<p>Prince \u00abfue encontrado inconsciente en un ascensor\u00bb de los estudios Paisley Park en Chanhassen, su residencia situada cerca de la ciudad de Minneapolis, de acuerdo a la oficina del sheriff del condado de Carver.<\/p>\n<p>El cuerpo sin vida del artista ya est\u00e1 en el instituto forense y \u00abma\u00f1ana (viernes) comenzar\u00e1 la autopsia\u00bb, dijo a la AFP la portavoz Martha Weaver.<\/p>\n<p>Los resultados preliminares podr\u00edan obtenerse en unos d\u00edas, pero las pruebas toxicol\u00f3gicas llevar\u00e1n varias semanas, subray\u00f3.<\/p>\n<p>Prince quiso demostrar que se encontraba bien de salud organizando el s\u00e1bado un concierto a diez d\u00f3lares la entrada para sus fans en Paisley Park, seg\u00fan el diario local Star Tribune.<\/p>\n<p>&#8211; \u00abNecesito amor y agua\u00bb &#8211;<\/p>\n<p>El cantante se convirti\u00f3 en un referente del pop en la d\u00e9cada de 1980 gracias a discos como \u00abPurple Rain\u00bb, considerado uno de los mejores \u00e1lbumes de todos los tiempos seg\u00fan los expertos.<\/p>\n<p>Prince era un virtuoso de la m\u00fasica y tocaba decenas de instrumentos, con los que siempre deleit\u00f3 a sus fans sobre las tablas.<\/p>\n<p>La pasi\u00f3n que sent\u00eda por su profesi\u00f3n fue posiblemente la mejor herencia que recibi\u00f3 de sus padres, ambos amantes del jazz.<\/p>\n<p>En sus inicios prefiri\u00f3 no cantar porque pensaba que su voz no ten\u00eda la calidad suficiente para gustar al p\u00fablico. Pero varias personas lo animaron a tomar el micr\u00f3fono, convencidos de que su timbre encandilar\u00eda a m\u00e1s de uno.<\/p>\n<p>La industria se pele\u00f3 por \u00e9l, entusiasmada por su talento, pero finalmente firm\u00f3 su primer contrato con Warner Brothers. Hizo maletas, se mud\u00f3 a California y en 1978 grab\u00f3 \u00abFor You\u00bb, en el que adem\u00e1s toc\u00f3 todos los instrumentos.<\/p>\n<p>Al final el \u00abKid de Minneapolis\u00bb -como cari\u00f1osamente se le conoc\u00eda- termin\u00f3 convirti\u00e9ndose en uno de los grandes m\u00fasicos de la d\u00e9cada de 1980, cuyo poder e influencia fueron comparados muchas veces a los de Michael Jackson, otro grande muerto en 2009 a los 50 a\u00f1os.<\/p>\n<p>Public\u00f3 39 discos, vendi\u00f3 m\u00e1s de 100 millones de copias y gan\u00f3 siete premios Grammy.<\/p>\n<p>Su 1,60m de estatura no le impidi\u00f3 tener una gran personalidad, con la que marc\u00f3 tendencia dentro y fuera del escenario.<\/p>\n<p>Fiel a su estilo dandy y a su aspecto andr\u00f3gino, Prince regal\u00f3 algunas de las mejores melod\u00edas funk de la historia, acompa\u00f1adas por letras que rozaban poes\u00eda.<\/p>\n<p>En la d\u00e9cada de 1990 se cambi\u00f3 su nombre por el del \u00abs\u00edmbolo del amor\u00bb y llev\u00f3 escrita la palabra \u00abslave\u00bb -esclavo- en una de sus mejillas como se\u00f1al de protesta contra Warner cuando intentaba independizarse.<\/p>\n<p>Inconformista y rebelde, siempre dio qu\u00e9 hablar por su forma de vivir la vida.<\/p>\n<p>\u00abNo vivo en una prisi\u00f3n. No tengo miedo de nada\u00bb, dijo en una de sus pocas entrevistas concedidas en 1986 al canal MTV.<\/p>\n<p>\u00abNo he construido ning\u00fan muro a mi alrededor. Soy como cualquier otro. Necesito amor y agua, y no tengo miedo de una respuesta negativa porque, como digo, hay gente que apoyar\u00e1 mis costumbres como he apoyado las de ellos\u00bb.<\/p>\n<p>Hace apenas un mes anunci\u00f3 durante uno de sus conciertos que sus memorias -tituladas \u00abThe Beautiful Ones\u00bb en honor a \u00abPurple Rain\u00bb- ver\u00edan la luz en 2017.<\/p>\n<p>&#8211; \u00abNo conoc\u00ed a Mozart, pero conoc\u00eda a Prince\u00bb &#8211;<\/p>\n<p>El mundo entero se estremeci\u00f3 con la noticia de su muerte e inund\u00f3 las redes sociales de mensajes de amor y agradecimiento.<\/p>\n<p>Su exesposa Mayte Garc\u00eda, una bailarina de origen puertorrique\u00f1o con la que estuvo casado entre 1996 y 1998, dijo incr\u00e9dula que Prince \u00ablo era todo\u00bb para ella.<\/p>\n<p>\u00abAhora est\u00e1 con nuestro hijo\u00bb, asegur\u00f3. La pareja tuvo un hijo hace justo 10 a\u00f1os, que muri\u00f3 al poco de nacer.<\/p>\n<p>El presidente estadounidense, Barack Obama, record\u00f3 al artista como un \u00abicono creativo\u00bb y un \u00abartista electrizante\u00bb que conquist\u00f3 a millones de seguidores en el mundo.<\/p>\n<p>Bono, el vocalista de U2, le dedic\u00f3 unas sentidas palabras: \u00abNunca conoc\u00ed a Mozart, nunca conoc\u00ed a Duke Ellington o a Charlie Parker, nunca conoc\u00ed a Elvis pero conoc\u00ed a Prince\u00bb.<\/p>\n<p>El l\u00edder de The Rolling Stones, Mick Jagger, dijo que su talento \u00abno ten\u00eda l\u00edmites\u00bb y Madonna, totalmente devastada, alab\u00f3 el car\u00e1cter \u00abvisionario\u00bb de Prince. \u00abCambi\u00f3 el mundo\u00bb, se\u00f1al\u00f3.<\/p>\n<p>El rapero Will Smith no sal\u00eda de la sorpresa: \u00abAnoche habl\u00e9 con \u00e9l\u00bb, escribi\u00f3 en Facebook.<\/p>\n<p>El mundo del cine, que dio a Prince un \u00d3scar en 1985 por \u00abPurple Rain\u00bb, tambi\u00e9n expres\u00f3 su dolor.<\/p>\n<p>El director Spike Lee, los actores Samuel L. Jackson y Elijah Wood y las artistas Whoopi Goldberg, Michelle Williams, Ellen DeGeneres y Alyssa Milano le rindieron homenaje en las redes sociales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cantante estadounidense Prince, genio de la m\u00fasica e icono del pop, falleci\u00f3 este jueves a los 57 a\u00f1os, dejando hu\u00e9rfanas a miles de personas que crecieron bailando sus m\u00edticos temas como \u00abPurple Rain\u00bb, \u00abGirls &amp; Boys\u00bb o \u00abKiss\u00bb.<\/p>\n","protected":false},"author":12,"featured_media":54894,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-54893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=54893"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54893\/revisions"}],"predecessor-version":[{"id":54895,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/54893\/revisions\/54895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/54894"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=54893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=54893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=54893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}