{"id":55176,"date":"2016-05-04T06:47:46","date_gmt":"2016-05-04T10:47:46","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=55176"},"modified":"2016-05-04T06:47:46","modified_gmt":"2016-05-04T10:47:46","slug":"descubren-el-gen-de-la-juventud","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/descubren-el-gen-de-la-juventud\/","title":{"rendered":"Descubren el gen de la juventud"},"content":{"rendered":"<div id=\"super-carousel\" class=\"clearfix\"><\/div>\n<div class=\"article-wrapper\">\n<div class=\"article-main-area\">\n<div class=\"article-top title-on-top\">\n<div id=\"galleria\">\n<div class=\"galleria-container notouch\">\n<div class=\"galleria-stage\">\n<div class=\"galleria-info-wrapper\"><\/div>\n<div class=\"galleria-images\">\n<div class=\"galleria-image\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/gen-de-la-juventud.jpeg\" rel=\"attachment wp-att-55177\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-55177\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/gen-de-la-juventud.jpeg\" alt=\"gen-de-la-juventud\" width=\"858\" height=\"540\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/gen-de-la-juventud.jpeg 858w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/gen-de-la-juventud-300x189.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/gen-de-la-juventud-768x483.jpeg 768w\" sizes=\"auto, (max-width: 858px) 100vw, 858px\" \/><\/a><br \/>\nInvestigadores de <b>Unilever<\/b> han hecho un descubrimiento muy interesante que revela la primera <b>evidencia gen\u00e9tica<\/b> que explica la diferencia entre la <b>edad<\/b> que se tiene y la que se refleja.<!--more--><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"article-main-wrapper\">\n<div class=\"article-left-wrapper title-on-top\">\n<div class=\"article-full-width\">\n<div class=\"body-area has-related\">\n<div class=\"article-body\">\n<p>Estos cient\u00edficos han descubierto el <b>gen<\/b> de la <b>apariencia juvenil<\/b>, lo<b>\u00a0<\/b>permite saber por qu\u00e9 algunas personas lucen m\u00e1s j\u00f3venes que otras, aunque tengan la misma edad.<\/p>\n<\/div>\n<div class=\"article-box-fact-para\">\n<div class=\"article-box-fact-inline\">\n<div class=\"article-box-fact-inline column\">\n<div class=\"body small\">\n<p>\u00abEsta investigaci\u00f3n es tremendamente emocionante y abre una nueva comprensi\u00f3n del por qu\u00e9 algunas personas mantienen una apariencia m\u00e1s joven a medida que envejecen\u00bb, afirma el <b>David Gunn<\/b>, cient\u00edfico l\u00edder del estudio.<\/p>\n<p>\u00abAl aprender los \u2018secretos\u2019 de los que se ven m\u00e1s j\u00f3venes para su edad, podemos encontrar formas innovadoras para ayudar a todos a mantener un aspecto m\u00e1s joven durante m\u00e1s tiempo\u00bb, concluye.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"article-body\">\n<p>Este estudio es el primero de su tipo y descubri\u00f3 que hay personas portadoras de un gen llamado <b>MC1R<\/b>, lo que las hace verse dos a\u00f1os mayores en comparaci\u00f3n a aquellos con tipos diferentes.<\/p>\n<p>Para realizar las pruebas se examinaron m\u00e1s de 8 millones de variantes de ADN para investigar si las personas que lucen m\u00e1s j\u00f3venes, en funci\u00f3n de su edad, presentan variantes diferentes en comparaci\u00f3n a los que parecen mayores a su edad real. \u00bfQu\u00e9 te parece?<\/p>\n<p>Para m\u00e1s informaci\u00f3n visita la <a href=\"https:\/\/www.unilever.com\/news\/press-releases\/2016\/Anti-ageing-breakthrough-scientists-discover-a-gene-of-youthful-looks.html\" target=\"_blank\">p\u00e1gina web<\/a> de la marca.<\/p>\n<\/div>\n<div class=\"article-body\">\n<div class=\"image-component inline-large\"><img decoding=\"async\" src=\"http:\/\/www.publinews.gt\/_internal\/gxml!0\/r0dc21o2f3vste5s7ezej9x3a10rp3w$26fdj7756jebltrm9c5a7yyaezd3bja\/Captura-de-pantalla-2016-05-03-a-las-13.jpeg\" alt=\"\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Investigadores de Unilever han hecho un descubrimiento muy interesante que revela la primera evidencia gen\u00e9tica que explica la diferencia entre la edad que se tiene y la que se refleja.<\/p>\n","protected":false},"author":12,"featured_media":55177,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-55176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=55176"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55176\/revisions"}],"predecessor-version":[{"id":55178,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55176\/revisions\/55178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/55177"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=55176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=55176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=55176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}