{"id":55205,"date":"2016-05-05T08:54:12","date_gmt":"2016-05-05T12:54:12","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=55205"},"modified":"2016-05-05T08:54:12","modified_gmt":"2016-05-05T12:54:12","slug":"el-ojo-bionico-y-virus-transgenicos-nuevas-soluciones-contra-la-ceguera","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-ojo-bionico-y-virus-transgenicos-nuevas-soluciones-contra-la-ceguera\/","title":{"rendered":"El ojo bi\u00f3nico y virus transg\u00e9nicos, nuevas soluciones contra la ceguera"},"content":{"rendered":"<p class=\"access\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/ojo-bionico.jpg\" rel=\"attachment wp-att-55208\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-55208 size-full alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/ojo-bionico.jpg\" alt=\"ojo bionico\" width=\"213\" height=\"143\" \/><\/a>Varios grupos de investigaci\u00f3n trabajan en soluciones para recuperar algo de capacidad visual cuando esta se pierde debido a la degeneraci\u00f3n de la retina. Se est\u00e1n siguiendo dos estrategias fundamentales en este sentido: el ojo bi\u00f3nico y el desarrollo de virus transg\u00e9nicos que aporten a la retina la fotosensibilidad perdida. Por Javier Molina.<!--more--><\/p>\n<div id=\"para_1\" class=\"para_15095111 resize\">\n<div class=\"texte\">\n<div class=\"access firstletter\">Diversas causas pueden provocar la ceguera. Una de las m\u00e1s comunes es la\u00a0retinosis pigmentaria, una enfermedad que engloba dolencias que llevan a la progresiva desaparici\u00f3n de las c\u00e9lulas fotosensibles de la retina.<\/p>\n<p>Estas c\u00e9lulas son las encargadas de captar la luz para transformarla en impulsos el\u00e9ctricos que se transmiten al cerebro mediante el nervio \u00f3ptico. El cerebro es despu\u00e9s el encargado de interpretar esa ingente cantidad de informaci\u00f3n para hacernos entender lo que ocurre a nuestro alrededor.<\/p>\n<p>Los tratamientos de \u00faltima generaci\u00f3n se centran en estos casos, en los que el problema se focaliza en la retina, concretamente en las c\u00e9lulas encargadas de convertir la luz en mensajes para el cerebro: los conos y los bastones.<\/p>\n<p>Actualmente existen, fundamentalmente, dos estrategias para intentar solucionar el problema de la retinosis pigmentaria. Los resultados, por ahora solo probados en unas pocas personas, son modestos, pero a la vez prometedores y de gran utilidad para aquellos pacientes que pasan de no ver casi nada a ser capaces de percibir visualmente la presencia de una persona o una l\u00ednea blanca en el suelo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"center\">\n<div id=\"video_15106087_5314779\" class=\"center\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/YGRIRUWgUiQ\" width=\"560\" height=\"379\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Varios grupos de investigaci\u00f3n trabajan en soluciones para recuperar algo de capacidad visual cuando esta se pierde debido a la degeneraci\u00f3n de la retina. Se est\u00e1n siguiendo dos estrategias fundamentales en este sentido: el ojo bi\u00f3nico y el desarrollo de virus transg\u00e9nicos que aporten a la retina la fotosensibilidad perdida. Por Javier Molina.<\/p>\n","protected":false},"author":12,"featured_media":55208,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-55205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=55205"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55205\/revisions"}],"predecessor-version":[{"id":55209,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55205\/revisions\/55209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/55208"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=55205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=55205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=55205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}