{"id":55242,"date":"2016-05-06T18:11:57","date_gmt":"2016-05-06T22:11:57","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=55242"},"modified":"2016-05-06T18:11:57","modified_gmt":"2016-05-06T22:11:57","slug":"jack-veneno-y-juanchy-sanchez-seran-reconocidos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/jack-veneno-y-juanchy-sanchez-seran-reconocidos\/","title":{"rendered":"Jack Veneno y Juanchy S\u00e1nchez ser\u00e1n reconocidos"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/jackk.jpg\" rel=\"attachment wp-att-55243\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-55243\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/jackk.jpg\" alt=\"jackk\" width=\"281\" height=\"350\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/jackk.jpg 281w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/jackk-241x300.jpg 241w\" sizes=\"auto, (max-width: 281px) 100vw, 281px\" \/><\/a>SANTO DOMINGO.-<\/strong> El ex luchador profesional Rafael S\u00e1nchez, mejor conocido como \u2018Jack Veneno\u2019, otro \u00eddolo de generaciones, junto al empresario y deportista santiagu\u00e9s Juanchy S\u00e1nchez, ser\u00e1n objetos de sendos reconocimientos durante la Gala \u2018Cronista del A\u00f1o de la ACD, galard\u00f3n que otorga la Asociaci\u00f3n de Cronistas Deportivos de Santo Domingo.<!--more--><\/p>\n<p>La ceremonia de premiaci\u00f3n est\u00e1 pautada para el 22 de mayo a partir del medio d\u00eda en uno de los salones del hotel Lina, con el respaldo de Cervecer\u00eda Nacional Dominicana, Claro Y Logomarca.<\/p>\n<p>El legendario luchador Jack Veneno fue por d\u00e9cadas uno de los grandes \u00eddolos del deporte nacional, al extremo de llegar a ser idolatrado por ni\u00f1os, j\u00f3venes, adolescentes y adultos, quienes segu\u00edan sus actuaciones en la lucha libre local.<\/p>\n<p>De su lado, Juanchy S\u00e1nchez, es conocido por su gran vinculaci\u00f3n como directivo de las \u00c1guilas Cibae\u00f1as en la pelota oto\u00f1o-invernal dominicana, adem\u00e1s de ser la cabeza principal de la empresa Comercializadora Deportiva Dominicana.<\/p>\n<p>El periodista Ram\u00f3n Cuello, presidente de la ACD, destac\u00f3 las cualidades de ambas figuras y dijo que para la instituci\u00f3n que preside constituye un gran honor \u201creconocer a estos dos grandes hombres del deporte nacional\u201d.<\/p>\n<p>La Gala \u2018Cronista del A\u00f1o de la ACD\u2019 reconoce y premia cada a\u00f1o el trabajo que realizan los cronistas deportivos de Santo Domingo, en sus respectivos medios de comunicaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El ex luchador profesional Rafael S\u00e1nchez, mejor conocido como \u2018Jack Veneno\u2019, otro \u00eddolo de generaciones, junto al empresario y deportista santiagu\u00e9s Juanchy S\u00e1nchez, ser\u00e1n objetos de sendos reconocimientos durante la Gala \u2018Cronista del A\u00f1o de la ACD, galard\u00f3n que otorga la Asociaci\u00f3n de Cronistas Deportivos de Santo Domingo.<\/p>\n","protected":false},"author":12,"featured_media":55243,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,4],"tags":[],"class_list":["post-55242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=55242"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55242\/revisions"}],"predecessor-version":[{"id":55244,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55242\/revisions\/55244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/55243"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=55242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=55242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=55242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}