{"id":55249,"date":"2016-05-07T09:31:09","date_gmt":"2016-05-07T13:31:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=55249"},"modified":"2016-05-07T09:31:09","modified_gmt":"2016-05-07T13:31:09","slug":"con-31-puntos-de-kawhi-leonard-spurs-vencen-al-thunder","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/con-31-puntos-de-kawhi-leonard-spurs-vencen-al-thunder\/","title":{"rendered":"Con 31 puntos de Kawhi Leonard, Spurs vencen al Thunder"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/leonard.jpg\" rel=\"attachment wp-att-55250\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-55250 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/leonard.jpg\" alt=\"leonard\" width=\"259\" height=\"195\" \/><\/a>OKLAHOMA CITY. Esta vez, los Spurs de San Antonio consiguieron las artima\u00f1as que necesitaban para vencer al Thunder.<!--more--><\/p>\n<p>Un rebote ofensivo clave de Kawhi Leonard tras un fallo de LaMarcus Aldridge llev\u00f3 a dos tiros libres de Tony Parker a 18 segundos para el final que pusieron a los Spurs cuatro arriba en el marcador, y San Antonio aguant\u00f3 para ganar 100-96 el viernes y ponerse 2-1 en su serie de semifinales de la Conferencia Oeste.<\/p>\n<p>Leonard sum\u00f3 31 puntos y 11 rebotes, pero su rebote al final fue su jugada m\u00e1s importante de la noche. En su habitual estilo modesto, el jugador hizo como si no fuera gran cosa.<\/p>\n<p>\u201cS\u00f3lo ataqu\u00e9 y salt\u00e9 y lo agarr\u00e9\u201d, dijo tras el partido.<\/p>\n<p>Puede que eso suene sencillo, pero no fue as\u00ed en el anterior juego de los Spurs. En su derrota del lunes en casa, San Antonio no consigui\u00f3 un bal\u00f3n en una refriega bajo la canasta en los \u00faltimos segundos, y el Thunder se hizo con una victoria 98-97. El viernes, el rebote de Leonard ayud\u00f3 a lograr la victoria.<\/p>\n<p>\u201cFue agotador\u201d, dijo el alero del Thunder Kevin Durant. \u201cJugamos con una buena defensa y est\u00e1bamos siete abajo con un minuto para el final, y lo redujimos a dos. Hicimos que (Aldridge) fallara la canasta, y el bal\u00f3n como que cay\u00f3 en sus manos (de Leonard). Estaba en una posici\u00f3n genial para atrapar el rebote, y eso es un fastidio\u201d.<\/p>\n<p>Aldridge aport\u00f3 24 puntos y ocho rebotes y Tony Parker sum\u00f3 19 puntos y ocho rebotes para los Spurs, que recuperaron la ventaja de jugar en casa tras perder en el Juego 2.<\/p>\n<p>Russel Westbrook anot\u00f3 31 puntos para el Thunder, pero s\u00f3lo encest\u00f3 10 de 31 lanzamientos. Tambi\u00e9n atrap\u00f3 9 rebotes y ofreci\u00f3 ocho asistencias. Kevin Durant anot\u00f3 26 puntos, el congole\u00f1o nacionalizado espa\u00f1ol Serge Ibaka a\u00f1adi\u00f3 15 y Steven Adams atrap\u00f3 11 rebotes para Oklahoma City.<\/p>\n<p>El argentino Manu Gin\u00f3bili sum\u00f3 5 puntos y 3 asistencias para los Spurs.<\/p>\n<p>El Thunder s\u00f3lo acert\u00f3 un 41,5% de sus tiros de cancha.<\/p>\n<p>El Juego 4 se disputar\u00e1 el domingo en Oklahoma City.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OKLAHOMA CITY. Esta vez, los Spurs de San Antonio consiguieron las artima\u00f1as que necesitaban para vencer al Thunder.<\/p>\n","protected":false},"author":12,"featured_media":55250,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-55249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=55249"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55249\/revisions"}],"predecessor-version":[{"id":55251,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55249\/revisions\/55251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/55250"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=55249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=55249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=55249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}