{"id":55292,"date":"2016-05-08T09:03:52","date_gmt":"2016-05-08T13:03:52","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=55292"},"modified":"2016-05-08T09:03:52","modified_gmt":"2016-05-08T13:03:52","slug":"canelo-alvarez-noquea-a-amir-khan-en-6to-asalto","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/canelo-alvarez-noquea-a-amir-khan-en-6to-asalto\/","title":{"rendered":"Canelo \u00c1lvarez noquea a Amir Khan en 6to asalto"},"content":{"rendered":"<div class=\"text\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/canelo-manda-contrario-a-la-lona.jpg\" rel=\"attachment wp-att-55294\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-55294\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/canelo-manda-contrario-a-la-lona.jpg\" alt=\"canelo manda contrario a la lona\" width=\"693\" height=\"370\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/canelo-manda-contrario-a-la-lona.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/05\/canelo-manda-contrario-a-la-lona-300x160.jpg 300w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/a>LAS VEGAS. Sa\u00fal \u201cCanelo\u201d \u00c1lvarez s\u00f3lo necesit\u00f3 un gran derechazo para convertir una pelea ajustada en un nocaut demoledor.<!--more--><\/p>\n<p>Asediado por la velocidad de Amir Khan, \u00c1lvarez asest\u00f3 un largo derechazo que hizo caer a Khan de espaldas sobre la lona. El \u00e1rbitro Kenny Bayless ni siquiera se molest\u00f3 en contar los segundos del nocaut, a los 2:37 del sexto asalto.<\/p>\n<p>\u00c1lvarez conserv\u00f3 su cetro de peso mediano, pero no sin algunos momentos de nerviosismo para sus seguidores, que abarrotaron la nueva T-Mobile Arena en Las Vegas. Khan estaba haciendo algo m\u00e1s que defenderse en una pelea t\u00e1ctica, finiquitada de improviso con el derechazo.<\/p>\n<p>El mexicano acudi\u00f3 y arrodill\u00f3 ante el inconsciente Khan, y despu\u00e9s hizo un gesto a Gennady Golovkin, que estaba junto al cuadril\u00e1tero, para que subiera al ring a pelear.<\/p>\n<p>\u201cLe invit\u00e9 a venir al ring\u201d, dijo \u00c1lvarez. \u201cAhora mismo me volver\u00eda a poner los guantes\u201d.<\/p>\n<p>Puede que no falte mucho tiempo para la pelea que los aficionados est\u00e1n esperando, aunque el peso podr\u00eda ser una complicaci\u00f3n. \u00c1lvarez quiere que el combate est\u00e9 por debajo del l\u00edmite de peso mediano de 160 libras, mientras que Golovkin, que tiene su propio trozo de la diadema de la categor\u00eda, prefiere pelear en su mejor peso.<\/p>\n<p>\u201cSoy de la vieja escuela\u201d coment\u00f3 Golovkin justo antes de la pelea. \u201cEl peso mediano es 160. Yo respeto el deporte del boxeo\u201d.<\/p>\n<p>Khan, que ten\u00eda las apuestas en contra 6-1, hab\u00eda prometido utilizar su velocidad para hacer frente a \u00c1lvarez y su plan parec\u00eda estar funcionando. Pele\u00f3 en acelerones, con combinaciones y parec\u00eda que frustrando al mexicano con su movimiento.<\/p>\n<p>Pero un derechazo que sali\u00f3 de la nada impact\u00f3 en el ment\u00f3n de Khan, y estaba fuera de combate antes de golpear la lona.<\/p>\n<p>\u201cMe met\u00ed en el ring con un tipo grande\u201d, coment\u00f3 Khan. \u201cPor desgracia no llegu\u00e9 al final\u201d.<\/p>\n<p>\u00c1lvarez defend\u00eda por primera vez el t\u00edtulo de WBC que gan\u00f3 en noviembre a Miguel Cotto, aunque la pelea se libr\u00f3 con un peso l\u00edmite de 155 libras. La WBC ha dicho que le quitar\u00e1 el t\u00edtulo a \u00c1lvarez si no inicia las conversaciones para pelear con Golovkin en 15 d\u00edas.<\/p>\n<p>\u201cNo tengo miedo de nadie\u201d, afirm\u00f3 \u00c1lvarez. \u201cA este deporte no venimos a jugar\u201d.<\/p>\n<p>El nuevo estadio en Las Vegas se llen\u00f3 de seguidores de \u00c1lvarez, en el fin de semana de la Fiesta Nacional mexicana, en el que sol\u00eda pelear Floyd Mayweather Jr. Los asistentes llegaron esperando ver un espect\u00e1culo de \u00c1lvarez (47-1-1, 33 nocauts), aunque en los primeros asaltos tuvo problemas con la velocidad y el movimiento de Khan.<\/p>\n<p>\u00c1lvarez persigui\u00f3 a Khan (31-4) desde el primer asalto, intentando arrinconarle contra las cuerdas. No tuvo mucho \u00e9xito, y Khan respondi\u00f3 con combinaciones a la cabeza, aunque parecieron tener poco efecto en el campe\u00f3n pelirrojo mexicano.<\/p>\n<p>Las estad\u00edsticas del combate apuntaban a que Khan acert\u00f3 48 de 166 golpes, frente a los 64 de 170 de \u00c1lvarez.<\/p>\n<p>El mexicano ganaba en las tarjetas de dos de los jueces cuando termin\u00f3 el combate, mientras que Khan ganaba por un punto seg\u00fan el tercer juez.<\/p>\n<p>\u201cLa gente s\u00f3lo me conoc\u00eda por mi potencia\u201d, dijo \u00c1lvarez. \u201cTengo muchas m\u00e1s cualidades en el ring y lo demostr\u00e9. Creo que la gente vio m\u00e1s de m\u00ed\u201d.<\/p>\n<\/div>\n<div class=\"foto_central cutlineShow\">\n<div><img loading=\"lazy\" decoding=\"async\" class=\"waslazy\" title=\"Canelo \u00c1lvarez noquea a Amir Khan en 6to asalto \" src=\"http:\/\/www.diariolibre.com\/documents\/10157\/0\/512x365\/0c0\/0d0\/none\/10904\/BTDX\/image_content_6593040_20160508081109.jpg\" alt=\"Canelo \u00c1lvarez noquea a Amir Khan en 6to asalto \" width=\"512\" height=\"365\" data-original=\"\/documents\/10157\/0\/512x365\/0c0\/0d0\/none\/10904\/BTDX\/image_content_6593040_20160508081109.jpg\" \/><\/div>\n<div class=\"img-info\">Canelo \u00c1lvarez, a la derecha, noquea a Amir Khan durante su combate de peso mediano de WBC el s\u00e1bado 7 de mayo de 2016 en Las Vegas. <span class=\"byline-image\">( AP\/Isaac Brekken)<\/span><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>LAS VEGAS. Sa\u00fal \u201cCanelo\u201d \u00c1lvarez s\u00f3lo necesit\u00f3 un gran derechazo para convertir una pelea ajustada en un nocaut demoledor.<\/p>\n","protected":false},"author":12,"featured_media":55294,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-55292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=55292"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55292\/revisions"}],"predecessor-version":[{"id":55295,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55292\/revisions\/55295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/55294"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=55292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=55292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=55292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}