{"id":55849,"date":"2016-06-01T14:28:25","date_gmt":"2016-06-01T18:28:25","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=55849"},"modified":"2016-06-01T14:28:25","modified_gmt":"2016-06-01T18:28:25","slug":"animales-adorables-que-podrian-matarte-en-segundos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/animales-adorables-que-podrian-matarte-en-segundos\/","title":{"rendered":"Animales adorables que podr\u00edan matarte en segundos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-55850 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/delfin-672xXx80-300x183.jpg\" alt=\"delfin-672xXx80\" width=\"300\" height=\"183\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/delfin-672xXx80-300x183.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/delfin-672xXx80-440x270.jpg 440w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/delfin-672xXx80.jpg 656w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Son unos mam\u00edferos preciosos y adiestrados todav\u00eda m\u00e1s. En el zoo podemos verlos haciendo aut\u00e9nticas maravillas, interactuando con los humanos e incluso d\u00e1ndose besos y cari\u00f1os con ellos. Parece que son unos animales perfectos para hacer compa\u00f1\u00eda al hombre, sobre todo con esa sonrisa tan simpaticona, pero ese pensamiento est\u00e1 muy lejos de la realidad.\u00a0<!--more--><\/p>\n<p>En realidad, el mam\u00edfero m\u00e1s inteligente del mundo animal se parece m\u00e1s al delf\u00edn que Lisa libera en Los Simpsons, que asesina a los habitantes de Springfield, que a los que vemos en los parques tem\u00e1ticos. Son extremadamente peligrosos en cualquier tipo de situaci\u00f3n, ya que son los \u00fanicos animales que <strong>matan a otros simplemente por placer <\/strong>y no para sobrevivir. Muchos estudios han demostrado que son capaces de arrancar la cabeza a otros para utilizarla como bal\u00f3n para jugar. \u00bfA que ya no les miras con los mismos ojos?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Son unos mam\u00edferos preciosos y adiestrados todav\u00eda m\u00e1s. En el zoo podemos verlos haciendo aut\u00e9nticas maravillas, interactuando con los humanos e incluso d\u00e1ndose besos y cari\u00f1os con ellos. Parece que son unos animales perfectos para hacer compa\u00f1\u00eda al hombre, sobre todo con esa sonrisa tan simpaticona, pero ese pensamiento est\u00e1 muy lejos de la realidad.\u00a0<\/p>\n","protected":false},"author":9,"featured_media":55850,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-55849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=55849"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55849\/revisions"}],"predecessor-version":[{"id":55851,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/55849\/revisions\/55851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/55850"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=55849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=55849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=55849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}