{"id":56366,"date":"2016-06-13T13:19:08","date_gmt":"2016-06-13T17:19:08","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=56366"},"modified":"2016-06-13T13:19:08","modified_gmt":"2016-06-13T17:19:08","slug":"encuentran-un-farmaco-que-reduce-la-expansion-del-cancer-de-mama-mas-agresivo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/encuentran-un-farmaco-que-reduce-la-expansion-del-cancer-de-mama-mas-agresivo\/","title":{"rendered":"Encuentran un f\u00e1rmaco que reduce la expansi\u00f3n del c\u00e1ncer de mama m\u00e1s agresivo"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/B0593B7D-77DB-4E86-B23E-0C4E0F7F79C7.jpg__778__440__CROPz3x778y440.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-56368\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/B0593B7D-77DB-4E86-B23E-0C4E0F7F79C7.jpg__778__440__CROPz3x778y440.jpg\" alt=\"B0593B7D-77DB-4E86-B23E-0C4E0F7F79C7.jpg__778__440__CROPz3x778y440\" width=\"778\" height=\"440\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/B0593B7D-77DB-4E86-B23E-0C4E0F7F79C7.jpg__778__440__CROPz3x778y440.jpg 778w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/B0593B7D-77DB-4E86-B23E-0C4E0F7F79C7.jpg__778__440__CROPz3x778y440-300x170.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/B0593B7D-77DB-4E86-B23E-0C4E0F7F79C7.jpg__778__440__CROPz3x778y440-768x434.jpg 768w\" sizes=\"auto, (max-width: 778px) 100vw, 778px\" \/><\/a>Londres, 13 jun (EFE).- Un grupo de investigadores de Cancer Research UK descubri\u00f3 un f\u00e1rmaco que puede reducir la expansi\u00f3n del tipo m\u00e1s agresivo de c\u00e1ncer de mama, seg\u00fan public\u00f3 hoy la revista Oncogene.<!--more--><\/p>\n<div>El compuesto conocido como JQ1 altera la reacci\u00f3n de las c\u00e9lulas cancer\u00edgenas ante la hipoxia o falta de ox\u00edgeno, un proceso que se encuentra presente en m\u00e1s del 50 % de los tumores y es m\u00e1s com\u00fan en los c\u00e1nceres de mama del tipo triple negativo, el m\u00e1s dif\u00edcil de tratar.<\/p>\n<\/div>\n<div>Cient\u00edficos de las universidades de Oxford y Nottingham (en el centro de Inglaterra) concluyeron en su estudio que el JQ1 provoca que el tejido cancer\u00edgeno deje de adaptarse a la carencia de ox\u00edgeno, lo que ralentiza su desarrollo.<\/div>\n<div>\nEl coautor de la investigaci\u00f3n, Alan McIntyre, afirm\u00f3 que \u00abel tratamiento de la hipoxia a veces compromete el tratamiento del c\u00e1ncer de mama y el JQ1 puede ser la clave para ayudar a las pacientes de esta enfermedad\u00bb.<\/div>\n<div>\nCuando este tipo de tumor se acostumbra a los niveles bajos de ox\u00edgeno, su biolog\u00eda se altera y se vuele resistente a terapias comunes, raz\u00f3n por la que este nuevo medicamento podr\u00eda cambiar la forma de combatir este c\u00e1ncer, seg\u00fan los investigadores.<\/div>\n<div>\nDesde Cancer Research UK, Nell Barrie, apunt\u00f3 que \u00abel estudio muestra c\u00f3mo funciona este f\u00e1rmaco\u00bb y que \u00abpodr\u00eda ser una forma de detener la expansi\u00f3n del c\u00e1ncer\u00bb, aunque remarca que ahora se debe examinar \u00abla efectividad del JQ1 sobre los pacientes\u00bb. EFE<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Londres, 13 jun (EFE).- Un grupo de investigadores de Cancer Research UK descubri\u00f3 un f\u00e1rmaco que puede reducir la expansi\u00f3n del tipo m\u00e1s agresivo de c\u00e1ncer de mama, seg\u00fan public\u00f3 hoy la revista Oncogene.<\/p>\n","protected":false},"author":12,"featured_media":56368,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-56366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=56366"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56366\/revisions"}],"predecessor-version":[{"id":56369,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56366\/revisions\/56369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/56368"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=56366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=56366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=56366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}