{"id":56396,"date":"2016-06-16T17:33:31","date_gmt":"2016-06-16T21:33:31","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=56396"},"modified":"2016-06-16T17:33:31","modified_gmt":"2016-06-16T21:33:31","slug":"imagenes-bailarinas-de-la-nba-en-republica-dominicana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/imagenes-bailarinas-de-la-nba-en-republica-dominicana\/","title":{"rendered":"Im\u00e1genes: Bailarinas de la NBA en Rep\u00fablica Dominicana"},"content":{"rendered":"<p>Como parte de las actividades de la NBA Fan Events \u00a0la sucursal del centro comercial Megacentro de la cadena de tiendas deportiva Sportline Am\u00e9rica recibi\u00f3 una visita muy especial: las Honey Bees Dancers del equipo de baloncesto de la NBA Charlotte Hornest y la mascota Franklin The Dog, del equipo Philadelphia 76ers.<!--more--><\/p>\n<p>Durante el divertido encuentro, clientes, fan\u00e1ticos y dem\u00e1s asistentes compartieron con las bailarinas y disfrutaron de las ocurrencias de la mascota, mientras se tomaban fotograf\u00edas y solicitaban aut\u00f3grafos de las mismas.<\/p>\n<p><a href=\"http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Ni%C3%B1a.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-261261\" src=\"http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Ni%C3%B1a-1024x683.jpg\" sizes=\"auto, (max-width: 606px) 100vw, 606px\" srcset=\"http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Ni\u00f1a-1024x683.jpg 1024w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Ni\u00f1a-300x200.jpg 300w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Ni\u00f1a-768x512.jpg 768w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Ni\u00f1a-630x420.jpg 630w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Ni\u00f1a-640x427.jpg 640w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Ni\u00f1a-681x454.jpg 681w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Ni\u00f1a.jpg 1138w\" alt=\"Ni\u00f1a\" width=\"606\" height=\"404\" \/><\/a><a href=\"http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/rubias.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-261262\" src=\"http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/rubias-1024x683.jpg\" sizes=\"auto, (max-width: 606px) 100vw, 606px\" srcset=\"http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/rubias-1024x683.jpg 1024w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/rubias-300x200.jpg 300w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/rubias-768x512.jpg 768w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/rubias-630x420.jpg 630w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/rubias-640x427.jpg 640w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/rubias-681x454.jpg 681w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/rubias.jpg 1138w\" alt=\"rubias\" width=\"606\" height=\"404\" \/><\/a><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/Sixers-681x454.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-56398\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/Sixers-681x454.jpg\" alt=\"Sixers-681x454\" width=\"609\" height=\"406\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/Sixers-681x454.jpg 681w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/Sixers-681x454-300x200.jpg 300w\" sizes=\"auto, (max-width: 609px) 100vw, 609px\" \/><\/a><a href=\"http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Sixers.jpg\"><br \/>\n<\/a><a href=\"http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Honey-Dancers.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-261264\" src=\"http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Honey-Dancers-1024x683.jpg\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" srcset=\"http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Honey-Dancers-1024x683.jpg 1024w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Honey-Dancers-300x200.jpg 300w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Honey-Dancers-768x512.jpg 768w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Honey-Dancers-630x420.jpg 630w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Honey-Dancers-640x427.jpg 640w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Honey-Dancers-681x454.jpg 681w, http:\/\/ensegundos.do\/wp-content\/uploads\/2016\/06\/Honey-Dancers.jpg 1138w\" alt=\"Honey Dancers\" width=\"598\" height=\"399\" \/><\/a><\/p>\n<div><\/div>\n<p>Sportline Am\u00e9rica es la cadena de tiendas deportivas m\u00e1s importante del Caribe, Centroam\u00e9rica y Suram\u00e9rica, con presencia en Panam\u00e1, Honduras, El Salvador, Nicaragua, Colombia, Guatemala y Rep\u00fablica Dominicana, donde cuenta con tres localidades (Agora, Sambil y Megacentro).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de las actividades de la NBA Fan Events \u00a0la sucursal del centro comercial Megacentro de la cadena de tiendas deportiva Sportline Am\u00e9rica recibi\u00f3 una visita muy especial: las Honey Bees Dancers del equipo de baloncesto de la NBA Charlotte Hornest y la mascota Franklin The Dog, del equipo Philadelphia 76ers.<\/p>\n","protected":false},"author":12,"featured_media":56398,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-56396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=56396"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56396\/revisions"}],"predecessor-version":[{"id":56399,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56396\/revisions\/56399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/56398"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=56396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=56396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=56396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}