{"id":56402,"date":"2016-06-16T20:43:53","date_gmt":"2016-06-17T00:43:53","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=56402"},"modified":"2016-06-16T20:43:53","modified_gmt":"2016-06-17T00:43:53","slug":"hotel-villa-taina-celebra-20-anos-en-cabarete","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/hotel-villa-taina-celebra-20-anos-en-cabarete\/","title":{"rendered":"Hotel Villa Taina Celebra 20 A\u00f1os en Cabarete"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/13445255_1098485760208534_3972190201197299443_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-56408 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/13445255_1098485760208534_3972190201197299443_n.jpg\" alt=\"13445255_1098485760208534_3972190201197299443_n\" width=\"411\" height=\"333\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/13445255_1098485760208534_3972190201197299443_n.jpg 960w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/13445255_1098485760208534_3972190201197299443_n-300x243.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/13445255_1098485760208534_3972190201197299443_n-768x622.jpg 768w\" sizes=\"auto, (max-width: 411px) 100vw, 411px\" \/><\/a>Cabarete, Sos\u00faa.-<\/strong> El Hotel Villa Taina celebr\u00f3 20 a\u00f1os de fundaci\u00f3n y trabajo en la comunidad tur\u00edstica de Cabarete. La noche del viernes fue motivo para celebrar entre los propietarios fundadores, cuerpo gerencial y operativo del hotel, amigos, prensa y relacionados en un ambiente emotivo y festivo.<!--more--><\/p>\n<p>En su intervenci\u00f3n la presidenta y socia fundadora, Sra. Claudia Schwarz destac\u00f3 el apoyo de personalidades que desde sus inicios concibieron este hotel como punta de lanza para el desarrollo y proyecci\u00f3n de Cabarete, adem\u00e1s dej\u00f3 demostrada su conexi\u00f3n con los elementos culturales de la dominicanidad relacionados al nombre del hotel que por estos 20 a\u00f1os lidera junto a su equipo siendo una alemana radicada en dicha comunidad tur\u00edstica.<\/p>\n<p>\u201cEn Villa Taina hemos traido la memoria de la cultura de los Tainos al presente. El legado de los Tainos se ha convertido en nuestra filosof\u00eda: respetar el medio ambiente que nos rodea. Crear, brindar y mantener un ambiente de armon\u00eda, un oasis de paz y relajaci\u00f3n para todos nuestros hu\u00e9spedes y visitantes. Nuestra meta es de que todas las personas que se hospedan con nosotros o pasan por el Hotel se sientan transformados y elevados en nuestros espacios frente al mar. Asi, nuestro reto ha sido en las \u00faltimas dos d\u00e9cadas, mejorar cada d\u00eda mas nuestras instalaciones y el servicio al cliente\u201d, destac\u00f3\u00a0\u00a0 Claudia Schwarz en su discurso principal.<\/p>\n<p>La ocasi\u00f3n fue propicia para reconocer a tres mujeres que desde sus inicios y evoluci\u00f3n, han sido parte integral del desarrollo de este hotel: Iris Carrillo Dottin, Yris Lara e Ydaisa N\u00fa\u00f1ez Clark. Adem\u00e1s se present\u00f3 ante todo el p\u00fablico al equipo que ha mantenido el prestigio y buen funcionamiento de este hotel en sus distintas \u00e1reas como son: Osaris Garc\u00eda en Control de Calidad; Jenny Salvador, contadora; Marlecia Aragon\u00e9s, Asistente de Reservaciones; Nicole Friedel, Gerente de Reservas y Contrataciones; Francis Bonilla, Gerente de Operaciones y finalmente la gerente general, se\u00f1ora Diane Tremblay.<a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/13466000_1077110789029770_8893525259923748059_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-56407\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/13466000_1077110789029770_8893525259923748059_n.jpg\" alt=\"13466000_1077110789029770_8893525259923748059_n\" width=\"557\" height=\"343\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/13466000_1077110789029770_8893525259923748059_n.jpg 960w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/13466000_1077110789029770_8893525259923748059_n-300x185.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/13466000_1077110789029770_8893525259923748059_n-768x473.jpg 768w\" sizes=\"auto, (max-width: 557px) 100vw, 557px\" \/><\/a><\/p>\n<p>El evento fue amenizado por los grupos musicales \u201cLas Mariposas\u201d de The Mariposa Foundation y \u201cFedujazz Emsemble\u201d de Fedujazz quienes pusieron de manifiesto todo su talento en escenario y deleitaron a los presentes con sus interpretaciones.<\/p>\n<p>En un momento de gran regocijo y para culminar con gran emotividad, todo el equipo de Villa Ta\u00edna hizo entrega de una placa de reconocimiento a la se\u00f1ora Schwarz por su esp\u00edritu emprendedor y visi\u00f3n de lucha que la ha mantenido como una gran l\u00edder en 20 a\u00f1os de gesti\u00f3n y direcci\u00f3n hotelera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cabarete, Sos\u00faa.- El Hotel Villa Taina celebr\u00f3 20 a\u00f1os de fundaci\u00f3n y trabajo en la comunidad tur\u00edstica de Cabarete. La noche del viernes fue motivo para celebrar entre los propietarios fundadores, cuerpo gerencial y operativo del hotel, amigos, prensa y relacionados en un ambiente emotivo y festivo.<\/p>\n","protected":false},"author":12,"featured_media":56408,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-56402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=56402"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56402\/revisions"}],"predecessor-version":[{"id":56409,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56402\/revisions\/56409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/56408"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=56402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=56402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=56402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}