{"id":56442,"date":"2016-06-18T11:12:33","date_gmt":"2016-06-18T15:12:33","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=56442"},"modified":"2016-06-18T11:12:33","modified_gmt":"2016-06-18T15:12:33","slug":"descubre-por-que-deberias-poner-cascara-de-limon-en-tus-pies-antes-de-ir-a-dormir","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/descubre-por-que-deberias-poner-cascara-de-limon-en-tus-pies-antes-de-ir-a-dormir\/","title":{"rendered":"Descubre por qu\u00e9 deber\u00edas poner c\u00e1scara de lim\u00f3n en tus pies antes de ir a dormir"},"content":{"rendered":"<p>Podemos aprovechar la c\u00e1scara del lim\u00f3n directamente o bien rallarla y aplicarla a modo de exfoliante. En ambos casos deberemos dejarla actuar toda la noche para obtener mejores resultados.<!--more--><br \/>\n<a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/Pies-c\u00e1scara-limon-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-56443\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/Pies-c\u00e1scara-limon-1.png\" alt=\"Pies-c\u00e1scara-limon-1\" width=\"735\" height=\"414\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/Pies-c\u00e1scara-limon-1.png 735w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/06\/Pies-c\u00e1scara-limon-1-300x169.png 300w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/><\/a><\/p>\n<p><strong>Durante mucho tiempo se le rest\u00f3 importancia a los pies<\/strong> y no se le brindaron los cuidados necesarios para conservarlos en buen estado.<\/p>\n<p>No obstante, por cuestiones est\u00e9ticas y de salud, poco a poco se comenzaron a tomar m\u00e1s medidas para <strong>cuidar su piel y evitar el desarrollo de varios tipos de infecciones.<\/strong><\/p>\n<p>Mantenerlos suaves y con una buena apariencia son referentes de buena higiene y cuidado personal, en especial cuando se desea lucir un calzado descubierto.<\/p>\n<p>El inconveniente es que <strong>muchos no saben c\u00f3mo tratarlos y qu\u00e9 hacer para que no desarrollen alteraciones.<\/strong><\/p>\n<p>Esto hace que tiendan a padecer molestias como las callosidades, los talones agrietados y las afecciones mic\u00f3ticas.<\/p>\n<p>Por fortuna, hay varios remedios de origen natural que nos permiten combatir todos estos problemas para darles un mejor aspecto en poco tiempo.<\/p>\n<p>Entre <strong>estos nos encontramos con la prodigiosa c\u00e1scara de lim\u00f3n<\/strong>, un ingrediente que muchos han desperdiciado sin alcanzar a imaginar sus beneficios.<\/p>\n<p>En este espacio queremos contarte c\u00f3mo emplearla y qu\u00e9 efectos positivos tiene para la salud de los pies.<\/p>\n<p>\u00bfTe animas a probarla?<\/p>\n<h2>Tratamiento de c\u00e1scara de lim\u00f3n para mejorar la salud de los pies<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-104770\" src=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2016\/05\/limones-talones-500x269.png\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" srcset=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2016\/05\/limones-talones-500x269.png 500w, http:\/\/mejorconsalud.com\/wp-content\/uploads\/2016\/05\/limones-talones.png 620w\" alt=\"limones-talones\" width=\"500\" height=\"269\" \/><\/p>\n<p>La mayor\u00eda de las personas arrojan las c\u00e1scaras de lim\u00f3n a la basura y no tienen ni la m\u00e1s m\u00ednima idea de las propiedades que estas ocultan.<\/p>\n<p>Los expertos aseguran que <strong>contienen hasta 10 veces m\u00e1s vitamina C que el jugo<\/strong>, adem\u00e1s de aceites esenciales y poderosos antioxidantes.<\/p>\n<p>Muchas de estas bondades se aprovechan a trav\u00e9s de su consumo, ya que se cree que puede curar y prevenir varios tipos de enfermedades.<\/p>\n<p>Sin embargo, como en este caso nuestro objetivo es otro, vamos a observar <strong>c\u00f3mo aprovecharla para reparar la piel da\u00f1ada de los pies.<\/strong><\/p>\n<h3>Vas a necesitar<\/h3>\n<ul>\n<li>1 lim\u00f3n grande<\/li>\n<li>1 par de calcetines<\/li>\n<\/ul>\n<h3>Instrucciones<\/h3>\n<ul>\n<li>Debes cortar el lim\u00f3n en dos partes, de tal modo que cada mitad se ajuste\u00a0a la perfecci\u00f3n en los talones de los\u00a0pies.<\/li>\n<li>Exprime la totalidad del jugo\u00a0de lim\u00f3n y procede a poner el fruto sobre las zonas afectadas.<\/li>\n<li>Haz una ligera presi\u00f3n sobre el tal\u00f3n y aseg\u00farate de que encaje a la perfecci\u00f3n para que no se caiga.<\/li>\n<li>A continuaci\u00f3n, ponte los calcetines bien ajustados y acu\u00e9state.<\/li>\n<li>Recuerda que es un tratamiento para hacer antes de ir a dormir, ya que<strong> las c\u00e1scaras necesitan varias horas para hacer efecto<\/strong>.<\/li>\n<\/ul>\n<h3>\u00bfCu\u00e1l es el resultado?<\/h3>\n<ul>\n<li>Al cabo de dos o tres noches comenzar\u00e1s a notar un cambio significativo en el estado de tus pies. <strong>Sentir\u00e1s los callos m\u00e1s blanditos y las grietas comenzar\u00e1n a desaparecer.<\/strong><\/li>\n<li>El alivio total de estas condiciones depender\u00e1 de la constancia con que apliques el remedio.<\/li>\n<\/ul>\n<h2>Exfoliante de c\u00e1scara de lim\u00f3n y vaselina para aliviar los pies<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-80189\" src=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2015\/10\/C%C3%B3mo-aprovechar-la-c%C3%A1scara-de-lim%C3%B3n-500x334.jpg\" alt=\"C\u00f3mo aprovechar la c\u00e1scara de lim\u00f3n\" width=\"500\" height=\"334\" \/><\/p>\n<p>La combinaci\u00f3n de c\u00e1scara de lim\u00f3n con vaselina es otra buena alternativa para<strong>acelerar la recuperaci\u00f3n de las durezas que alteran los pies.<\/strong><\/p>\n<p>Ambos crean un exfoliante natural que facilita la eliminaci\u00f3n de piel muerta y otras impurezas que van causando sequedad.<\/p>\n<p>La vaselina es uno de los ingredientes naturales m\u00e1s recomendados para hidratar esta parte del cuerpo, ya que <strong>protege la piel y la mantiene h\u00fameda.<\/strong><\/p>\n<h3>Vas a necesitar<\/h3>\n<ul>\n<li>1 cucharada de vaselina (15 g)<\/li>\n<li>1 cucharada de c\u00e1scara de lim\u00f3n rallada (10 g)<\/li>\n<li>1 vendaje<\/li>\n<\/ul>\n<h3>Instrucciones<\/h3>\n<ul>\n<li>Congela un lim\u00f3n y p\u00e1salo por un rallador para obtener un polvillo de su c\u00e1scara.<\/li>\n<li>Mezcla este ingrediente con la cucharada de vaselina, hasta obtener una crema.<\/li>\n<li>Frota el producto en los pies y c\u00fabrelos con el\u00a0vendaje.<\/li>\n<li>D\u00e9jalo actuar toda la noche y enjuaga de inmediato a la ma\u00f1ana siguiente.<\/li>\n<\/ul>\n<h3>\u00bfCu\u00e1l es el resultado?<\/h3>\n<ul>\n<li>Al usarlo\u00a0dos o tres veces a la semana <strong>conseguir\u00e1s unos pies m\u00e1s suaves, hidratados y protegidos.<\/strong><\/li>\n<li>Lo puedes utilizar como parte de tu pedicura en lugar de los exfoliantes convencionales.<\/li>\n<\/ul>\n<h2>Consejos para obtener mejores resultados\u2026<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-93635\" src=\"http:\/\/mejorconsalud.com\/wp-content\/uploads\/2016\/02\/Calzado-500x334.jpg\" alt=\"Calzado\" width=\"500\" height=\"334\" \/><\/p>\n<p>Para que ninguno de estos trucos con c\u00e1scara de lim\u00f3n te falle, recuerda utilizar un calzado c\u00f3modo y ventilado. La mayor\u00eda de problemas de los pies tienen su origen en <strong>el uso continuo de zapatos inapropiados.<\/strong><\/p>\n<p>Despu\u00e9s de la ducha y antes de ponerte los zapatos, apl\u00edcate una cantidad abundante de crema hidratante.<\/p>\n<p>En caso de callos demasiado gruesos, <strong>sumerge los pies en agua caliente y fr\u00f3talos con una piedra p\u00f3mez.<\/strong><\/p>\n<p>Por \u00faltimo, recuerda que las u\u00f1as tambi\u00e9n requieren una atenci\u00f3n especial. Evita que est\u00e9n en ambientes h\u00famedos y prot\u00e9gelas frente a los hongos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Podemos aprovechar la c\u00e1scara del lim\u00f3n directamente o bien rallarla y aplicarla a modo de exfoliante. En ambos casos deberemos dejarla actuar toda la noche para obtener mejores resultados.<\/p>\n","protected":false},"author":12,"featured_media":56443,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-56442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=56442"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56442\/revisions"}],"predecessor-version":[{"id":56444,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56442\/revisions\/56444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/56443"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=56442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=56442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=56442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}