{"id":5668,"date":"2014-07-08T13:58:05","date_gmt":"2014-07-08T17:58:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=5668"},"modified":"2014-12-02T12:13:12","modified_gmt":"2014-12-02T16:13:12","slug":"demanda-por-us-10-millones-a-espn-por-mostrarlo-dormido","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/demanda-por-us-10-millones-a-espn-por-mostrarlo-dormido\/","title":{"rendered":"Demanda Por U$S 10 Millones A ESPN Por Mostrarlo Dormido"},"content":{"rendered":"<p style=\"color: #404040;\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/Lo-Mostran-Dormido-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5670 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/Lo-Mostran-Dormido-1.jpg\" alt=\"Lo-Mostran-Dormido (1)\" width=\"270\" height=\"149\" \/><\/a>Un hombre que fue mostrado en la cadena ESPN mientras dorm\u00eda durante un partido entre los Yankees de Nueva York y los Medias Rojas de Boston, introdujo una demanda por difamaci\u00f3n, por haber sido, presuntamente, retratado como \u201cgordo, poco inteligente y est\u00fapido\u201d.<!--more--><\/p>\n<p style=\"color: #404040;\">Andrew Robert Rector demand\u00f3 ante la Corte Suprema del condado del Bronx al Sistema de Medios del B\u00e9isbol de Grandes Ligas, a ESPN Nueva York, a los Yankees de Nueva York y a los comentaristas del canal Dan Shulman y John Kruk.<\/p>\n<p>Rector exige diez millones de d\u00f3lares en da\u00f1os por difamaci\u00f3n y estr\u00e9s emocional causado intencionalmente, luego de aparecer en las pantallas de la popular cadena deportiva durante la transmisi\u00f3n del juego entre Yankees y \u2019Red Sox\u2019 del pasado 13 de abril. Rector estaba sentado en las tribunas del Yankee Stadium, plenamente dormido en la imagen.<\/p>\n<p style=\"color: #404040;\">\u201cComentaristas como Dan Shulman y John Kruk soltaron una avalancha de palabras despreciativas en contra de la persona a la que concierne la demanda. Estas palabras incluyen pero no se limitan a \u2019estupor, gordito, no inteligente, est\u00fapido\u2019, sabiendo y con la intenci\u00f3n de que eso fuera escuchado por millones de personas en todo el mundo\u201d, dice la demanda.<\/p>\n<p style=\"color: #404040;\">La imagen de Rector durmiendo fue luego colocada en el portal oficial de las Mayores, MLB.com, haci\u00e9ndose viral entre los aficionados a la pelota norteamericana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un hombre que fue mostrado en la cadena ESPN mientras dorm\u00eda durante un partido entre los Yankees de Nueva York y los Medias Rojas de Boston, introdujo una demanda por difamaci\u00f3n, por haber sido, presuntamente, retratado como \u201cgordo, poco inteligente y est\u00fapido\u201d.<\/p>\n","protected":false},"author":3,"featured_media":33906,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-5668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/5668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=5668"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/5668\/revisions"}],"predecessor-version":[{"id":33907,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/5668\/revisions\/33907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/33906"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=5668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=5668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=5668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}