{"id":56764,"date":"2016-07-01T07:36:14","date_gmt":"2016-07-01T11:36:14","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=56764"},"modified":"2016-07-01T07:36:14","modified_gmt":"2016-07-01T11:36:14","slug":"video-nino-se-vuelve-viral-por-curiosos-gestos-en-juego-de-beisbol","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/video-nino-se-vuelve-viral-por-curiosos-gestos-en-juego-de-beisbol\/","title":{"rendered":"Video: Ni\u00f1o se vuelve viral por curiosos gestos en juego de b\u00e9isbol"},"content":{"rendered":"<div class=\"article-body\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/nino-portada.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-56767\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/nino-portada.jpeg\" alt=\"nino-portada\" width=\"858\" height=\"540\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/nino-portada.jpeg 858w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/nino-portada-300x189.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/nino-portada-768x483.jpeg 768w\" sizes=\"auto, (max-width: 858px) 100vw, 858px\" \/><\/a>Durante las semifinales del torneo de NCAA Divisi\u00f3n I entre <b>Texas Christian University y Coastal Carolina, <\/b>por unos instantes el protagonista se encontr\u00f3 en las tribunas y no en el diamante.<!--more--><\/p>\n<p>Un peque\u00f1o rob\u00f3 los reflectores durante varios segundos por las <b>divertidas caras<\/b> que era capaz de hacer cuando era enfocado por las c\u00e1maras.<\/p>\n<p>Solo con miradas, movimientos de hombros y peque\u00f1as sonrisas logr\u00f3 hacer re\u00edr a los comentaristas del partido que desviaron su atenci\u00f3n por completo al ni\u00f1o.<\/p>\n<\/div>\n<div class=\"video-component large\">\n<div class=\"video-wrapper\"><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/v05XIPnf4T8\" width=\"630\" height=\"350\" frameborder=\"0\"><\/iframe><\/div>\n<\/div>\n<div class=\"article-body\">\n<p>El show del peque\u00f1o continu\u00f3 hasta que su mam\u00e1 se dio cuenta que la c\u00e1mara los enfocaba.<\/p>\n<p>El final feliz de este divertido ni\u00f1o lleg\u00f3 cuando su madre le mostr\u00f3 una imagen que le lleg\u00f3 a su celular, cuando comenz\u00f3 a viralizarse el video.<\/p>\n<p>Por cierto, la semifinal la gan\u00f3 Coastal Carolina, que a la postre super\u00f3 en la Serie de Campeonato a Arizona.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durante las semifinales del torneo de NCAA Divisi\u00f3n I entre Texas Christian University y Coastal Carolina, por unos instantes el protagonista se encontr\u00f3 en las tribunas y no en el diamante.<\/p>\n","protected":false},"author":12,"featured_media":56767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-56764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=56764"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56764\/revisions"}],"predecessor-version":[{"id":56768,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56764\/revisions\/56768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/56767"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=56764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=56764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=56764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}