{"id":56827,"date":"2016-07-03T09:33:36","date_gmt":"2016-07-03T13:33:36","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=56827"},"modified":"2016-07-03T09:33:36","modified_gmt":"2016-07-03T13:33:36","slug":"como-le-administro-la-tecnologia-en-verano-a-los-ninos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/como-le-administro-la-tecnologia-en-verano-a-los-ninos\/","title":{"rendered":"\u00bfC\u00f3mo le administro la tecnolog\u00eda en verano a los ni\u00f1os?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/1366_2000-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-56829\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/1366_2000-4.jpg\" alt=\"1366_2000 (4)\" width=\"784\" height=\"523\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/1366_2000-4.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/1366_2000-4-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/1366_2000-4-768x512.jpg 768w\" sizes=\"auto, (max-width: 784px) 100vw, 784px\" \/><\/a>Hace un mes hablamos de la generaci\u00f3n de padres que se siente culpable porque sus hijos pasan mucho tiempo mirando pantallas, que es la nuestra, que en estos d\u00edas se enfrenta a una nueva encrucijada porque los ni\u00f1os ya no tienen colegio.<!--more--> Mucho tiempo libre, hace calor en el exterior y, aunque tambi\u00e9n hay mucho por hacer para divertirse dentro (y fuera) de casa, a menudo acaban con el ocio f\u00e1cil y llamativo de la tecnolog\u00eda, para preocupaci\u00f3n nuestra.<\/p>\n<p>Para hablar de este tema hemos querido <strong>preguntar a los profesionales de la psicolog\u00eda<\/strong> y <strong>tambi\u00e9n a los padres<\/strong>, para que nos dieran ideas y as\u00ed ayudarnos a que los ni\u00f1os no se pasen el verano pegados a una pantalla: <strong>\u00bfC\u00f3mo le administro la tecnolog\u00eda en verano a los ni\u00f1os?<\/strong><\/p>\n<h2>Controlar su uso haciendo que las pantallas sean un complemento<\/h2>\n<p>Cuando Disney confirm\u00f3 que sus productos <strong>Baby Einstein<\/strong> no aportaban ning\u00fan beneficio a nivel del desarrollo para los ni\u00f1os, y devolvi\u00f3 el dinero a los padres en EE.UU., muchos padres consideraron que al no ser positivos para los ni\u00f1os, porque no estimulaban su inteligencia, era una p\u00e9rdida de tiempo pon\u00e9rselos a sus hijos. Sin embargo, bien aprovechados, eran v\u00eddeos \u00fatiles, con canciones bonitas, que pod\u00edan servir de apoyo para el juego y la estimulaci\u00f3n.<\/p>\n<p>Un apoyo, como lo es un juguete. Porque, \u00bfcu\u00e1l es el fin de un juguete? Pues el juego. Lo importante es el juego, no el juguete, as\u00ed que <strong>un juguete es maravilloso en tanto ofrece la posibilidad de jugar con \u00e9l<\/strong>, y lo es si puede aprovecharse. En m\u00e1s de una ocasi\u00f3n he o\u00eddo a padres criticar un juguete porque su hijo de un a\u00f1o apenas le hace caso. \u00bfAcaso no saben que un ni\u00f1o de un a\u00f1o dif\u00edcilmente aprovechar\u00e1 el potencial de un juguete, si nadie juega con \u00e9l? Y no digo que los padres tengan que ense\u00f1arle a utilizarlo, sino que tienen que estar ah\u00ed, porque lo \u00faltimo que quiere un ni\u00f1o es estar solo. Y si est\u00e1 acompa\u00f1ado, seguro que jugar\u00e1 m\u00e1s y aprender\u00e1 m\u00e1s a trav\u00e9s del juego.<\/p>\n<p>Pues las pantallas pueden ser utilizadas de ese modo, como apoyo para un juego mayor, como recurso para otras actividades. Teresa Garc\u00eda, psic\u00f3loga que trabaja en La Cantonera y autora de la web Sin Castigos nos lo explica as\u00ed:<\/p>\n<blockquote><p>La tecnolog\u00eda se ha convertido en parte crucial de nuestra vida y fuente de problemas en las relaciones humanas a cuenta del tiempo \u201cseguro\u201d de uso. Se escuchan palabras como: \u201cadicci\u00f3n\u201d, \u201caislamiento social\u201d, \u201cda\u00f1os en la visi\u00f3n\u201d, etc.<\/p>\n<p>Como soluci\u00f3n en mi pr\u00e1ctica personal y profesional los he convertido en un aliado para aumentar la conexi\u00f3n entre personas de diferentes edades. Trabajo en una escuela: IIP Dharma College La Cantonera. All\u00ed los ni\u00f1os y ni\u00f1as tienen acceso libre a las nuevas tecnolog\u00edas. Les puedes ver consultando lo que necesitan para construir una casa en un \u00e1rbol o jugando a diferentes juegos. Entre ellos se explican las reglas, aprenden lectura e ingl\u00e9s dado que la mayor\u00eda est\u00e1n en ese idioma. Y adem\u00e1s sirven como base a los juegos de grupo que forman despu\u00e9s bajo los laureles de India. El tiempo de acceso es completamente libre.<\/p>\n<p>En el taller de padres que pone fin al curso escolar el tema estrella son las pantallas y su uso. Explico que al igual que en el cole, pueden convertirse en un elemento de relaci\u00f3n y conexi\u00f3n en la familia. Usarlas juntos y aprender juntos conduce a una relaci\u00f3n intrafamiliar equilibrada.<\/p><\/blockquote>\n<p>Esto quiere decir que igual no es una cuesti\u00f3n de ponerles l\u00edmites, sino de aprovechar sus bondades para el d\u00eda a d\u00eda.<\/p>\n<h2>Las bicicletas son para el verano<\/h2>\n<p>O el verano es para las bicicletas, para aprovecharlo y hacer todo aquello que durante el resto del a\u00f1o apenas podemos porque las obligaciones nos limitan. S\u00ed, es cierto que durante el a\u00f1o no pueden jugar mucho con las pantallas porque, o tienen otras cosas que hacer (extraescolares, deberes, etc.) o los padres limitamos su uso. \u00bfQuiere decir esto que como ahora tienen fiesta pueden aprovechar para jugar m\u00e1s con ellas? Pues quiz\u00e1s habr\u00eda que intentar no sobrepasar las dos horas de pantallas que se marcan como l\u00edmite diario (la AAP\u00a0recomienda que los ni\u00f1os de 3 a 5 a\u00f1os no excedan la hora diaria, y los de 6 a 18 a\u00f1os, no pasen de las dos horas) y aumentar otras actividades que tambi\u00e9n est\u00e1n muy limitadas todo el a\u00f1o.<\/p>\n<p>El psic\u00f3logo Alberto Soler nos ha dado algunas indicaciones al respecto:<\/p>\n<blockquote><p>En casa los ordenadores deber\u00edan estar en una zona com\u00fan o de paso, con una sesi\u00f3n para cada miembro de la familia y siendo su uso supervisado por los padres y los tel\u00e9fonos m\u00f3viles y tabletas se deber\u00edan cargar siempre en una zona com\u00fan, nunca en el dormitorio. De este modo protegemos la zona de descanso y estudio de distracciones innecesarias. Es positivo establecer un \u201ctoque de queda\u201d tecnol\u00f3gico: a partir de una determinada hora, ning\u00fan miembro de la familia hace uso de tel\u00e9fonos o tabletas. Por eso es muy importante que nosotros como padres limitemos tambi\u00e9n el uso que hacemos de estos dispositivos personales delante de nuestros hijos. Por un lado, porque debemos recordar la importancia que los padres tenemos como modelo: lo que hacemos nosotros, ellos lo van a replicar.<\/p>\n<p>En realidad, la tecnolog\u00eda no es mala: el wifi no fr\u00ede el cerebro ni las pantallas de los m\u00f3viles las retinas, pero cada cosa tiene su momento, y los ni\u00f1os aprenden mucho mejor de la interacci\u00f3n con iguales que mediante pantallas. Ahora en vacaciones, si es posible, m\u00e1s que aumentar la tolerancia con medios, deber\u00edamos aumentar las oportunidades de ocio alternativo: campo, playa, piscina, deporte, etc. No deber\u00eda haber variaci\u00f3n excesiva&#8230;<\/p><\/blockquote>\n<div class=\"article-asset-image article-asset-large\">\n<div class=\"asset-content\"><img decoding=\"async\" class=\"centro_sinmarco\" src=\"http:\/\/i.blogs.es\/478bc1\/8222037187_7f9c56009e_k\/450_1000.jpg\" srcset=\"http:\/\/i.blogs.es\/478bc1\/8222037187_7f9c56009e_k\/450_1000.jpg 450w, http:\/\/i.blogs.es\/478bc1\/8222037187_7f9c56009e_k\/650_1200.jpg 681w, http:\/\/i.blogs.es\/478bc1\/8222037187_7f9c56009e_k\/1024_2000.jpg 1024w, http:\/\/i.blogs.es\/478bc1\/8222037187_7f9c56009e_k\/1366_2000.jpg 1366w\" alt=\"Padres, ni\u00f1os y pantallas\" \/><\/div>\n<\/div>\n<p>Por su parte, la psicopegadoga Alma Garc\u00eda explica que las vacaciones de verano no deber\u00edan ser un momento para darles libertad con las pantallas, sino <strong>una ocasi\u00f3n para limitarlos<\/strong>, y es que en vacaciones hay mucho por hacer pero como los padres andan de aqu\u00ed a all\u00e1, no acaban por saber qu\u00e9 alternativas dar a los ni\u00f1os:<\/p>\n<blockquote><p>Yo siempre digo a los padres que hagan una lista de \u00abcosas que hacer en verano durante el tiempo libre\u00bb. Y que la hagan lo m\u00e1s larga que puedan, que sea realista, y que se hagan con los materiales necesarios para llevarla a cabo. De ese modo tendr\u00e1n una bater\u00eda de ideas para ofrecer a los ni\u00f1os antes del \u00abanda, toma mi m\u00f3vil un rato pero me lo devuelves enseguida, eh?\u00bb.<\/p>\n<p>No debemos temer que por ello se vayan a quedar atr\u00e1s con la tecnolog\u00eda, pues lo llevan en las venas. Reducirla al m\u00ednimo lo que s\u00ed asegura es un verano sano, libre, con mucho movimiento (tan necesario para evitar problemas de aprendizaje), creatividad y conexi\u00f3n consigo mismos, con los dem\u00e1s y con el mundo maravilloso que les rodea.<\/p>\n<p>Ah, y que los pap\u00e1s dejen de hacer el s\u00edmil entre \u00abpremio\u00bb y \u00abratito tecnol\u00f3gico\u00bb. Puede que el verdadero premio, el verdadero regalo, sea un ratito de aburrimiento que les haga encender su imaginaci\u00f3n, su creatividad y sus neuronas.<\/p><\/blockquote>\n<h2>\u00bfY c\u00f3mo lo hacen los padres?<\/h2>\n<p>Adem\u00e1s de a los profesionales hemos querido preguntar <strong>a los pap\u00e1s<\/strong>, los que est\u00e1n al pie del ca\u00f1\u00f3n, y para ello hemos contactado con los Pap\u00e1s blogueros, que nos han dado diferentes opiniones al respecto.<\/p>\n<p><strong>Fernando \u00c1lvarez<\/strong>, del blog Las historias de Pap\u00e1 Lobo, nos ha explicado lo siguiente:<\/p>\n<blockquote><p>Yo en verano levanto m\u00e1s la mano, pero salvo circunstancias especiales procuro que no est\u00e9n todo el d\u00eda con las pantallas. De momento, con los m\u00edos funciona el bajar a la piscina o jugar juntos a algo.<\/p><\/blockquote>\n<p>Por su parte, <strong>Oscar Penate<\/strong>, de El Mundo de Leo, nos ha dicho esto:<\/p>\n<blockquote><p>Por un lado creo que es normal que quieran m\u00e1s y que levantemos un poco m\u00e1s la mano, por otro no queremos que se enganchen y por otro (s\u00ed, qu\u00e9 pasa, tengo tres lados) lo del avance de la tecnolog\u00eda es inevitable y va con los tiempos&#8230; en mi caso particular sabe que tiene la tablet restringida a un rato los mi\u00e9rcoles y otro los s\u00e1bados, m\u00e1s alg\u00fan momento ocasional el m\u00f3vil. La semana pasada levant\u00e9 un poco m\u00e1s la mano&#8230; y me cost\u00f3 sudor y l\u00e1grimas quit\u00e1rsela. Tambi\u00e9n es que yo me enganch\u00e9 m\u00e1s. En fin, todo muy normal&#8230; seguimos aprendiendo.<\/p><\/blockquote>\n<div class=\"article-asset-image article-asset-large\">\n<div class=\"asset-content\"><img decoding=\"async\" class=\"centro_sinmarco\" src=\"http:\/\/i.blogs.es\/7cf1ad\/6660040845_df16b08be8_b\/450_1000.jpg\" srcset=\"http:\/\/i.blogs.es\/7cf1ad\/6660040845_df16b08be8_b\/450_1000.jpg 450w, http:\/\/i.blogs.es\/7cf1ad\/6660040845_df16b08be8_b\/650_1200.jpg 681w, http:\/\/i.blogs.es\/7cf1ad\/6660040845_df16b08be8_b\/1024_2000.jpg 1024w, http:\/\/i.blogs.es\/7cf1ad\/6660040845_df16b08be8_b\/1366_2000.jpg 1366w\" alt=\"Padres, ni\u00f1os y pantallas\" \/><\/div>\n<\/div>\n<p><strong>Daniel Benavides<\/strong> del blog Tang de Naranja nos ha dicho:<\/p>\n<blockquote><p>Yo ahora la dejo jugar entre semana pero no \u00abpara quitarla del medio\u00bb. Como no suele jugar (en periodo lectivo s\u00f3lo puede acceder a la consola los fines de semana y aun as\u00ed juntando ratos no llegar\u00e1 ni a la hora en los dos d\u00edas y medio), jugamos pas\u00e1ndonos el mando, as\u00ed que es una actividad m\u00e1s que hacer juntos.<\/p>\n<p>Para que deje de jugar tampoco sufrimos mucho, primero porque la hemos educado muy bien (jajaja) pero sobre todo porque si le propones otra cosa como por ejemplo ponernos a jugar a un juego de mesa o colorear o cualquier actividad que no implique abandonarla, aceptar\u00e1. Y tablet no tenemos, as\u00ed que no hay problema.<\/p><\/blockquote>\n<p>Y <strong>Manolo P\u00e9rez<\/strong>, de la p\u00e1gina Tropofoto, por su parte, nos ha explicado:<\/p>\n<blockquote><p>Mi hija tiene 5 a\u00f1os y le dejo manejar la tablet como mucho 20 minutos. (est\u00e1 con temporizador) A la hora de comer y cenar, nada de nada, hablamos. Si que ven v\u00eddeos (ella y el hermano de 1 a\u00f1o) en la tele cuando pap\u00e1 y mam\u00e1 tienen que hacer cosas y no podemos encargarnos de ellos (el peque\u00f1o es un torbellino y hay que ponerle mil ojos). A veces, antes del ba\u00f1o y mientras preparo la ba\u00f1era y dem\u00e1s tambi\u00e9n ven un poco de dibujos. Pero siempre controlados.<\/p><\/blockquote>\n<p>As\u00ed que como veis los consejos son diversos y los temores est\u00e1n ah\u00ed, porque el ocio f\u00e1cil y r\u00e1pido de la pantalla puede absorber a nuestros hijos hasta un punto en que <strong>se pierdan gran parte de su verano<\/strong> con algo que, en realidad, ya hacen el resto del a\u00f1o. El verano es ideal para hacer <strong>cosas diferentes<\/strong> y aprovechar el buen tiempo, que las piscinas est\u00e1n abiertas, que los padres podemos estar algo m\u00e1s con ellos y que hay actividades geniales para compartir juegos y <strong>recuperar el tiempo perdido<\/strong> por las obligaciones del resto del a\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace un mes hablamos de la generaci\u00f3n de padres que se siente culpable porque sus hijos pasan mucho tiempo mirando pantallas, que es la nuestra, que en estos d\u00edas se enfrenta a una nueva encrucijada porque los ni\u00f1os ya no tienen colegio.<\/p>\n","protected":false},"author":12,"featured_media":56829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-56827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=56827"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56827\/revisions"}],"predecessor-version":[{"id":56830,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56827\/revisions\/56830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/56829"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=56827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=56827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=56827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}