{"id":56955,"date":"2016-07-07T08:32:30","date_gmt":"2016-07-07T12:32:30","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=56955"},"modified":"2016-07-07T08:32:30","modified_gmt":"2016-07-07T12:32:30","slug":"voleibolista-puertoplatena-eve-castillo-se-destaca-en-equipo-nacional-de-esa-disciplina-que-sigue-invicto","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/voleibolista-puertoplatena-eve-castillo-se-destaca-en-equipo-nacional-de-esa-disciplina-que-sigue-invicto\/","title":{"rendered":"Voleibolista puertoplate\u00f1a Eve-Castillo se destaca en equipo nacional de esa disciplina que sigue invicto"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/la-china.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-56956\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/la-china.jpg\" alt=\"la china\" width=\"635\" height=\"374\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/la-china.jpg 635w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/la-china-300x177.jpg 300w\" sizes=\"auto, (max-width: 635px) 100vw, 635px\" \/><\/a>La voleibolista profesional nativa de Puerto Plata, Lisvel Eve-Castillo en compa\u00f1\u00eda de sus compa\u00f1eras Anneris Valdez, Brenda Castillo, Brayelyn Martinez, Gina Mambru, Bethania De la Cruz y Niberka Marte, se han destacado de mane incre\u00edble para que el equipo nacional de la Rep\u00fablica Dominicana se impusiera la noche del martes a Canad\u00e1 con un espectacular 3-0 (26-24\/25-21\/25-13) para as\u00ed llegar invicta al partido que definir\u00e1 qui\u00e9n ser\u00e1 el l\u00edder del Grupo A.<!--more--><\/p>\n<p>Tras la victoria ante Canad\u00e1, \u201cLas reinas del Caribe\u201d se enfrentar\u00e1n nada m\u00e1s que ante su archirrival que es Puerto Rico, que tambi\u00e9n se presentar\u00e1 al encuentro sin conocer derrota, pero todos los fan\u00e1ticos que asistieron al Palacio de los Deportes Gioriver Arias, pudieron ver de lo que era capaz el equipo dominicano en el nivel \u00e9lite, lo contemplaron directamente, en especial en el primer set, cuando Canad\u00e1 comenz\u00f3 a dominar el encuentro.<\/p>\n<p>Las canadienses se colocaron 18-14 y m\u00e1s adelante se pusieron 24-23, con Dominicana al saque, en ese punto lleg\u00f3 un rally de seis puntos y de esa manera las merengueras reclamaron el primer set 26-24, cuando un fuerte remate de Gina Mambr\u00fa igual\u00f3 el set a 24 puntos y un \u201choyo\u201d encontrado por Bethania de la Cruz lo defini\u00f3 en un ataque desde la posici\u00f3n de zaguero.<\/p>\n<p>Dominicana sac\u00f3 varios puntos ante la defensa canadiense acudiendo a los \u201choyitos\u201d ya que al explicar la clave para regresar, la libero Brenda Castillo, dijo: \u201cDebimos cumplir con el bloqueo y acoplarnos en la defensa\u2026 Y as\u00ed retuvimos el set\u201d. Mientras que en\u00a0 el segundo set, las cosas no fueron muy diferentes, pero Dominicana ajust\u00f3 un poco m\u00e1s ante un equipo canadiense, que por tradici\u00f3n han dominado en los \u00faltimos a\u00f1os.<\/p>\n<p>\u201cCada una jug\u00f3 fuerte. Estoy agradecida de Dios\u201d, continu\u00f3 Castillo. \u201cHicimos lo que el profesor Marcos Kwiek nos dijo en los planteamientos\u201d y as\u00ed se vio el resultado. En el tercer set, Canad\u00e1 ya ten\u00eda pocas respuestas ante el ataque y la defensa dominicana, que se manej\u00f3 muy bien en la red, tanto a la defensa como con sus remates.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La voleibolista profesional nativa de Puerto Plata, Lisvel Eve-Castillo en compa\u00f1\u00eda de sus compa\u00f1eras Anneris Valdez, Brenda Castillo, Brayelyn Martinez, Gina Mambru, Bethania De la Cruz y Niberka Marte, se han destacado de mane incre\u00edble para que el equipo nacional de la Rep\u00fablica Dominicana se impusiera la noche del martes a Canad\u00e1 con un espectacular 3-0 (26-24\/25-21\/25-13) para as\u00ed llegar invicta al partido que definir\u00e1 qui\u00e9n ser\u00e1 el l\u00edder del Grupo A.<\/p>\n","protected":false},"author":12,"featured_media":56956,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-56955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=56955"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56955\/revisions"}],"predecessor-version":[{"id":56957,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/56955\/revisions\/56957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/56956"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=56955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=56955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=56955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}