{"id":57015,"date":"2016-07-08T17:49:55","date_gmt":"2016-07-08T21:49:55","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=57015"},"modified":"2016-07-08T17:49:55","modified_gmt":"2016-07-08T21:49:55","slug":"sospechoso-de-ataque-en-dallas-habia-sido-movilizado-a-afganistan","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/sospechoso-de-ataque-en-dallas-habia-sido-movilizado-a-afganistan\/","title":{"rendered":"Sospechoso de ataque en Dallas hab\u00eda sido movilizado a Afganist\u00e1n"},"content":{"rendered":"<p>Washington, Estados Unidos. El joven Micah Xavier Johnson, se\u00f1alado como sospechoso por el tiroteo que dej\u00f3 en Dallas un saldo de cinco polic\u00edas muertos y otras nueve personas heridas, era un reservista del ej\u00e9rcito y hab\u00eda sido movilizado a Afganist\u00e1n, inform\u00f3 este viernes el Pent\u00e1gono.<!--more--><\/p>\n<figure id=\"attachment_263017\" class=\"wp-caption aligncenter\">\n<p><div id=\"attachment_57022\" style=\"width: 642px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/Micah-Xavier-Johnson-632x420.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-57022\" class=\"size-full wp-image-57022\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/Micah-Xavier-Johnson-632x420.jpg\" alt=\"Micah Xavier Johnson\" width=\"632\" height=\"420\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/Micah-Xavier-Johnson-632x420.jpg 632w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/Micah-Xavier-Johnson-632x420-300x199.jpg 300w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/a><p id=\"caption-attachment-57022\" class=\"wp-caption-text\">Micah Xavier Johnson<\/p><\/div><figcaption class=\"wp-caption-text\"><\/figcaption><\/figure>\n<p><strong>Johnson, un hombre negro de 25 a\u00f1os, sirvi\u00f3 en Afganist\u00e1n entre noviembre de 2013 y julio de 2014, inform\u00f3 el ej\u00e9rcito estadounidense.<\/strong><\/p>\n<p><strong>En ese pa\u00eds, Johnson era soldado aunque tambi\u00e9n desempe\u00f1aba funciones de alba\u00f1iler\u00eda y carpinter\u00eda, inform\u00f3 una vocero del Pent\u00e1gono, Cynthia Smith.<\/strong><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-0246812289979917\" data-ad-slot=\"1045525976\" data-adsbygoogle-status=\"done\"><\/ins><ins id=\"aswift_1_expand\"><\/ins><ins id=\"aswift_1_anchor\"><\/ins><\/p>\n<p><strong>El joven resid\u00eda en Mesquite, un suburbio de Dallas, y de acuerdo con informaciones de prensa no pose\u00eda antecedentes policiales.<\/strong><\/p>\n<p>Una manifestaci\u00f3n contra la violencia policial hacia ciudadanos negros se convirti\u00f3 en la noche del jueves en un ca\u00f3tico ba\u00f1o de sangre en el centro de Dallas, al degenerar en un violento tiroteo que sacudi\u00f3 al pa\u00eds.<\/p>\n<p>La polic\u00eda logr\u00f3 acorralar a Johnson en un edificio y trat\u00f3 de negociar una rendici\u00f3n. En esa negociaci\u00f3n, el joven asegur\u00f3 que no pertenec\u00eda a ninguna organizaci\u00f3n y que solo deseaba matar polic\u00edas blancos.<\/p>\n<div><\/div>\n<p>En ese intercambio tambi\u00e9n afirm\u00f3 haber instalado bombas en todo el centro de Dallas, aunque peritos en explosivos no hallaron esos artefactos. Johnson result\u00f3 muerto despu\u00e9s que la polic\u00eda utiliz\u00f3 un robot para trasladar explosivos al lugar donde se encontraba atrincherado.<\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Washington, Estados Unidos. El joven Micah Xavier Johnson, se\u00f1alado como sospechoso por el tiroteo que dej\u00f3 en Dallas un saldo de cinco polic\u00edas muertos y otras nueve personas heridas, era un reservista del ej\u00e9rcito y hab\u00eda sido movilizado a Afganist\u00e1n, inform\u00f3 este viernes el Pent\u00e1gono.<\/p>\n","protected":false},"author":12,"featured_media":57022,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-57015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/57015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=57015"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/57015\/revisions"}],"predecessor-version":[{"id":57023,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/57015\/revisions\/57023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/57022"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=57015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=57015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=57015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}