{"id":57036,"date":"2016-07-08T19:13:39","date_gmt":"2016-07-08T23:13:39","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=57036"},"modified":"2016-07-08T19:13:39","modified_gmt":"2016-07-08T23:13:39","slug":"piden-se-atiendan-monumentos-historicos-del-municipio-turistico-de-sosua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/piden-se-atiendan-monumentos-historicos-del-municipio-turistico-de-sosua\/","title":{"rendered":"Piden se atiendan monumentos hist\u00f3ricos del municipio tur\u00edstico de Sos\u00faa"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13615494_903079856504568_6645625674793018900_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-57041\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13615494_903079856504568_6645625674793018900_n.jpg\" alt=\"13615494_903079856504568_6645625674793018900_n\" width=\"558\" height=\"418\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13615494_903079856504568_6645625674793018900_n.jpg 960w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13615494_903079856504568_6645625674793018900_n-300x225.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13615494_903079856504568_6645625674793018900_n-768x576.jpg 768w\" sizes=\"auto, (max-width: 558px) 100vw, 558px\" \/><\/a>Sos\u00faa.- Ciudadanos preocupados por el verdadero desarrollo de este municipio y que no obedecen a intereses particulares, solicitaron de las autoridades, poner atenci\u00f3n a los pocos monumentos hist\u00f3ricos que representan los verdaderos s\u00edmbolos de origen y desarrollo e este ub\u00e9rrimo municipio, como lo es el Parque Hist\u00f3rico Parque Herma Strauss el cual luce sucio y abandonado y en pleno proceso de deterioro.<!--more--><\/p>\n<p>Pidieron al cabildo local salir en rescate de este importante monumento el cual simboliza ese triste y controversial suceso hist\u00f3rico conocido como \u201cLA NOCHE DE LOS CRISTALES ROTOS\u201d, hecho referente al 9 de Noviembre de 1938.<br \/>\nConsideraron que este importante monumento es un vital atractivo tur\u00edstico de este municipio, por lo que debe contar con la inmediata atenci\u00f3n de las autoridades y de igual manera salir al rescate de otros que est\u00e1n abandonados, en un programa hist\u00f3rico \u2013 cultural, que implique la colocaci\u00f3n de tarjas donde estaba ubicado el cuartel del ej\u00e9rcito en la Playa Sos\u00faa, en el lugar donde cayeron abatidos el Ingeniero Pedro Clisante y el doctor Alejo Mart\u00ednez, agregaron.<\/p>\n<p>He aqu\u00ed un fragmento hist\u00f3rico de \u201cLA NOCHE DE LOS CRISTALES ROTO\u201d: La\u00a0<strong>noche de los Cristales Rotos<\/strong>(en\u00a0alem\u00e1n:\u00a0<strong><em>Kristallnacht<\/em><\/strong>o\u00a0<strong><em>Novemberpogrome<\/em><\/strong>) fue una serie de\u00a0pogromos y ataques combinados ocurridos en la\u00a0Alemania nazi(comprendiendo\u00a0Austria tambi\u00e9n) durante la noche del\u00a09 al\u00a010 de noviembre de\u00a01938\u00a0y llevado a cabo contra ciudadanos jud\u00edos por las\u00a0tropas de asalto de las SAconjuntamente con la poblaci\u00f3n civil, mientras las autoridades alemanas observaban sin intervenir.<\/p>\n<p>\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-57036 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sosuaonline.net\/inicio\/piden-se-atiendan-monumentos-historicos-del-municipio-turistico-de-sosua\/13615494_903079856504568_6645625674793018900_n\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13615494_903079856504568_6645625674793018900_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13615494_903079856504568_6645625674793018900_n-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13615494_903079856504568_6645625674793018900_n-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sosuaonline.net\/inicio\/piden-se-atiendan-monumentos-historicos-del-municipio-turistico-de-sosua\/13620800_903079853171235_1798497514052057090_n\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13620800_903079853171235_1798497514052057090_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13620800_903079853171235_1798497514052057090_n-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13620800_903079853171235_1798497514052057090_n-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sosuaonline.net\/inicio\/piden-se-atiendan-monumentos-historicos-del-municipio-turistico-de-sosua\/13592616_903079843171236_6145294408582377297_n\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13592616_903079843171236_6145294408582377297_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13592616_903079843171236_6145294408582377297_n-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13592616_903079843171236_6145294408582377297_n-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/sosuaonline.net\/inicio\/piden-se-atiendan-monumentos-historicos-del-municipio-turistico-de-sosua\/13620011_903079849837902_9017820555917029910_n\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13620011_903079849837902_9017820555917029910_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13620011_903079849837902_9017820555917029910_n-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13620011_903079849837902_9017820555917029910_n-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/sosuaonline.net\/inicio\/piden-se-atiendan-monumentos-historicos-del-municipio-turistico-de-sosua\/13615149_903079846504569_1359678711548115568_n\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13615149_903079846504569_1359678711548115568_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13615149_903079846504569_1359678711548115568_n-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/13615149_903079846504569_1359678711548115568_n-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n<br \/>\nPresentado por los responsables\u00a0naziscomo una reacci\u00f3n espont\u00e1nea de la poblaci\u00f3n tras el asesinato, el\u00a07 de noviembre de\u00a01938, de\u00a0Ernst vom Rath, secretario de la embajada alemana en\u00a0Par\u00eds por un joven jud\u00edo polaco de origen alem\u00e1n,\u00a0Herschel Grynszpan, los pogromos fueron ordenados en realidad por el canciller del Reich,\u00a0Adolf Hitler, organizados por\u00a0Joseph Goebbels y cometidos por miembros de la\u00a0Sturmabteilung (SA), la\u00a0Schutzstaffel(SS) y las\u00a0Juventudes Hitlerianas, apoyadas por el\u00a0Sicherheitsdienst (SD), la\u00a0Gestapo y otras fuerzas de la polic\u00eda.<br \/>\nEstos pogromos fueron dirigidos contra los ciudadanos jud\u00edos y sus propiedades, as\u00ed como tambi\u00e9n la destrucci\u00f3n de las\u00a0sinagogas de todo el pa\u00eds.\u00a0Los ataques dejaron las calles cubiertas de vidrios rotos pertenecientes a los\u00a0escaparates de las tiendas y a las ventanas de los edificios de propiedad jud\u00eda.<\/p>\n<p>Al menos 91 ciudadanos jud\u00edos fueron asesinados durante los ataques y otros 30\u00a0000 fueron detenidos y posteriormente\u00a0deportados en masa\u00a0a los\u00a0campos de concentraci\u00f3n\u00a0de\u00a0Sachsenhausen,\u00a0Buchenwald\u00a0y\u00a0Dachau.\u00a0Las casas de la poblaci\u00f3n jud\u00eda, as\u00ed como sus hospitales y sus escuelas fueron saqueadas y destruidas por los atacantes, demoli\u00e9ndolas con mazos.\u00a0M\u00e1s de 1000\u00a0sinagogas fueron quemadas \u201495 solo en\u00a0Viena\u2014 y m\u00e1s de 7000 tiendas de propiedad de jud\u00edos fueron destruidas o seriamente da\u00f1adas.<\/p>\n<p>La Kristallnacht fue seguida por una persistente persecuci\u00f3n pol\u00edtica y econ\u00f3mica a la poblaci\u00f3n jud\u00eda, y es considerada por los historiadores como parte de la\u00a0pol\u00edtica racial en la Alemania nazi y el paso previo del inicio de la\u00a0Soluci\u00f3n Final y del\u00a0Holocausto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa.- Ciudadanos preocupados por el verdadero desarrollo de este municipio y que no obedecen a intereses particulares, solicitaron de las autoridades, poner atenci\u00f3n a los pocos monumentos hist\u00f3ricos que representan los verdaderos s\u00edmbolos de origen y desarrollo e este ub\u00e9rrimo municipio, como lo es el Parque Hist\u00f3rico Parque Herma Strauss el cual luce sucio y abandonado y en pleno proceso de deterioro.<\/p>\n","protected":false},"author":12,"featured_media":57041,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-57036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/57036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=57036"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/57036\/revisions"}],"predecessor-version":[{"id":57042,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/57036\/revisions\/57042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/57041"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=57036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=57036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=57036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}