{"id":57211,"date":"2016-07-17T10:33:07","date_gmt":"2016-07-17T14:33:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=57211"},"modified":"2016-07-17T10:33:07","modified_gmt":"2016-07-17T14:33:07","slug":"nuevas-revelaciones-sobre-el-autor-de-la-masacre-de-niza","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/nuevas-revelaciones-sobre-el-autor-de-la-masacre-de-niza\/","title":{"rendered":"Nuevas revelaciones sobre el autor de la masacre de Niza"},"content":{"rendered":"<div>\n<div class=\"body-area\">\n<div class=\"article-body\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/60636c97639133ae900170541bbbefed6f569352.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-57215\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/60636c97639133ae900170541bbbefed6f569352.jpeg\" alt=\"60636c97639133ae900170541bbbefed6f569352\" width=\"858\" height=\"540\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/60636c97639133ae900170541bbbefed6f569352.jpeg 858w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/60636c97639133ae900170541bbbefed6f569352-300x189.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/60636c97639133ae900170541bbbefed6f569352-768x483.jpeg 768w\" sizes=\"auto, (max-width: 858px) 100vw, 858px\" \/><\/a>Francia detuvo este domingo a otras dos personas relacionadas con la matanza de Niza, reivindicada por el grupo yihadista Estado Isl\u00e1mico, mientras los investigadores agregaban nuevas piezas al rompecabezas sobre los motivos del asesino y la preparaci\u00f3n del atentado.<!--more--><\/p>\n<p>Varios testigos, entre los cerca de 100 interrogados por la polic\u00eda, mencionaron por primera vez que el tunecino Mohamed Lahouaiej-Bouhlel, de 31 a\u00f1os, mostr\u00f3 signos de religiosidad. Su padre en cambio hab\u00eda afirmado que \u00abno ten\u00eda ning\u00fan v\u00ednculo con la religi\u00f3n\u00bb, que beb\u00eda alcohol y no iba a la mezquita.<\/p>\n<p>Por otra parte, fuentes allegadas a la investigaci\u00f3n indicaron que Lahouaiej-Bouhlel, hasta ahora desconocido de los servicios de informaci\u00f3n franceses, estuvo con el cami\u00f3n en el paseo de los Ingleses el 12 y el 13 de julio preparando el atentado del d\u00eda 14.<\/p>\n<p>Al penetrar el jueves por la noche con su cami\u00f3n de 19 toneladas en el famoso paseo, atestado de familias y turistas que celebraban la fiesta nacional, Lahouaiej-Bouhlel arroll\u00f3 a la multitud y mat\u00f3 a 84 personas, entre ellas diez ni\u00f1os y adolescentes, e hiri\u00f3 a otras 200. Entre las v\u00edctimas mortales figuran 17 extranjeros.<\/p>\n<p>El domingo, 85 personas segu\u00edan hospitalizadas, 18 de ellas, incluyendo a un ni\u00f1o, con pron\u00f3stico reservado, inform\u00f3 la ministra de Sanidad francesa, Marisol Touraine.<\/p>\n<p>Seg\u00fan algunos de sus vecinos, el atacante, que la organizaci\u00f3n yihadista present\u00f3 como \u00abun soldado del Estado Isl\u00e1mico\u00bb, ten\u00eda un perfil de persona desequilibrada, que vivi\u00f3 m\u00faltiples \u00abcrisis\u00bb familiares.<\/p>\n<p>Las autoridades detuvieron el domingo a otras dos personas, un hombre y una mujer, seg\u00fan una fuente judicial. Cuatro hombres del entorno de Lahouaiej-Bouhlel segu\u00edan arrestados. Su exmujer, detenida desde el viernes para ser interrogada, fue puesta en libertad el domingo.<\/p>\n<p>Todo indica que el atacante \u00abse radicaliz\u00f3 muy r\u00e1pido\u00bb, asegur\u00f3 el s\u00e1bado el ministro del Interior franc\u00e9s Bernard Cazeneuve, en base a testimonios de allegados.<\/p>\n<p>\u00abNos enfrentamos a individuos sensibles al mensaje de D\u00e1esh [Estado Isl\u00e1mico] que llevan a cabo acciones extremadamente violentas sin necesariamente haber combatido o haber sido entrenados\u00bb, a\u00f1adi\u00f3 el ministro, destacando que se trata de un \u00abnuevo modo\u00bb que ilustra \u00abla extremada complejidad de la lucha antiterrorista\u00bb.<\/p>\n<p>&#8211; \u00abFranceses patriotas\u00bb &#8211;<\/p>\n<p>Ocho meses despu\u00e9s de haber decretado el estado de urgencia en Francia y haber adoptado nuevas les leyes antiterroristas despu\u00e9s de los ataques del 13 de noviembre en Par\u00eds, las autoridades francesas hicieron el s\u00e1bado un llamamiento a \u00abtodos los franceses patriotas\u00bb para apoyar a las fuerzas de seguridad.<\/p>\n<p>Cazeneuve inst\u00f3 as\u00ed a los ciudadanos a unirse a la reserva operacional de la polic\u00eda y de la gendarmer\u00eda, efectivos que se puede movilizar \u00abr\u00e1pidamente\u00bb en funci\u00f3n de los \u00abhechos\u00bb. Se trata de la \u00fanica nueva propuesta del Gobierno tras la matanza, presionado para que tome r\u00e1pidamente medidas.<\/p>\n<p>La l\u00edder de la extrema derecha francesa, Marine Le Pen, exigi\u00f3 la dimisi\u00f3n del ministro del Interior y denunci\u00f3 \u00abcarencias grav\u00edsimas del Estado en su deber de proteger\u00bb a los franceses.<\/p>\n<p>\u00abEn cualquier pa\u00eds del mundo, un ministro con un balance tan horrible como el de Bernard Cazeneuve, 250 muertos en 18 meses, tendr\u00eda que haber renunciado\u00bb, dijo.<\/p>\n<p>Las autoridades hacen todo lo posible para tranquilizar a la opini\u00f3n p\u00fablica sobre la implicaci\u00f3n de las fuerzas de seguridad: \u00ab100.000 polic\u00edas, gendarmes y militares est\u00e1n movilizados para garantizar la seguridad de nuestros ciudadanos\u00bb, afirm\u00f3 el ministro del Interior.<\/p>\n<p>Los efectivos de la operaci\u00f3n militara Sentinelle, mantenidos en 10.000 hombres pese a que estaba previsto que se redujeran a 7.000 despu\u00e9s de la Eurocopa-2016, seguir\u00e1n en ese nivel \u00abhasta finales de verano\u00bb, anunci\u00f3 por su parte el ministro de Defensa, Jean-Yves le Drian.<\/p>\n<p>En Niza, en los numerosos mensajes depositados en el paseo de los Ingleses de esta tur\u00edstica localidad de la Riviera francesa, se pod\u00eda percibir el hartazgo de los franceses frente a esta tr\u00e1gica serie de atentados. \u00ab\u00a1Paremos la masacre!\u00bb, \u00ab\u00a1Hartos de matanzas en nuestras calles!\u00bb o \u00ab\u00a1Basta de discursos!\u00bb, se pod\u00eda leer.<\/p>\n<p>Sumida en tres d\u00edas de duelo nacional, Francia observar\u00e1 el lunes a mediod\u00eda un minuto de silencio. Despu\u00e9s de este momento de recogimiento, se reabrir\u00e1 por completo el acceso al paseo de los Ingleses.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"article-1-col-left padding-0\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Francia detuvo este domingo a otras dos personas relacionadas con la matanza de Niza, reivindicada por el grupo yihadista Estado Isl\u00e1mico, mientras los investigadores agregaban nuevas piezas al rompecabezas sobre los motivos del asesino y la preparaci\u00f3n del atentado.<\/p>\n","protected":false},"author":12,"featured_media":57215,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-57211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/57211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=57211"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/57211\/revisions"}],"predecessor-version":[{"id":57216,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/57211\/revisions\/57216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/57215"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=57211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=57211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=57211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}