{"id":57244,"date":"2016-07-17T19:13:51","date_gmt":"2016-07-17T23:13:51","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=57244"},"modified":"2016-07-17T19:13:51","modified_gmt":"2016-07-17T23:13:51","slug":"seis-advertencias-para-quienes-insisten-con-encontrar-pareja-en-el-lugar-de-trabajo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/seis-advertencias-para-quienes-insisten-con-encontrar-pareja-en-el-lugar-de-trabajo\/","title":{"rendered":"Seis advertencias para quienes insisten con encontrar pareja en el lugar de trabajo"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/image_content_6930029_20160717164431.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-57255\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/image_content_6930029_20160717164431.jpg\" alt=\"image_content_6930029_20160717164431\" width=\"693\" height=\"370\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/image_content_6930029_20160717164431.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/07\/image_content_6930029_20160717164431-300x160.jpg 300w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/a>Especialistas en el comportamiento humano advierten que tratar de hallar el amor en el lugar de trabajo casi siempre es una mala idea. Pero, para quienes se atreven a experimentar con el \u201ccasi\u201d, aqu\u00ed una lista de recomendaciones de psic\u00f3logos y profesionales dichas al New York Post.<!--more--><\/p>\n<p><b>No salgas con el jefe: <\/b>El doctor Seth Meyers, autor del libro \u201cDr. Seth\u2019s Love Prescription\u201d, advierte que los romances dentro de la oficina, particularmente los que involucran a los jefes pueden terminar de mala manera. \u201cComenzar una relaci\u00f3n donde alguien tiene poder sobre el otro es tonto, no puedes predecir en qu\u00e9 momento ese poder puede usarse dentro de la relaci\u00f3n, para favorecer a otros, o d\u00f3nde comienza y d\u00f3nde termina.\u201d<\/p>\n<p><b>Crea reglas de juego<\/b>: Hacer p\u00fablico el amor de oficina puede tener repercusiones que afecten la reputaci\u00f3n profesional de ambos, explica Francesca Hogi, asistente de relaciones con base en Brooklyn.<\/p>\n<p><b>No le cuentes a tus compa\u00f1eros: <\/b>Si le dices a tus compa\u00f1eros demasiado r\u00e1pido y la relaci\u00f3n no evoluciona como piensas, diste demasiada informaci\u00f3n demasiado r\u00e1pido. Lo mejor es esperar, y contar si es necesario.<\/p>\n<p>Instala barreras en el trabajo: Luego de que informes sobre la situaci\u00f3n ante tu jefe y compa\u00f1eros, aseg\u00farate tambi\u00e9n de separar el ambiente laboral de la relaci\u00f3n, indica Hogi.<\/p>\n<p><b>No uses los recursos de la compa\u00f1\u00eda para coquetear:<\/b> Correos electr\u00f3nicos, e-mail, m\u00f3viles de la empresa, todo eso puede jugar a tu favor para una mala reputaci\u00f3n o pueden llegar a o\u00eddos y ojos de quienes no debe, indica a Lynn Robinson, autora de \u201cPut Your Intuition to Work.<\/p>\n<p><b>S\u00e9 discreto: <\/b>\u201cLas relaciones no solo se cuentan en el lugar de trabajo, tambi\u00e9n en las redes sociales y cada vez hay m\u00e1s redes para cometer el error de la indiscreci\u00f3n\u201d, indica Robinson.<\/p>\n<p><b>Las actividades laborales, son laborales<\/b>: Una actividad social entre empleados siempre tendr\u00e1 ese matiz. Es un error pensar que porque se est\u00e9 fuera de la empresa, te puedes poner cari\u00f1oso o cari\u00f1osa con tu pareja, advierte Hogi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Especialistas en el comportamiento humano advierten que tratar de hallar el amor en el lugar de trabajo casi siempre es una mala idea. Pero, para quienes se atreven a experimentar con el \u201ccasi\u201d, aqu\u00ed una lista de recomendaciones de psic\u00f3logos y profesionales dichas al New York Post.<\/p>\n","protected":false},"author":12,"featured_media":57255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-57244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/57244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=57244"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/57244\/revisions"}],"predecessor-version":[{"id":57256,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/57244\/revisions\/57256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/57255"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=57244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=57244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=57244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}