{"id":5741,"date":"2014-07-09T11:52:26","date_gmt":"2014-07-09T15:52:26","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=5741"},"modified":"2014-07-09T11:53:26","modified_gmt":"2014-07-09T15:53:26","slug":"5741","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/5741\/","title":{"rendered":"Un incendio reduce a cenizas el bar Antica Locanda en Sos\u00faa"},"content":{"rendered":"<p><span style=\"color: #000000;\">\u00a0<a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/antica_405_210_120.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5747 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/antica_405_210_120.gif\" alt=\"antica_405_210_120\" width=\"340\" height=\"194\" \/><\/a>Sos\u00faa.-\u00a0 Un incendio ha destruido durante la madrugada de hoy mi\u00e9rcoles buena parte de las instalaciones del Bar-Restaurante Antica Locanda, situado en la calle Pedro Clisante del Batey, a escasos metros donde hace unos meses tambi\u00e9n resultara reducido a cenizas el Restaurant Jolly Rogers.<br \/>\n<!--more--><br \/>\n<\/span>El fuego se ha producido por causas desconocidas a eso de las 4:30 am y afecto en gran parte sus instalaciones y ajuares en su mayor\u00eda fabricados en madera.<\/p>\n<p style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-5746 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/1_405_210_120.gif\" alt=\"1_405_210_120\" width=\"375\" height=\"214\" \/>La actuaci\u00f3n de los bomberos de este municipio fue r\u00e1pida, pero ya el fuego se hab\u00eda propagado bastante imposibilitando que el fuego fuera sofocado inmediatamente.<\/p>\n<p style=\"color: #000000;\">Se esperan las investigaciones \u00a0que realicen los miembros de la Unidad Anti-Explosivos de la Polic\u00eda Nacional y el Cuerpo de Bomberos del Municipio de Sos\u00faa, para poder determinar el origen del siniestro.<\/p>\n<p style=\"color: #000000;\">Personas pr\u00f3ximas al bar incendiado narraron a periodistas de este medio, que existen sospechas de que el incendio fue provocado por manos criminales.<\/p>\n<p style=\"color: #000000;\">Dijeron que el fuego inicio en una mesa del establecimiento por lo que creen alguien lanzo alg\u00fan material inflamable o explosivo.<\/p>\n<p style=\"color: #000000;\">Por M\u00e1ximo Reynoso. <a href=\"http:\/\/cntv3.tv\/index.php\/k2-component\/regionales\/4317-un-incendio-reduce-a-cenizas-el-bar-antica-locanda-en-sosua\">Fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Sos\u00faa.-\u00a0 Un incendio ha destruido durante la madrugada de hoy mi\u00e9rcoles buena parte de las instalaciones del Bar-Restaurante Antica Locanda, situado en la calle Pedro Clisante del Batey, a escasos metros donde hace unos meses tambi\u00e9n resultara reducido a cenizas el Restaurant Jolly Rogers.<\/p>\n","protected":false},"author":3,"featured_media":5747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-5741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/5741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=5741"}],"version-history":[{"count":3,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/5741\/revisions"}],"predecessor-version":[{"id":5751,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/5741\/revisions\/5751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/5747"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=5741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=5741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=5741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}